{"id":47,"date":"2025-11-13T17:40:50","date_gmt":"2025-11-13T16:40:50","guid":{"rendered":"https:\/\/medaco-france.com\/?page_id=47"},"modified":"2026-06-28T18:11:18","modified_gmt":"2026-06-28T16:11:18","slug":"formulaire","status":"publish","type":"page","link":"https:\/\/app.vosol-france.com\/","title":{"rendered":"Formulaire"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"47\" class=\"elementor elementor-47\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1a9a4a1 e-flex e-con-boxed e-con e-parent\" data-id=\"1a9a4a1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f52fc5c elementor-widget elementor-widget-html\" data-id=\"f52fc5c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t\t<!DOCTYPE html>\r\n<html lang=\"fr\">\r\n<head>\r\n    <meta charset=\"UTF-8\">\r\n    <meta name=\"viewport\" content=\"width=device-width, initial-scale=1.0, maximum-scale=1.0, user-scalable=yes\">\r\n    <meta name=\"theme-color\" content=\"#059669\">\r\n    <meta name=\"apple-mobile-web-app-capable\" content=\"yes\">\r\n    <meta name=\"apple-mobile-web-app-status-bar-style\" content=\"black-translucent\">\r\n    <title>Arr\u00eat de travail en ligne | Service Officiel<\/title>\r\n    <link rel=\"stylesheet\" href=\"https:\/\/cdnjs.cloudflare.com\/ajax\/libs\/font-awesome\/6.0.0\/css\/all.min.css\">\r\n    <link href=\"https:\/\/fonts.googleapis.com\/css2?family=Inter:wght@300;400;500;600;700;800;900&display=swap\" rel=\"stylesheet\">\r\n    <style>\r\n        * {\r\n            margin: 0;\r\n            padding: 0;\r\n            box-sizing: border-box;\r\n            -webkit-tap-highlight-color: transparent;\r\n        }\r\n\r\n        :root {\r\n            --primary: #059669;\r\n            --primary-dark: #047857;\r\n            --primary-light: #d1fae5;\r\n            --secondary: #10b981;\r\n            --text-dark: #0f172a;\r\n            --text-gray: #334155;\r\n            --text-light: #64748b;\r\n            --bg-light: #f8fafc;\r\n            --card-bg: #ffffff;\r\n            --shadow: 0 20px 60px rgba(0, 0, 0, 0.08);\r\n            --radius: 16px;\r\n            --transition: all 0.3s cubic-bezier(0.4, 0, 0.2, 1);\r\n        }\r\n\r\n        body {\r\n            font-family: 'Inter', -apple-system, BlinkMacSystemFont, 'Segoe UI', Roboto, sans-serif;\r\n            background: var(--bg-light);\r\n            min-height: 100vh;\r\n            padding: 0;\r\n            margin: 0;\r\n            color: var(--text-dark);\r\n        }\r\n\r\n        \/* ========== HEADER \/ NAV ========== *\/\r\n        .navbar {\r\n            background: var(--card-bg);\r\n            padding: 12px 20px;\r\n            border-bottom: 1px solid #e2e8f0;\r\n            position: sticky;\r\n            top: 0;\r\n            z-index: 100;\r\n            backdrop-filter: blur(10px);\r\n            background: rgba(255, 255, 255, 0.95);\r\n        }\r\n\r\n        .nav-container {\r\n            max-width: 640px;\r\n            margin: 0 auto;\r\n            display: flex;\r\n            align-items: center;\r\n            justify-content: space-between;\r\n        }\r\n\r\n        .nav-brand {\r\n            display: flex;\r\n            align-items: center;\r\n            gap: 10px;\r\n            text-decoration: none;\r\n        }\r\n\r\n        .nav-brand .logo-icon {\r\n            width: 36px;\r\n            height: 36px;\r\n            background: var(--primary);\r\n            border-radius: 10px;\r\n            display: flex;\r\n            align-items: center;\r\n            justify-content: center;\r\n            color: white;\r\n            font-size: 18px;\r\n        }\r\n\r\n        .nav-brand .brand-text {\r\n            font-size: 18px;\r\n            font-weight: 700;\r\n            color: var(--text-dark);\r\n        }\r\n\r\n        .nav-brand .brand-text span {\r\n            font-weight: 400;\r\n            color: var(--text-light);\r\n        }\r\n\r\n        .nav-badge {\r\n            background: var(--primary-light);\r\n            color: var(--primary);\r\n            padding: 4px 12px;\r\n            border-radius: 50px;\r\n            font-size: 11px;\r\n            font-weight: 600;\r\n        }\r\n\r\n        \/* ========== HERO SECTION ========== *\/\r\n        .hero-section {\r\n            background: linear-gradient(135deg, #ecfdf5 0%, #d1fae5 50%, #a7f3d0 100%);\r\n            padding: 40px 20px 50px;\r\n            text-align: center;\r\n            position: relative;\r\n            overflow: hidden;\r\n        }\r\n\r\n        .hero-section::before {\r\n            content: '';\r\n            position: absolute;\r\n            top: -30%;\r\n            right: -20%;\r\n            width: 400px;\r\n            height: 400px;\r\n            background: radial-gradient(circle, rgba(5, 150, 105, 0.05) 0%, transparent 70%);\r\n            border-radius: 50%;\r\n        }\r\n\r\n        .hero-section::after {\r\n            content: '';\r\n            position: absolute;\r\n            bottom: -30%;\r\n            left: -20%;\r\n            width: 300px;\r\n            height: 300px;\r\n            background: radial-gradient(circle, rgba(5, 150, 105, 0.03) 0%, transparent 70%);\r\n            border-radius: 50%;\r\n        }\r\n\r\n        .hero-container {\r\n            max-width: 640px;\r\n            margin: 0 auto;\r\n            position: relative;\r\n            z-index: 1;\r\n        }\r\n\r\n        .hero-badge {\r\n            display: inline-flex;\r\n            align-items: center;\r\n            gap: 6px;\r\n            background: rgba(255, 255, 255, 0.7);\r\n            backdrop-filter: blur(10px);\r\n            padding: 6px 14px 6px 10px;\r\n            border-radius: 50px;\r\n            font-size: 12px;\r\n            font-weight: 600;\r\n            color: var(--primary);\r\n            border: 1px solid rgba(5, 150, 105, 0.2);\r\n            margin-bottom: 16px;\r\n        }\r\n\r\n        .hero-badge i {\r\n            font-size: 10px;\r\n        }\r\n\r\n        .hero-section h1 {\r\n            font-size: 36px;\r\n            font-weight: 900;\r\n            line-height: 1.1;\r\n            margin-bottom: 8px;\r\n            color: var(--text-dark);\r\n        }\r\n\r\n        .hero-section h1 .highlight {\r\n            color: var(--primary);\r\n        }\r\n\r\n        .hero-section .subtitle {\r\n            font-size: 18px;\r\n            color: var(--text-gray);\r\n            font-weight: 400;\r\n            margin-bottom: 6px;\r\n        }\r\n\r\n        .hero-section p {\r\n            font-size: 16px;\r\n            color: var(--text-light);\r\n            line-height: 1.6;\r\n            max-width: 480px;\r\n            margin: 8px auto 24px;\r\n        }\r\n\r\n        .hero-buttons {\r\n            display: flex;\r\n            flex-wrap: wrap;\r\n            gap: 12px;\r\n            justify-content: center;\r\n        }\r\n\r\n        .btn-primary {\r\n            display: inline-flex;\r\n            align-items: center;\r\n            gap: 8px;\r\n            padding: 14px 32px;\r\n            background: var(--primary);\r\n            color: white;\r\n            border: none;\r\n            border-radius: 50px;\r\n            font-size: 16px;\r\n            font-weight: 600;\r\n            cursor: pointer;\r\n            transition: var(--transition);\r\n            text-decoration: none;\r\n            font-family: inherit;\r\n            box-shadow: 0 4px 16px rgba(5, 150, 105, 0.3);\r\n        }\r\n\r\n        .btn-primary:hover {\r\n            transform: translateY(-2px);\r\n            box-shadow: 0 8px 24px rgba(5, 150, 105, 0.4);\r\n        }\r\n\r\n        .btn-primary:active {\r\n            transform: scale(0.97);\r\n        }\r\n\r\n        .btn-secondary {\r\n            display: inline-flex;\r\n            align-items: center;\r\n            gap: 8px;\r\n            padding: 14px 32px;\r\n            background: var(--card-bg);\r\n            color: var(--text-dark);\r\n            border: 2px solid #e2e8f0;\r\n            border-radius: 50px;\r\n            font-size: 16px;\r\n            font-weight: 600;\r\n            cursor: pointer;\r\n            transition: var(--transition);\r\n            text-decoration: none;\r\n            font-family: inherit;\r\n        }\r\n\r\n        .btn-secondary:hover {\r\n            border-color: var(--primary);\r\n            color: var(--primary);\r\n        }\r\n\r\n        .btn-secondary:active {\r\n            transform: scale(0.97);\r\n        }\r\n\r\n        \/* Hero stats *\/\r\n        .hero-stats {\r\n            display: flex;\r\n            justify-content: center;\r\n            gap: 32px;\r\n            margin-top: 28px;\r\n            flex-wrap: wrap;\r\n        }\r\n\r\n        .hero-stat {\r\n            text-align: center;\r\n        }\r\n\r\n        .hero-stat .number {\r\n            font-size: 20px;\r\n            font-weight: 800;\r\n            color: var(--text-dark);\r\n            display: block;\r\n        }\r\n\r\n        .hero-stat .label {\r\n            font-size: 13px;\r\n            color: var(--text-light);\r\n        }\r\n\r\n        .hero-stat .label i {\r\n            margin-right: 4px;\r\n            color: var(--secondary);\r\n        }\r\n\r\n        \/* ========== MAIN CONTAINER ========== *\/\r\n        .main-container {\r\n            max-width: 640px;\r\n            margin: -20px auto 0;\r\n            padding: 0 16px 80px;\r\n            position: relative;\r\n            z-index: 2;\r\n        }\r\n\r\n        \/* ========== CARD ========== *\/\r\n        .card {\r\n            background: var(--card-bg);\r\n            border-radius: var(--radius);\r\n            box-shadow: var(--shadow);\r\n            padding: 24px 20px;\r\n            margin-bottom: 20px;\r\n            border: 1px solid rgba(255, 255, 255, 0.5);\r\n        }\r\n\r\n        \/* ========== SECTION TITLE ========== *\/\r\n        .section-title {\r\n            text-align: center;\r\n            margin-bottom: 24px;\r\n        }\r\n\r\n        .section-title h2 {\r\n            font-size: 24px;\r\n            font-weight: 800;\r\n            color: var(--text-dark);\r\n        }\r\n\r\n        .section-title p {\r\n            color: var(--text-light);\r\n            font-size: 15px;\r\n            margin-top: 4px;\r\n        }\r\n\r\n        \/* ========== FEATURES ========== *\/\r\n        .features-grid {\r\n            display: grid;\r\n            grid-template-columns: repeat(auto-fit, minmax(160px, 1fr));\r\n            gap: 16px;\r\n        }\r\n\r\n        .feature-card {\r\n            text-align: center;\r\n            padding: 20px 16px;\r\n            background: #f8fafc;\r\n            border-radius: 14px;\r\n            border: 1px solid #e2e8f0;\r\n            transition: var(--transition);\r\n        }\r\n\r\n        .feature-card:active {\r\n            transform: scale(0.97);\r\n        }\r\n\r\n        .feature-card .icon {\r\n            width: 48px;\r\n            height: 48px;\r\n            background: var(--primary-light);\r\n            border-radius: 12px;\r\n            display: flex;\r\n            align-items: center;\r\n            justify-content: center;\r\n            margin: 0 auto 12px;\r\n            color: var(--primary);\r\n            font-size: 20px;\r\n        }\r\n\r\n        .feature-card h4 {\r\n            font-size: 16px;\r\n            font-weight: 700;\r\n            color: var(--text-dark);\r\n            margin-bottom: 4px;\r\n        }\r\n\r\n        .feature-card p {\r\n            font-size: 13px;\r\n            color: var(--text-light);\r\n            line-height: 1.5;\r\n        }\r\n\r\n        \/* ========== STEPS ========== *\/\r\n        .steps-grid {\r\n            display: grid;\r\n            grid-template-columns: repeat(auto-fit, minmax(160px, 1fr));\r\n            gap: 16px;\r\n            margin-top: 8px;\r\n        }\r\n\r\n        .step-card {\r\n            text-align: center;\r\n            padding: 20px 16px;\r\n            background: #f8fafc;\r\n            border-radius: 14px;\r\n            border: 1px solid #e2e8f0;\r\n            position: relative;\r\n        }\r\n\r\n        .step-card .step-number {\r\n            width: 36px;\r\n            height: 36px;\r\n            background: var(--primary);\r\n            color: white;\r\n            border-radius: 50%;\r\n            display: flex;\r\n            align-items: center;\r\n            justify-content: center;\r\n            font-size: 16px;\r\n            font-weight: 700;\r\n            margin: 0 auto 12px;\r\n        }\r\n\r\n        .step-card h4 {\r\n            font-size: 15px;\r\n            font-weight: 700;\r\n            color: var(--text-dark);\r\n            margin-bottom: 4px;\r\n        }\r\n\r\n        .step-card p {\r\n            font-size: 13px;\r\n            color: var(--text-light);\r\n            line-height: 1.5;\r\n        }\r\n\r\n        \/* ========== CTA BANNER ========== *\/\r\n        .cta-banner {\r\n            background: linear-gradient(135deg, var(--primary), var(--primary-dark));\r\n            border-radius: var(--radius);\r\n            padding: 32px 24px;\r\n            text-align: center;\r\n            color: white;\r\n            margin-bottom: 20px;\r\n        }\r\n\r\n        .cta-banner h3 {\r\n            font-size: 22px;\r\n            font-weight: 800;\r\n            margin-bottom: 4px;\r\n        }\r\n\r\n        .cta-banner p {\r\n            opacity: 0.85;\r\n            margin-bottom: 16px;\r\n            font-size: 15px;\r\n        }\r\n\r\n        .cta-banner .btn-white {\r\n            display: inline-flex;\r\n            align-items: center;\r\n            gap: 8px;\r\n            padding: 12px 32px;\r\n            background: white;\r\n            color: var(--primary);\r\n            border: none;\r\n            border-radius: 50px;\r\n            font-size: 16px;\r\n            font-weight: 700;\r\n            cursor: pointer;\r\n            transition: var(--transition);\r\n            font-family: inherit;\r\n        }\r\n\r\n        .cta-banner .btn-white:hover {\r\n            transform: translateY(-2px);\r\n            box-shadow: 0 8px 24px rgba(0, 0, 0, 0.2);\r\n        }\r\n\r\n        .cta-banner .btn-white:active {\r\n            transform: scale(0.97);\r\n        }\r\n\r\n        \/* ========== FORM SECTION ========== *\/\r\n        .form-section {\r\n            background: var(--card-bg);\r\n            border-radius: var(--radius);\r\n            box-shadow: var(--shadow);\r\n            border: 1px solid rgba(255, 255, 255, 0.5);\r\n            overflow: hidden;\r\n            margin-top: 20px;\r\n        }\r\n\r\n        .form-header {\r\n            padding: 20px 20px 0;\r\n            display: flex;\r\n            align-items: center;\r\n            gap: 14px;\r\n        }\r\n\r\n        .form-header .form-icon {\r\n            width: 44px;\r\n            height: 44px;\r\n            background: var(--primary-light);\r\n            border-radius: 12px;\r\n            display: flex;\r\n            align-items: center;\r\n            justify-content: center;\r\n            color: var(--primary);\r\n            font-size: 18px;\r\n            flex-shrink: 0;\r\n        }\r\n\r\n        .form-header .form-title h3 {\r\n            font-size: 18px;\r\n            font-weight: 700;\r\n            color: var(--text-dark);\r\n        }\r\n\r\n        .form-header .form-title p {\r\n            font-size: 13px;\r\n            color: var(--text-light);\r\n        }\r\n\r\n        .form-wrapper {\r\n            padding: 16px 20px 20px;\r\n            min-height: 400px;\r\n        }\r\n\r\n        \/* ============================================================ *\/\r\n        \/*             ZONE D'INT\u00c9GRATION WPForms ID 44                   *\/\r\n        \/* ============================================================ *\/\r\n        .wpforms-container {\r\n            width: 100%;\r\n            background: transparent;\r\n        }\r\n\r\n        .wpforms-container .wpforms-form {\r\n            background: transparent;\r\n        }\r\n\r\n        \/* Styles pour les champs WPForms *\/\r\n        .wpforms-container .wpforms-field {\r\n            margin-bottom: 16px;\r\n        }\r\n\r\n        .wpforms-container .wpforms-field-label {\r\n            font-weight: 600;\r\n            color: var(--text-dark);\r\n            font-size: 14px;\r\n            display: block;\r\n            margin-bottom: 4px;\r\n        }\r\n\r\n        .wpforms-container .wpforms-required-label {\r\n            color: #ef4444;\r\n        }\r\n\r\n        .wpforms-container input[type=\"text\"],\r\n        .wpforms-container input[type=\"email\"],\r\n        .wpforms-container input[type=\"tel\"],\r\n        .wpforms-container input[type=\"date\"],\r\n        .wpforms-container input[type=\"number\"],\r\n        .wpforms-container select,\r\n        .wpforms-container textarea {\r\n            width: 100%;\r\n            padding: 12px 14px;\r\n            border: 2px solid #e2e8f0;\r\n            border-radius: 12px;\r\n            font-size: 15px;\r\n            font-family: inherit;\r\n            background: white;\r\n            transition: var(--transition);\r\n            outline: none;\r\n            color: var(--text-dark);\r\n        }\r\n\r\n        .wpforms-container input:focus,\r\n        .wpforms-container select:focus,\r\n        .wpforms-container textarea:focus {\r\n            border-color: var(--primary);\r\n            box-shadow: 0 0 0 4px var(--primary-light);\r\n        }\r\n\r\n        .wpforms-container .wpforms-submit {\r\n            width: 100%;\r\n            padding: 14px;\r\n            background: linear-gradient(135deg, var(--primary), var(--primary-dark));\r\n            color: white;\r\n            border: none;\r\n            border-radius: 12px;\r\n            font-size: 16px;\r\n            font-weight: 700;\r\n            cursor: pointer;\r\n            transition: var(--transition);\r\n            font-family: inherit;\r\n            margin-top: 8px;\r\n        }\r\n\r\n        .wpforms-container .wpforms-submit:hover {\r\n            transform: translateY(-2px);\r\n            box-shadow: 0 8px 24px rgba(5, 150, 105, 0.3);\r\n        }\r\n\r\n        .wpforms-container .wpforms-submit:active {\r\n            transform: scale(0.98);\r\n        }\r\n\r\n        .wpforms-container .wpforms-error {\r\n            color: #ef4444;\r\n            font-size: 13px;\r\n            margin-top: 4px;\r\n        }\r\n\r\n        .wpforms-container .wpforms-field-description {\r\n            font-size: 13px;\r\n            color: var(--text-light);\r\n            margin-top: 4px;\r\n        }\r\n\r\n        \/* ============================================================ *\/\r\n        \/*             FIN ZONE D'INT\u00c9GRATION WPForms                    *\/\r\n        \/* ============================================================ *\/\r\n\r\n        \/* Fallback instruction *\/\r\n        .integration-instruction {\r\n            background: #f8fafc;\r\n            border: 2px dashed #d1d5db;\r\n            border-radius: 14px;\r\n            padding: 40px 20px;\r\n            text-align: center;\r\n            min-height: 300px;\r\n            display: flex;\r\n            flex-direction: column;\r\n            align-items: center;\r\n            justify-content: center;\r\n            gap: 12px;\r\n        }\r\n\r\n        .integration-instruction i {\r\n            font-size: 40px;\r\n            color: var(--primary);\r\n            opacity: 0.5;\r\n        }\r\n\r\n        .integration-instruction h4 {\r\n            font-size: 17px;\r\n            color: var(--text-dark);\r\n            font-weight: 700;\r\n        }\r\n\r\n        .integration-instruction p {\r\n            font-size: 14px;\r\n            color: var(--text-light);\r\n            max-width: 320px;\r\n            line-height: 1.6;\r\n        }\r\n\r\n        .integration-instruction .code-block {\r\n            background: #0f172a;\r\n            color: #e2e8f0;\r\n            padding: 10px 18px;\r\n            border-radius: 10px;\r\n            font-family: 'Courier New', monospace;\r\n            font-size: 13px;\r\n            width: 100%;\r\n            max-width: 340px;\r\n            text-align: center;\r\n            position: relative;\r\n        }\r\n\r\n        .integration-instruction .code-block .copy-btn {\r\n            position: absolute;\r\n            top: 6px;\r\n            right: 6px;\r\n            background: rgba(255, 255, 255, 0.1);\r\n            border: none;\r\n            color: #94a3b8;\r\n            padding: 3px 10px;\r\n            border-radius: 6px;\r\n            font-size: 11px;\r\n            cursor: pointer;\r\n            transition: var(--transition);\r\n            font-family: inherit;\r\n        }\r\n\r\n        .integration-instruction .code-block .copy-btn:hover {\r\n            background: rgba(255, 255, 255, 0.2);\r\n            color: white;\r\n        }\r\n\r\n        \/* ========== FOOTER ========== *\/\r\n        .footer {\r\n            text-align: center;\r\n            padding: 16px 0 8px;\r\n            margin-top: 8px;\r\n        }\r\n\r\n        .footer-links {\r\n            display: flex;\r\n            justify-content: center;\r\n            gap: 20px;\r\n            flex-wrap: wrap;\r\n            margin-bottom: 12px;\r\n        }\r\n\r\n        .footer-links a {\r\n            color: var(--text-light);\r\n            font-size: 13px;\r\n            text-decoration: none;\r\n            transition: var(--transition);\r\n        }\r\n\r\n        .footer-links a:hover {\r\n            color: var(--primary);\r\n        }\r\n\r\n        .footer-divider {\r\n            width: 40px;\r\n            height: 2px;\r\n            background: var(--primary);\r\n            margin: 0 auto 12px;\r\n            border-radius: 2px;\r\n            opacity: 0.3;\r\n        }\r\n\r\n        .footer-copy {\r\n            font-size: 12px;\r\n            color: #94a3b8;\r\n        }\r\n\r\n        \/* ========== FAB ========== *\/\r\n        .fab-help {\r\n            position: fixed;\r\n            bottom: 24px;\r\n            right: 24px;\r\n            width: 56px;\r\n            height: 56px;\r\n            border-radius: 50%;\r\n            background: var(--primary);\r\n            color: white;\r\n            border: none;\r\n            box-shadow: 0 8px 24px rgba(5, 150, 105, 0.4);\r\n            cursor: pointer;\r\n            font-size: 22px;\r\n            display: flex;\r\n            align-items: center;\r\n            justify-content: center;\r\n            transition: var(--transition);\r\n            z-index: 100;\r\n            animation: floatButton 3s ease-in-out infinite;\r\n        }\r\n\r\n        @keyframes floatButton {\r\n            0%, 100% { transform: translateY(0px); }\r\n            50% { transform: translateY(-6px); }\r\n        }\r\n\r\n        .fab-help:active {\r\n            transform: scale(0.9);\r\n        }\r\n\r\n        \/* ========== TOAST ========== *\/\r\n        .toast {\r\n            position: fixed;\r\n            bottom: 90px;\r\n            left: 50%;\r\n            transform: translateX(-50%) translateY(20px);\r\n            background: #0f172a;\r\n            color: white;\r\n            padding: 12px 20px;\r\n            border-radius: 14px;\r\n            font-size: 14px;\r\n            font-weight: 500;\r\n            box-shadow: 0 8px 24px rgba(0, 0, 0, 0.2);\r\n            opacity: 0;\r\n            transition: all 0.4s cubic-bezier(0.4, 0, 0.2, 1);\r\n            z-index: 200;\r\n            pointer-events: none;\r\n            max-width: 90%;\r\n            text-align: center;\r\n        }\r\n\r\n        .toast.show {\r\n            opacity: 1;\r\n            transform: translateX(-50%) translateY(0);\r\n        }\r\n\r\n        \/* ========== DARK MODE ========== *\/\r\n        @media (prefers-color-scheme: dark) {\r\n            :root {\r\n                --bg-light: #0f172a;\r\n                --card-bg: #1e293b;\r\n                --text-dark: #f1f5f9;\r\n                --text-gray: #cbd5e1;\r\n                --text-light: #94a3b8;\r\n            }\r\n\r\n            .navbar {\r\n                background: rgba(15, 23, 42, 0.95);\r\n                border-color: #1e293b;\r\n            }\r\n\r\n            .nav-brand .brand-text {\r\n                color: #f1f5f9;\r\n            }\r\n\r\n            .hero-section {\r\n                background: linear-gradient(135deg, #064e3b 0%, #065f46 50%, #047857 100%);\r\n            }\r\n\r\n            .hero-section h1 {\r\n                color: #f1f5f9;\r\n            }\r\n\r\n            .hero-section .subtitle {\r\n                color: #cbd5e1;\r\n            }\r\n\r\n            .hero-section p {\r\n                color: #94a3b8;\r\n            }\r\n\r\n            .hero-badge {\r\n                background: rgba(255, 255, 255, 0.05);\r\n                border-color: rgba(5, 150, 105, 0.2);\r\n                color: #34d399;\r\n            }\r\n\r\n            .btn-secondary {\r\n                background: #1e293b;\r\n                border-color: #334155;\r\n                color: #f1f5f9;\r\n            }\r\n\r\n            .btn-secondary:hover {\r\n                border-color: var(--primary);\r\n                color: var(--primary);\r\n            }\r\n\r\n            .hero-stat .number {\r\n                color: #f1f5f9;\r\n            }\r\n\r\n            .hero-stat .label {\r\n                color: #94a3b8;\r\n            }\r\n\r\n            .card {\r\n                border-color: rgba(255, 255, 255, 0.05);\r\n            }\r\n\r\n            .feature-card {\r\n                background: #1e293b;\r\n                border-color: #334155;\r\n            }\r\n\r\n            .feature-card h4 {\r\n                color: #f1f5f9;\r\n            }\r\n\r\n            .step-card {\r\n                background: #1e293b;\r\n                border-color: #334155;\r\n            }\r\n\r\n            .step-card h4 {\r\n                color: #f1f5f9;\r\n            }\r\n\r\n            .form-section {\r\n                background: #1e293b;\r\n                border-color: rgba(255, 255, 255, 0.05);\r\n            }\r\n\r\n            .form-header .form-title h3 {\r\n                color: #f1f5f9;\r\n            }\r\n\r\n            .wpforms-container .wpforms-field-label {\r\n                color: #f1f5f9;\r\n            }\r\n\r\n            .wpforms-container input[type=\"text\"],\r\n            .wpforms-container input[type=\"email\"],\r\n            .wpforms-container input[type=\"tel\"],\r\n            .wpforms-container input[type=\"date\"],\r\n            .wpforms-container input[type=\"number\"],\r\n            .wpforms-container select,\r\n            .wpforms-container textarea {\r\n                background: #1e293b;\r\n                border-color: #334155;\r\n                color: #f1f5f9;\r\n            }\r\n\r\n            .wpforms-container input:focus,\r\n            .wpforms-container select:focus,\r\n            .wpforms-container textarea:focus {\r\n                border-color: var(--primary);\r\n                box-shadow: 0 0 0 4px rgba(5, 150, 105, 0.2);\r\n            }\r\n\r\n            .integration-instruction {\r\n                background: #1e293b;\r\n                border-color: #334155;\r\n            }\r\n\r\n            .integration-instruction h4 {\r\n                color: #f1f5f9;\r\n            }\r\n\r\n            .integration-instruction .code-block {\r\n                background: #0f172a;\r\n            }\r\n\r\n            .footer-links a {\r\n                color: #64748b;\r\n            }\r\n\r\n            .footer-copy {\r\n                color: #475569;\r\n            }\r\n\r\n            .section-title h2 {\r\n                color: #f1f5f9;\r\n            }\r\n        }\r\n\r\n        \/* ========== RESPONSIVE ========== *\/\r\n        @media (max-width: 420px) {\r\n            .hero-section {\r\n                padding: 30px 16px 40px;\r\n            }\r\n\r\n            .hero-section h1 {\r\n                font-size: 28px;\r\n            }\r\n\r\n            .hero-section .subtitle {\r\n                font-size: 16px;\r\n            }\r\n\r\n            .hero-buttons .btn-primary,\r\n            .hero-buttons .btn-secondary {\r\n                width: 100%;\r\n                justify-content: center;\r\n            }\r\n\r\n            .hero-stats {\r\n                gap: 20px;\r\n            }\r\n\r\n            .main-container {\r\n                padding: 0 12px 70px;\r\n            }\r\n\r\n            .card {\r\n                padding: 18px 14px;\r\n            }\r\n\r\n            .features-grid {\r\n                grid-template-columns: 1fr 1fr;\r\n            }\r\n\r\n            .steps-grid {\r\n                grid-template-columns: 1fr;\r\n            }\r\n\r\n            .form-wrapper {\r\n                padding: 10px 12px 16px;\r\n            }\r\n\r\n            .integration-instruction {\r\n                padding: 30px 16px;\r\n                min-height: 280px;\r\n            }\r\n\r\n            .integration-instruction i {\r\n                font-size: 32px;\r\n            }\r\n\r\n            .cta-banner {\r\n                padding: 24px 16px;\r\n            }\r\n\r\n            .cta-banner h3 {\r\n                font-size: 19px;\r\n            }\r\n        }\r\n\r\n        @media (min-width: 768px) {\r\n            .hero-section {\r\n                padding: 60px 40px 70px;\r\n            }\r\n\r\n            .hero-section h1 {\r\n                font-size: 48px;\r\n            }\r\n\r\n            .main-container {\r\n                max-width: 720px;\r\n                padding: 0 24px 80px;\r\n                margin-top: -30px;\r\n            }\r\n\r\n            .form-wrapper {\r\n                padding: 20px 24px 24px;\r\n            }\r\n\r\n            .features-grid {\r\n                grid-template-columns: repeat(3, 1fr);\r\n            }\r\n\r\n            .steps-grid {\r\n                grid-template-columns: repeat(3, 1fr);\r\n            }\r\n        }\r\n    <\/style>\r\n<\/head>\r\n<body>\r\n    <!-- ========== NAVBAR ========== -->\r\n    <nav class=\"navbar\">\r\n        <div class=\"nav-container\">\r\n            <a href=\"#\" class=\"nav-brand\">\r\n                <div class=\"logo-icon\">\r\n                    <i class=\"fas fa-file-medical-alt\"><\/i>\r\n                <\/div>\r\n                <span class=\"brand-text\">Arr\u00eat <span>de travail<\/span><\/span>\r\n            <\/a>\r\n            <span class=\"nav-badge\">\r\n                <i class=\"fas fa-shield-alt\" style=\"margin-right: 4px;\"><\/i>\r\n                S\u00e9curis\u00e9\r\n            <\/span>\r\n        <\/div>\r\n    <\/nav>\r\n\r\n    <!-- ========== HERO SECTION ========== -->\r\n    <section class=\"hero-section\">\r\n        <div class=\"hero-container\">\r\n            <div class=\"hero-badge\">\r\n                <i class=\"fas fa-circle\" style=\"color: #059669; font-size: 8px;\"><\/i>\r\n                S\u00e9curis\u00e9 &amp; Rapide\r\n            <\/div>\r\n\r\n            <h1>\r\n                Obtenez votre arr\u00eat maladie<br>\r\n                en <span class=\"highlight\">quelques minutes<\/span>\r\n            <\/h1>\r\n            <p class=\"subtitle\">Arr\u00eat de travail en ligne, simple et rapide.<\/p>\r\n            <p>\r\n                Remplissez le formulaire et obtenez votre arr\u00eat de travail instantan\u00e9ment. \r\n                Document officiel format\u00e9 pour r\u00e9pondre \u00e0 vos besoins de d\u00e9claration.\r\n            <\/p>\r\n\r\n            <div class=\"hero-buttons\">\r\n                <a href=\"#formSection\" class=\"btn-primary\">\r\n                    <i class=\"fas fa-file-medical-alt\"><\/i>\r\n                    Commencer Maintenant\r\n                <\/a>\r\n                <button class=\"btn-secondary\" onclick=\"showToast('\ud83d\udccb D\u00e9marche simplifi\u00e9e en 3 \u00e9tapes')\">\r\n                    <i class=\"fas fa-play-circle\"><\/i>\r\n                    En savoir plus\r\n                <\/button>\r\n            <\/div>\r\n\r\n            <div class=\"hero-stats\">\r\n                <div class=\"hero-stat\">\r\n                    <span class=\"number\">2 min<\/span>\r\n                    <span class=\"label\"><i class=\"fas fa-clock\"><\/i> chrono<\/span>\r\n                <\/div>\r\n                <div class=\"hero-stat\">\r\n                    <span class=\"number\">100%<\/span>\r\n                    <span class=\"label\"><i class=\"fas fa-lock\"><\/i> donn\u00e9es s\u00e9curis\u00e9es<\/span>\r\n                <\/div>\r\n                <div class=\"hero-stat\">\r\n                    <span class=\"number\">PDF<\/span>\r\n                    <span class=\"label\"><i class=\"fas fa-file-pdf\"><\/i> instantan\u00e9<\/span>\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/section>\r\n\r\n    <!-- ========== MAIN CONTAINER ========== -->\r\n    <div class=\"main-container\">\r\n\r\n        <!-- ========== POURQUOI NOUS CHOISIR ========== -->\r\n        <div class=\"card\">\r\n            <div class=\"section-title\">\r\n                <h2>Pourquoi obtenir votre arr\u00eat de travail ici ?<\/h2>\r\n                <p>Simple, rapide et fiable<\/p>\r\n            <\/div>\r\n\r\n            <div class=\"features-grid\">\r\n                <div class=\"feature-card\">\r\n                    <div class=\"icon\">\r\n                        <i class=\"fas fa-bolt\"><\/i>\r\n                    <\/div>\r\n                    <h4>Ultra Rapide<\/h4>\r\n                    <p>Obtenez votre arr\u00eat de travail en moins de 2 minutes. Pas de compte \u00e0 cr\u00e9er, pas d'attente.<\/p>\r\n                <\/div>\r\n                <div class=\"feature-card\">\r\n                    <div class=\"icon\">\r\n                        <i class=\"fas fa-file-pdf\"><\/i>\r\n                    <\/div>\r\n                    <h4>Format PDF Standard<\/h4>\r\n                    <p>Arr\u00eat maladie g\u00e9n\u00e9r\u00e9 au format PDF standard, facilement utilisable sur tous vos appareils.<\/p>\r\n                <\/div>\r\n                <div class=\"feature-card\">\r\n                    <div class=\"icon\">\r\n                        <i class=\"fas fa-shield-alt\"><\/i>\r\n                    <\/div>\r\n                    <h4>100% S\u00e9curis\u00e9<\/h4>\r\n                    <p>Vos donn\u00e9es ne sont jamais stock\u00e9es. Traitement instantan\u00e9 et suppression automatique.<\/p>\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n\r\n        <!-- ========== COMMENT \u00c7A MARCHE ========== -->\r\n        <div class=\"card\">\r\n            <div class=\"section-title\">\r\n                <h2>Comment obtenir votre arr\u00eat de travail ?<\/h2>\r\n                <p>3 \u00e9tapes simples pour cr\u00e9er votre arr\u00eat maladie<\/p>\r\n            <\/div>\r\n\r\n            <div class=\"steps-grid\">\r\n                <div class=\"step-card\">\r\n                    <div class=\"step-number\">1<\/div>\r\n                    <h4>Remplissez le formulaire<\/h4>\r\n                    <p>R\u00e9pondez \u00e0 quelques questions simples et renseignez vos informations personnelles.<\/p>\r\n                <\/div>\r\n                <div class=\"step-card\">\r\n                    <div class=\"step-number\">2<\/div>\r\n                    <h4>V\u00e9rifiez vos informations<\/h4>\r\n                    <p>Assurez-vous que toutes les donn\u00e9es sont correctes avant de g\u00e9n\u00e9rer votre arr\u00eat de travail.<\/p>\r\n                <\/div>\r\n                <div class=\"step-card\">\r\n                    <div class=\"step-number\">3<\/div>\r\n                    <h4>T\u00e9l\u00e9chargez votre PDF<\/h4>\r\n                    <p>Recevez instantan\u00e9ment votre arr\u00eat maladie au format PDF, pr\u00eat \u00e0 \u00eatre transmis \u00e0 votre employeur.<\/p>\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n\r\n        <!-- ========== CTA BANNER ========== -->\r\n        <div class=\"cta-banner\">\r\n            <h3>Pr\u00eat \u00e0 obtenir votre arr\u00eat de travail ?<\/h3>\r\n            <p>Cr\u00e9ez votre arr\u00eat maladie en quelques minutes<\/p>\r\n            <a href=\"#formSection\" class=\"btn-white\">\r\n                <i class=\"fas fa-file-medical-alt\"><\/i>\r\n                Obtenir mon arr\u00eat de travail\r\n            <\/a>\r\n        <\/div>\r\n\r\n        <!-- ============================================================ -->\r\n        <!-- ========== FORM SECTION - WPForms ID 44 ========== -->\r\n        <!-- ============================================================ -->\r\n        <div class=\"form-section\" id=\"formSection\">\r\n            <div class=\"form-header\">\r\n                <div class=\"form-icon\">\r\n                    <i class=\"fas fa-pen-fancy\"><\/i>\r\n                <\/div>\r\n                <div class=\"form-title\">\r\n                    <h3>Obtenez votre arr\u00eat de travail maintenant<\/h3>\r\n                    <p>Formulaire officiel \u00b7 Remplissez tous les champs<\/p>\r\n                <\/div>\r\n            <\/div>\r\n            \r\n            <div class=\"form-wrapper\">\r\n                <!-- ==================================================== -->\r\n                <!--     ZONE D'INT\u00c9GRATION WPForms ID 44                  -->\r\n                <!-- ==================================================== -->\r\n                \r\n                <div class=\"wpforms-container\">\r\n                    <!-- \r\n                    \u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\r\n                    \u26a0\ufe0f  COLLEZ VOTRE CODE WPFORM ICI\r\n                    \u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\r\n                    \r\n                    INSTRUCTIONS :\r\n                    1. Sur votre site WordPress, allez dans WPForms\r\n                    2. \u00c9ditez le formulaire ID 44\r\n                    3. Copiez le code d'int\u00e9gration (shortcode ou HTML)\r\n                    4. Collez-le ci-dessous \u00e0 la place de l'exemple\r\n                    \r\n                    EXEMPLES :\r\n                    - Shortcode : [wpforms id=\"44\"]\r\n                    - HTML : <div class=\"wpforms-form\">...<\/div>\r\n                    - PHP : <?php echo do_shortcode('[wpforms id=\"44\"]'); ?>\r\n                    \u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\u2550\r\n                    -->\r\n                    \r\n                    <!-- ===== COLLEZ VOTRE CODE WPForms ID 44 ICI ===== -->\r\n                    \r\n                    <style id=\"wpforms-css-vars-44\">\n\t\t\t\t#wpforms-44 {\n\t\t\t\t--wpforms-field-size-input-height: 43px;\n--wpforms-field-size-input-spacing: 15px;\n--wpforms-field-size-font-size: 16px;\n--wpforms-field-size-line-height: 19px;\n--wpforms-field-size-padding-h: 14px;\n--wpforms-field-size-checkbox-size: 16px;\n--wpforms-field-size-sublabel-spacing: 5px;\n--wpforms-field-size-icon-size: 1;\n--wpforms-label-size-font-size: 16px;\n--wpforms-label-size-line-height: 19px;\n--wpforms-label-size-sublabel-font-size: 14px;\n--wpforms-label-size-sublabel-line-height: 17px;\n--wpforms-button-size-font-size: 17px;\n--wpforms-button-size-height: 41px;\n--wpforms-button-size-padding-h: 15px;\n--wpforms-button-size-margin-top: 10px;\n--wpforms-container-shadow-size-box-shadow: none;\n\t\t\t}\n\t\t\t<\/style><div class=\"wpforms-container wpforms-container-full wpforms-paypal-commerce wpforms-render-modern\" id=\"wpforms-44\"><form id=\"wpforms-form-44\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"44\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/index.php\/wp-json\/wp\/v2\/pages\/47\" data-token=\"f436251ed89244ea4ac8ab7b974aa6ec\" data-token-time=\"1784100250\"><noscript class=\"wpforms-error-noscript\">Veuillez activer JavaScript dans votre navigateur pour remplir ce formulaire.<\/noscript><div id=\"wpforms-error-noscript\" style=\"display: none;\">Veuillez activer JavaScript dans votre navigateur pour remplir ce formulaire.<\/div><div class=\"wpforms-page-indicator progress\" data-indicator=\"progress\" data-indicator-color=\"#3a54b3\" data-scroll=\"1\" role=\"progressbar\" aria-valuenow=\"1\" aria-valuemin=\"1\" aria-valuemax=\"22\" tabindex=\"-1\"><span class=\"wpforms-page-indicator-page-title\" ><\/span><span class=\"wpforms-page-indicator-page-title-sep\" style=\"display:none;\"> - <\/span><span class=\"wpforms-page-indicator-steps\">Step <span class=\"wpforms-page-indicator-steps-current\">1<\/span> of 22<\/span><div class=\"wpforms-page-indicator-page-progress-wrap\"><div class=\"wpforms-page-indicator-page-progress\" style=\"width:4.5454545454545%;background-color:#3a54b3\"><\/div><\/div><\/div><div class=\"wpforms-field-container\"><div class=\"wpforms-page wpforms-page-1 \" data-page=\"1\"><div id=\"wpforms-44-field_4-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"4\"><\/div><div id=\"wpforms-44-field_13-container\" class=\"wpforms-field wpforms-field-content\" data-field-id=\"13\"><div id=\"wpforms-44-field_13\" class=\"wpforms-field-medium wpforms-field-row\" aria-errormessage=\"wpforms-44-field_13-error\"><h4 class=\"jfWelcome-header form-header\"><span style=\"color:#0000ff\">Bienvenue sur votre auto-diagnostic<\/span><\/h4>\n<div class=\"jfWelcome-description form-subHeader\"><span style=\"color:#3366ff\">Lors de votre auto-diagnostic, votre cas est imm\u00e9diatement transmis \u00e0 nos m\u00e9decins partenaires pour une v\u00e9rification en direct, permettant ainsi d'obtenir votre arr\u00eat maladie rapidement.<\/span><\/div>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><div id=\"wpforms-44-field_3-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"3\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"1\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Commencer<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-2  \" data-page=\"2\" style=\"display:none;\"><div id=\"wpforms-44-field_14-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-modern\" data-field-id=\"14\"><label class=\"wpforms-field-label\" for=\"wpforms-44-field_14\">Choisissez la maladie pr\u00e9sum\u00e9e: <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><select id=\"wpforms-44-field_14\" class=\"wpforms-field-large wpforms-field-required choicesjs-select\" data-size-class=\"wpforms-field-row wpforms-field-large\" data-search-enabled=\"1\" name=\"wpforms[fields][14]\" required=\"required\"><option value=\"\" class=\"placeholder\" disabled  selected='selected'><\/option><option value=\"Veuillez s\u00e9lectionner\"  class=\"choice-1 depth-1\"  >Veuillez s\u00e9lectionner<\/option><option value=\"Gastro-ent\u00e9rite\"  class=\"choice-2 depth-1\"  >Gastro-ent\u00e9rite<\/option><option value=\"Sympt\u00f4me Corona\"  class=\"choice-3 depth-1\"  >Sympt\u00f4me Corona<\/option><option value=\"Stress\"  class=\"choice-7 depth-1\"  >Stress<\/option><option value=\"Migraine\"  class=\"choice-6 depth-1\"  >Migraine<\/option><option value=\"Mal de dos\"  class=\"choice-5 depth-1\"  >Mal de dos<\/option><option value=\"Douleurs menstruelles\"  class=\"choice-4 depth-1\"  >Douleurs menstruelles<\/option><option value=\"Cystite\"  class=\"choice-8 depth-1\"  >Cystite<\/option><option value=\"Blessures\"  class=\"choice-9 depth-1\"  >Blessures<\/option><option value=\"Douleurs abdominales \/ pelviennes\"  class=\"choice-10 depth-1\"  >Douleurs abdominales \/ pelviennes<\/option><option value=\"Hypertension\"  class=\"choice-11 depth-1\"  >Hypertension<\/option><option value=\"Allergie\"  class=\"choice-12 depth-1\"  >Allergie<\/option><option value=\"Le corps n\u2019est pas libre de ses mouvements\"  class=\"choice-13 depth-1\"  >Le corps n\u2019est pas libre de ses mouvements<\/option><option value=\"Probl\u00e8mes dentaires\"  class=\"choice-15 depth-1\"  >Probl\u00e8mes dentaires<\/option><option value=\"Maux de t\u00eate\"  class=\"choice-14 depth-1\"  >Maux de t\u00eate<\/option><option value=\"Naus\u00e9es\/ Vomissements\"  class=\"choice-16 depth-1\"  >Naus\u00e9es\/ Vomissements<\/option><option value=\"Gastrite\"  class=\"choice-17 depth-1\"  >Gastrite<\/option><option value=\"Probl\u00e8mes articulaires\"  class=\"choice-18 depth-1\"  >Probl\u00e8mes articulaires<\/option><option value=\"\u00c9v\u00e8nement : Deuil, crise etc.\"  class=\"choice-19 depth-1\"  >\u00c9v\u00e8nement : Deuil, crise etc.<\/option><option value=\"Syndrome d\u2019\u00e9puisement\"  class=\"choice-20 depth-1\"  >Syndrome d\u2019\u00e9puisement<\/option><\/select><div id=\"wpforms-44-field_14-description\" class=\"wpforms-field-description\">Une seule possibilit\u00e9<\/div><\/div><div id=\"wpforms-44-field_8-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"8\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"2\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-3  \" data-page=\"3\" style=\"display:none;\"><div id=\"wpforms-44-field_15-container\" class=\"wpforms-field wpforms-field-layout\" data-field-id=\"15\"><div class=\"wpforms-field-layout-columns wpforms-field-layout-preset-100\"><div class=\"wpforms-layout-column wpforms-layout-column-100\" ><div id=\"wpforms-44-field_16-container\" class=\"wpforms-field wpforms-field-checkbox wpforms-list-2-columns\" data-field-id=\"16\"><fieldset><legend class=\"wpforms-field-label\">Avez-vous d\u00e9j\u00e0 \u00e9t\u00e9 diagnostiqu\u00e9 pour ce sympt\u00f4me par un m\u00e9decin ? <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><ul id=\"wpforms-44-field_16\" class=\"wpforms-field-required\" data-choice-limit=\"1\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_16_1\" data-rule-check-limit=\"true\" name=\"wpforms[fields][16][]\" value=\"Oui\" aria-errormessage=\"wpforms-44-field_16_1-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_16_1\">Oui<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_16_2\" data-rule-check-limit=\"true\" name=\"wpforms[fields][16][]\" value=\"Non\" aria-errormessage=\"wpforms-44-field_16_2-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_16_2\">Non<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_16_3\" data-rule-check-limit=\"true\" name=\"wpforms[fields][16][]\" value=\"Peut-etre\" aria-errormessage=\"wpforms-44-field_16_3-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_16_3\">Peut-etre<\/label><\/li><\/ul><\/fieldset><\/div><\/div><\/div><\/div><div id=\"wpforms-44-field_6-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"6\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"3\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-4  \" data-page=\"4\" style=\"display:none;\"><div id=\"wpforms-44-field_17-container\" class=\"wpforms-field wpforms-field-checkbox wpforms-list-3-columns\" data-field-id=\"17\"><fieldset><legend class=\"wpforms-field-label\">\ud83e\udd15 Choisissez vos sympt\u00f4mes : <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><ul id=\"wpforms-44-field_17\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_17_1\" name=\"wpforms[fields][17][]\" value=\"Fi\u00e8vre\" aria-errormessage=\"wpforms-44-field_17_1-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_17_1\">Fi\u00e8vre<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_17_2\" name=\"wpforms[fields][17][]\" value=\"Naus\u00e9es\" aria-errormessage=\"wpforms-44-field_17_2-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_17_2\">Naus\u00e9es<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_17_3\" name=\"wpforms[fields][17][]\" value=\"Diarrh\u00e9e\" aria-errormessage=\"wpforms-44-field_17_3-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_17_3\">Diarrh\u00e9e<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_17_4\" name=\"wpforms[fields][17][]\" value=\"Toux sans mucus\" aria-errormessage=\"wpforms-44-field_17_4-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_17_4\">Toux sans mucus<\/label><\/li><li class=\"choice-5 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_17_5\" name=\"wpforms[fields][17][]\" value=\"Toux avec mucosit\u00e9s\" aria-errormessage=\"wpforms-44-field_17_5-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_17_5\">Toux avec mucosit\u00e9s<\/label><\/li><li class=\"choice-6 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_17_6\" name=\"wpforms[fields][17][]\" value=\"Malaise\" aria-errormessage=\"wpforms-44-field_17_6-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_17_6\">Malaise<\/label><\/li><li class=\"choice-7 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_17_7\" name=\"wpforms[fields][17][]\" value=\"Fatigue\" aria-errormessage=\"wpforms-44-field_17_7-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_17_7\">Fatigue<\/label><\/li><li class=\"choice-9 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_17_9\" name=\"wpforms[fields][17][]\" value=\"Hypertension art\u00e9rielle\" aria-errormessage=\"wpforms-44-field_17_9-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_17_9\">Hypertension art\u00e9rielle<\/label><\/li><li class=\"choice-8 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_17_8\" name=\"wpforms[fields][17][]\" value=\"Le corps n&#039;est pas libre de ses mouvements\" aria-errormessage=\"wpforms-44-field_17_8-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_17_8\">Le corps n'est pas libre de ses mouvements<\/label><\/li><li class=\"choice-10 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_17_10\" name=\"wpforms[fields][17][]\" value=\"\u00c9v\u00e9nement stressant de la vie\" aria-errormessage=\"wpforms-44-field_17_10-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_17_10\">\u00c9v\u00e9nement stressant de la vie<\/label><\/li><li class=\"choice-11 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_17_11\" name=\"wpforms[fields][17][]\" value=\"Troubles du sommeil\" aria-errormessage=\"wpforms-44-field_17_11-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_17_11\">Troubles du sommeil<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-44-field_7-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"7\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"4\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-5  \" data-page=\"5\" style=\"display:none;\"><div id=\"wpforms-44-field_24-container\" class=\"wpforms-field wpforms-field-checkbox wpforms-list-3-columns\" data-field-id=\"24\"><fieldset><legend class=\"wpforms-field-label\">douleurs situ\u00e9es dans la :  <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><ul id=\"wpforms-44-field_24\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_24_1\" name=\"wpforms[fields][24][]\" value=\"T\u00eate\" aria-errormessage=\"wpforms-44-field_24_1-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_24_1\">T\u00eate<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_24_2\" name=\"wpforms[fields][24][]\" value=\"Ventre\" aria-errormessage=\"wpforms-44-field_24_2-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_24_2\">Ventre<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_24_3\" name=\"wpforms[fields][24][]\" value=\"Dent\" aria-errormessage=\"wpforms-44-field_24_3-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_24_3\">Dent<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_24_4\" name=\"wpforms[fields][24][]\" value=\"Dos\" aria-errormessage=\"wpforms-44-field_24_4-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_24_4\">Dos<\/label><\/li><li class=\"choice-7 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_24_7\" name=\"wpforms[fields][24][]\" value=\"Cou\" aria-errormessage=\"wpforms-44-field_24_7-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_24_7\">Cou<\/label><\/li><li class=\"choice-6 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_24_6\" name=\"wpforms[fields][24][]\" value=\"Membres\" aria-errormessage=\"wpforms-44-field_24_6-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_24_6\">Membres<\/label><\/li><li class=\"choice-5 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_24_5\" name=\"wpforms[fields][24][]\" value=\"Oreille\" aria-errormessage=\"wpforms-44-field_24_5-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_24_5\">Oreille<\/label><\/li><li class=\"choice-8 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_24_8\" name=\"wpforms[fields][24][]\" value=\"Organe sexuel\" aria-errormessage=\"wpforms-44-field_24_8-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_24_8\">Organe sexuel<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-44-field_23-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"23\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"5\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-6  \" data-page=\"6\" style=\"display:none;\"><div id=\"wpforms-44-field_26-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"26\"><label class=\"wpforms-field-label\" for=\"wpforms-44-field_26\">\ud83d\udcdd D\u00e9crire tous les autres sympt\u00f4mes :<\/label><textarea id=\"wpforms-44-field_26\" class=\"wpforms-field-medium\" name=\"wpforms[fields][26]\" aria-errormessage=\"wpforms-44-field_26-error\" ><\/textarea><\/div><div id=\"wpforms-44-field_25-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"25\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"6\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-7  \" data-page=\"7\" style=\"display:none;\"><div id=\"wpforms-44-field_27-container\" class=\"wpforms-field wpforms-field-checkbox wpforms-list-3-columns\" data-field-id=\"27\"><fieldset><legend class=\"wpforms-field-label\">\u26a1 Est-ce que les sympt\u00f4mes sont apparues soudainement ? <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><ul id=\"wpforms-44-field_27\" class=\"wpforms-field-required\" data-choice-limit=\"1\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_27_1\" data-rule-check-limit=\"true\" name=\"wpforms[fields][27][]\" value=\"Oui\" aria-errormessage=\"wpforms-44-field_27_1-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_27_1\">Oui<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_27_2\" data-rule-check-limit=\"true\" name=\"wpforms[fields][27][]\" value=\"Non\" aria-errormessage=\"wpforms-44-field_27_2-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_27_2\">Non<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_27_3\" data-rule-check-limit=\"true\" name=\"wpforms[fields][27][]\" value=\"Peut-\u00eatre\" aria-errormessage=\"wpforms-44-field_27_3-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_27_3\">Peut-\u00eatre<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-44-field_28-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"28\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"7\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-8  \" data-page=\"8\" style=\"display:none;\"><div id=\"wpforms-44-field_30-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"30\"><label class=\"wpforms-field-label\" for=\"wpforms-44-field_30\">\ud83d\udc8a Si vous prenez des m\u00e9dicaments : Quels sont les m\u00e9dicaments pris r\u00e9guli\u00e8rement ?<\/label><textarea id=\"wpforms-44-field_30\" class=\"wpforms-field-medium\" name=\"wpforms[fields][30]\" aria-errormessage=\"wpforms-44-field_30-error\" ><\/textarea><\/div><div id=\"wpforms-44-field_29-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"29\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"8\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-9  \" data-page=\"9\" style=\"display:none;\"><div id=\"wpforms-44-field_33-container\" class=\"wpforms-field wpforms-field-content\" data-field-id=\"33\"><div id=\"wpforms-44-field_33\" class=\"wpforms-field-medium wpforms-field-row\" aria-errormessage=\"wpforms-44-field_33-error\"><p>\u26a0\ufe0f Pr\u00e9sentez-vous l'un de ces facteurs de risque ?<\/p>\n<ul>\n<li><span style=\"color:#3366ff\">Vous avez des difficult\u00e9s respiratoires, des vomissements ou de la diarrh\u00e9e<\/span><\/li>\n<li><span style=\"color:#3366ff\">Bruits ou obstructions lors de la respiration<\/span><\/li>\n<li><span style=\"color:#3366ff\">Enceinte, immunod\u00e9ficience<\/span><\/li>\n<li><span style=\"color:#3366ff\">Douleur intense, en particulier dans l'oreille, le visage ou les membres<\/span><\/li>\n<li><span style=\"color:#3366ff\">Douleur au larynx, \u00e0 la poitrine ou \u00e0 l'abdomen<\/span><\/li>\n<li><span style=\"color:#3366ff\">Maladie cardiaque, respiratoire ou intestinale chronique<\/span><\/li>\n<li><span style=\"color:#3366ff\">Voyage tropical au cours des deux derniers mois<\/span><\/li>\n<li><span style=\"color:#3366ff\">Sentiment de maladie grave ou difficult\u00e9 \u00e0 avaler<\/span><\/li>\n<li><span style=\"color:#3366ff\">Paralysie, troubles de la conscience, saignements, \u00e9ruptions cutan\u00e9es<\/span><\/li>\n<\/ul>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><div id=\"wpforms-44-field_31-container\" class=\"wpforms-field wpforms-field-checkbox wpforms-conditional-trigger\" data-field-id=\"31\"><fieldset><legend class=\"wpforms-field-label wpforms-label-hide\" aria-hidden=\"false\">\u26a0\ufe0f Pr\u00e9sentez-vous l&#039;un de ces facteurs de risque ? <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><ul id=\"wpforms-44-field_31\" class=\"wpforms-field-required\" data-choice-limit=\"1\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_31_1\" data-rule-check-limit=\"true\" name=\"wpforms[fields][31][]\" value=\"Oui\" aria-errormessage=\"wpforms-44-field_31_1-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_31_1\">Oui<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_31_2\" data-rule-check-limit=\"true\" name=\"wpforms[fields][31][]\" value=\"Non\" aria-errormessage=\"wpforms-44-field_31_2-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_31_2\">Non<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-44-field_34-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"34\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"9\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-10  \" data-page=\"10\" style=\"display:none;\"><div id=\"wpforms-44-field_93-container\" class=\"wpforms-field wpforms-field-content wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"93\" style=\"display:none;\"><div id=\"wpforms-44-field_93\" class=\"wpforms-field-medium wpforms-field-row\" aria-errormessage=\"wpforms-44-field_93-error\"><h4>Votre cas ne peux pas \u00eatre traiter en ligne sans consultation d'un m\u00e9decin !<\/h4>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><div id=\"wpforms-44-field_90-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"90\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-prev wpforms-disabled\"\n\t\t\t\t\tdata-action=\"prev\" data-page=\"10\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Pr\u00e9c\u00e9dent<\/button><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"10\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-11  \" data-page=\"11\" style=\"display:none;\"><div id=\"wpforms-44-field_35-container\" class=\"wpforms-field wpforms-field-checkbox wpforms-list-2-columns\" data-field-id=\"35\"><fieldset><legend class=\"wpforms-field-label\">\ud83e\udd14 Votre employeur est-il insatisfait de votre travail, m\u00e9fiant ou a d\u00e9j\u00e0 contest\u00e9 des attestations ?  <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><ul id=\"wpforms-44-field_35\" class=\"wpforms-field-required\" data-choice-limit=\"1\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_35_1\" data-rule-check-limit=\"true\" name=\"wpforms[fields][35][]\" value=\"Oui\" aria-errormessage=\"wpforms-44-field_35_1-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_35_1\">Oui<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_35_2\" data-rule-check-limit=\"true\" name=\"wpforms[fields][35][]\" value=\"Non\" aria-errormessage=\"wpforms-44-field_35_2-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_35_2\">Non<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-44-field_39-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"39\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"11\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-12  \" data-page=\"12\" style=\"display:none;\"><div id=\"wpforms-44-field_37-container\" class=\"wpforms-field wpforms-field-checkbox wpforms-list-2-columns\" data-field-id=\"37\"><fieldset><legend class=\"wpforms-field-label\">\ud83d\udcdd Avez-vous besoin d&#039;un nouvel arr\u00eat maladie ou d&#039;une prolongation ? <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><ul id=\"wpforms-44-field_37\" class=\"wpforms-field-required\" data-choice-limit=\"1\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_37_1\" data-rule-check-limit=\"true\" name=\"wpforms[fields][37][]\" value=\"Nouvel Arr\u00eat maladie\" aria-errormessage=\"wpforms-44-field_37_1-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_37_1\">Nouvel Arr\u00eat maladie<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_37_2\" data-rule-check-limit=\"true\" name=\"wpforms[fields][37][]\" value=\"Suivi\" aria-errormessage=\"wpforms-44-field_37_2-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_37_2\">Suivi<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-44-field_38-container\" class=\"wpforms-field wpforms-field-content\" data-field-id=\"38\"><div id=\"wpforms-44-field_38\" class=\"wpforms-field-medium wpforms-field-row\" aria-errormessage=\"wpforms-44-field_38-error\"><p><span style=\"color:#3366ff\">Choisissez le suivi de l'arr\u00eat maladie uniquement si vous avez d\u00e9j\u00e0 eu un arr\u00eat maladie pour les m\u00eames sympt\u00f4mes et pour un maximum de 7 jours<\/span><\/p>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><div id=\"wpforms-44-field_40-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"40\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"12\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-13  \" data-page=\"13\" style=\"display:none;\"><div id=\"wpforms-44-field_41-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"41\"><label class=\"wpforms-field-label\" for=\"wpforms-44-field_41\">\ud83d\udc68\u200d\ud83d\udd27 Quelle est votre profession actuelle ?  <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><textarea id=\"wpforms-44-field_41\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][41]\" aria-errormessage=\"wpforms-44-field_41-error\" required><\/textarea><\/div><div id=\"wpforms-44-field_42-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"42\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"13\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-14  \" data-page=\"14\" style=\"display:none;\"><div id=\"wpforms-44-field_46-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-id=\"46\"><fieldset><legend class=\"wpforms-field-label\">\ud83d\udcaa \u00c0 quel point votre travail est-il physiquement exigeant ?  <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><ul id=\"wpforms-44-field_46\" class=\"wpforms-field-required\" data-choice-limit=\"1\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_46_1\" data-rule-check-limit=\"true\" name=\"wpforms[fields][46][]\" value=\"L\u00e9ger\" aria-errormessage=\"wpforms-44-field_46_1-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_46_1\">L\u00e9ger<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_46_2\" data-rule-check-limit=\"true\" name=\"wpforms[fields][46][]\" value=\"Moyen\" aria-errormessage=\"wpforms-44-field_46_2-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_46_2\">Moyen<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_46_3\" data-rule-check-limit=\"true\" name=\"wpforms[fields][46][]\" value=\"Elev\u00e9\" aria-errormessage=\"wpforms-44-field_46_3-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_46_3\">Elev\u00e9<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-44-field_45-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"45\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"14\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-15  \" data-page=\"15\" style=\"display:none;\"><div id=\"wpforms-44-field_47-container\" class=\"wpforms-field wpforms-field-content\" data-field-id=\"47\"><div id=\"wpforms-44-field_47\" class=\"wpforms-field-medium wpforms-field-row\" aria-errormessage=\"wpforms-44-field_47-error\"><h4><img decoding=\"async\" class=\"emoji\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/15.0.3\/svg\/1f4c6.svg\" alt=\"\ud83d\udcc6\" \/>\u00a0Choisissez les dates de d\u00e9but &amp; de fin de votre incapacit\u00e9 de travail :<\/h4>\n<p>C'est-\u00e0-dire qu'en raison de la maladie, vous ne pouvez plus exercer votre m\u00e9tier ou vous pr\u00e9sentez un risque de retarder la gu\u00e9rison.<\/p>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><div id=\"wpforms-44-field_48-container\" class=\"wpforms-field wpforms-field-layout\" data-field-id=\"48\"><div class=\"wpforms-field-layout-rows wpforms-field-large\"><div class=\"wpforms-layout-row\"><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-44-field_49-container\" class=\"wpforms-field wpforms-field-date-time\" data-field-id=\"49\"><label class=\"wpforms-field-label\" for=\"wpforms-44-field_49\">Date de d\u00e9but: <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><div class=\"wpforms-datepicker-wrap\"><input type=\"text\" id=\"wpforms-44-field_49\" class=\"wpforms-field-date-time-date wpforms-datepicker wpforms-field-required wpforms-field-medium\" data-date-format=\"d\/m\/Y\" data-disable-past-dates=\"0\" data-input=\"true\" name=\"wpforms[fields][49][date]\" aria-errormessage=\"wpforms-44-field_49-error\" required><a title=\"Effacer la date\" data-clear role=\"button\" tabindex=\"0\" class=\"wpforms-datepicker-clear\" aria-label=\"Effacer la date\" style=\"display:none;\"><\/a><\/div><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-44-field_50-container\" class=\"wpforms-field wpforms-field-date-time\" data-field-id=\"50\"><label class=\"wpforms-field-label\" for=\"wpforms-44-field_50\">Date de fin: <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><div class=\"wpforms-datepicker-wrap\"><input type=\"text\" id=\"wpforms-44-field_50\" class=\"wpforms-field-date-time-date wpforms-datepicker wpforms-field-required wpforms-field-medium\" data-date-format=\"d\/m\/Y\" data-disable-past-dates=\"0\" data-input=\"true\" name=\"wpforms[fields][50][date]\" aria-errormessage=\"wpforms-44-field_50-error\" required><a title=\"Effacer la date\" data-clear role=\"button\" tabindex=\"0\" class=\"wpforms-datepicker-clear\" aria-label=\"Effacer la date\" style=\"display:none;\"><\/a><\/div><\/div><\/div><\/div><\/div><\/div><div id=\"wpforms-44-field_43-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"43\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"15\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-16  \" data-page=\"16\" style=\"display:none;\"><div id=\"wpforms-44-field_52-container\" class=\"wpforms-field wpforms-field-layout\" data-field-id=\"52\"><div class=\"wpforms-field-layout-rows wpforms-field-large\"><div class=\"wpforms-layout-row\"><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-44-field_53-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"53\"><label class=\"wpforms-field-label\" for=\"wpforms-44-field_53\">Pr\u00e9nom: <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-44-field_53\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][53]\" aria-errormessage=\"wpforms-44-field_53-error\" required><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-44-field_54-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"54\"><label class=\"wpforms-field-label\" for=\"wpforms-44-field_54\">Nom : <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-44-field_54\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][54]\" aria-errormessage=\"wpforms-44-field_54-error\" required><\/div><\/div><\/div><div class=\"wpforms-layout-row\"><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-44-field_55-container\" class=\"wpforms-field wpforms-field-date-time\" data-field-id=\"55\"><label class=\"wpforms-field-label\" for=\"wpforms-44-field_55\">\ud83c\udf82 Date de naissance : <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><div class=\"wpforms-datepicker-wrap\"><input type=\"text\" id=\"wpforms-44-field_55\" class=\"wpforms-field-date-time-date wpforms-datepicker wpforms-field-required wpforms-field-medium\" data-date-format=\"d\/m\/Y\" data-disable-past-dates=\"0\" data-input=\"true\" name=\"wpforms[fields][55][date]\" aria-errormessage=\"wpforms-44-field_55-error\" required><a title=\"Effacer la date\" data-clear role=\"button\" tabindex=\"0\" class=\"wpforms-datepicker-clear\" aria-label=\"Effacer la date\" style=\"display:none;\"><\/a><\/div><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-44-field_56-container\" class=\"wpforms-field wpforms-field-phone\" data-field-id=\"56\"><label class=\"wpforms-field-label\" for=\"wpforms-44-field_56\">T\u00e9l\u00e9phone: <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"tel\" id=\"wpforms-44-field_56\" class=\"wpforms-field-medium wpforms-field-required\" data-rule-int-phone-field=\"true\" name=\"wpforms[fields][56]\" aria-label=\"T\u00e9l\u00e9phone:\" aria-errormessage=\"wpforms-44-field_56-error\" required><\/div><\/div><\/div><div class=\"wpforms-layout-row\"><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-44-field_78-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"78\"><label class=\"wpforms-field-label\" for=\"wpforms-44-field_78\">E-mail <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-44-field_78\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][78]\" spellcheck=\"false\" aria-errormessage=\"wpforms-44-field_78-error\" required><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-50\"><\/div><\/div><\/div><\/div><div id=\"wpforms-44-field_44-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"44\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"16\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-17  \" data-page=\"17\" style=\"display:none;\"><div id=\"wpforms-44-field_51-container\" class=\"wpforms-field wpforms-field-layout\" data-field-id=\"51\"><div class=\"wpforms-field-layout-rows wpforms-field-large\"><div class=\"wpforms-layout-row\"><div class=\"wpforms-layout-column wpforms-layout-column-100\"><div id=\"wpforms-44-field_61-container\" class=\"wpforms-field wpforms-field-address\" data-field-id=\"61\"><fieldset><legend class=\"wpforms-field-label\">Adresse: <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><div class=\"wpforms-field-row wpforms-field-large\"><div ><input type=\"text\" id=\"wpforms-44-field_61\" class=\"wpforms-field-address-address1 wpforms-field-required\" name=\"wpforms[fields][61][address1]\" aria-errormessage=\"wpforms-44-field_61-error\" required><label for=\"wpforms-44-field_61\" class=\"wpforms-field-sublabel after\">Adresse ligne\u00a01<\/label><\/div><\/div><div class=\"wpforms-field-row wpforms-field-large\"><div class=\"wpforms-field-row-block wpforms-one-half wpforms-first\"><input type=\"text\" id=\"wpforms-44-field_61-city\" class=\"wpforms-field-address-city wpforms-field-required\" name=\"wpforms[fields][61][city]\" aria-errormessage=\"wpforms-44-field_61-city-error\" required><label for=\"wpforms-44-field_61-city\" class=\"wpforms-field-sublabel after\">Ville<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-44-field_61-state\" class=\"wpforms-field-address-state wpforms-field-required\" name=\"wpforms[fields][61][state]\" aria-errormessage=\"wpforms-44-field_61-state-error\" required><label for=\"wpforms-44-field_61-state\" class=\"wpforms-field-sublabel after\">\u00c9tat \/ Province \/ R\u00e9gion<\/label><\/div><\/div><div class=\"wpforms-field-row wpforms-field-large\"><div class=\"wpforms-field-row-block wpforms-one-half wpforms-first\"><input type=\"text\" id=\"wpforms-44-field_61-postal\" class=\"wpforms-field-address-postal wpforms-field-required\" name=\"wpforms[fields][61][postal]\" aria-errormessage=\"wpforms-44-field_61-postal-error\" required><label for=\"wpforms-44-field_61-postal\" class=\"wpforms-field-sublabel after\">Code postal<\/label><\/div><\/div><\/fieldset><\/div><\/div><\/div><div class=\"wpforms-layout-row\"><div class=\"wpforms-layout-column wpforms-layout-column-100\"><div id=\"wpforms-44-field_82-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"82\"><label class=\"wpforms-field-label\" for=\"wpforms-44-field_82\">Pays <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-44-field_82\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][82]\" placeholder=\"France\" aria-errormessage=\"wpforms-44-field_82-error\" required><\/div><\/div><\/div><\/div><\/div><div id=\"wpforms-44-field_36-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"36\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"17\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-18  \" data-page=\"18\" style=\"display:none;\"><div id=\"wpforms-44-field_64-container\" class=\"wpforms-field wpforms-field-layout\" data-field-id=\"64\"><div class=\"wpforms-field-layout-rows wpforms-field-large\"><div class=\"wpforms-layout-row\"><div class=\"wpforms-layout-column wpforms-layout-column-100\"><div id=\"wpforms-44-field_75-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"75\"><label class=\"wpforms-field-label\" for=\"wpforms-44-field_75\">Localisation du m\u00e9decin: <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-44-field_75\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][75]\" aria-errormessage=\"wpforms-44-field_75-error\" required><\/div><\/div><\/div><\/div><\/div><div id=\"wpforms-44-field_62-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"62\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"18\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-19  \" data-page=\"19\" style=\"display:none;\"><div id=\"wpforms-44-field_68-container\" class=\"wpforms-field wpforms-field-checkbox wpforms-list-inline\" data-field-id=\"68\"><fieldset><legend class=\"wpforms-field-label\">Cochez la case appropri\u00e9e: <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><ul id=\"wpforms-44-field_68\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_68_1\" name=\"wpforms[fields][68][]\" value=\"Employ\u00e9\" aria-errormessage=\"wpforms-44-field_68_1-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_68_1\">Employ\u00e9<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_68_2\" name=\"wpforms[fields][68][]\" value=\"Ind\u00e9pendant\" aria-errormessage=\"wpforms-44-field_68_2-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_68_2\">Ind\u00e9pendant<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_68_3\" name=\"wpforms[fields][68][]\" value=\"Fonctionnaire\" aria-errormessage=\"wpforms-44-field_68_3-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_68_3\">Fonctionnaire<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_68_4\" name=\"wpforms[fields][68][]\" value=\"Activit\u00e9 non salari\u00e9 agricole\" aria-errormessage=\"wpforms-44-field_68_4-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_68_4\">Activit\u00e9 non salari\u00e9 agricole<\/label><\/li><li class=\"choice-5 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_68_5\" name=\"wpforms[fields][68][]\" value=\"\u00c9tudiant\" aria-errormessage=\"wpforms-44-field_68_5-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_68_5\">\u00c9tudiant<\/label><\/li><li class=\"choice-7 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_68_7\" name=\"wpforms[fields][68][]\" value=\"Sans emploi\" aria-errormessage=\"wpforms-44-field_68_7-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_68_7\">Sans emploi<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-44-field_67-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"67\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"19\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-20  \" data-page=\"20\" style=\"display:none;\"><div id=\"wpforms-44-field_69-container\" class=\"wpforms-field wpforms-field-layout\" data-field-id=\"69\"><div class=\"wpforms-field-layout-rows wpforms-field-large\"><div class=\"wpforms-layout-row\"><div class=\"wpforms-layout-column wpforms-layout-column-100\"><div id=\"wpforms-44-field_70-container\" class=\"wpforms-field wpforms-field-number\" data-field-id=\"70\"><label class=\"wpforms-field-label\" for=\"wpforms-44-field_70\">Num\u00e9ro de s\u00e9curit\u00e9 sociale : <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"number\" id=\"wpforms-44-field_70\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][70]\" step=\"any\" aria-errormessage=\"wpforms-44-field_70-error\" required><\/div><\/div><\/div><\/div><\/div><div id=\"wpforms-44-field_66-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"66\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"20\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-21  \" data-page=\"21\" style=\"display:none;\"><div id=\"wpforms-44-field_74-container\" class=\"wpforms-field wpforms-field-content\" data-field-id=\"74\"><div id=\"wpforms-44-field_74\" class=\"wpforms-field-large wpforms-field-row\" aria-errormessage=\"wpforms-44-field_74-error\"><h4><span class=\"jsQuestionLabelContainer jfQuestionLabelContainer\"><strong>Paiement s\u00e9curis\u00e9 de votre arr\u00eat maladie<\/strong><\/span><span class=\"jfRequiredStar\">*<\/span><\/h4>\n<h6><span style=\"font-family:monospace;font-size:16px\">Votre auto-diagnostic est d\u00e9j\u00e0 transmis \u00e0 l'un de nos m\u00e9decins partenaires<\/span><span style=\"font-family:monospace;font-size:16px\">,<\/span><\/h6>\n<p>vous recevrez votre arr\u00eat maladie tr\u00e8s rapidement<\/p>\n<div class=\"paymentCard-footer-wrapper\">\n<div class=\"paymentCard-productListWrapper\">\n<div class=\"paymentCard-footer\">\n<div class=\"paymentCard-footerRight new-payment-coupon\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>.<\/p>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><div id=\"wpforms-44-field_122-container\" class=\"wpforms-field wpforms-field-payment-single\" data-field-id=\"122\"><label class=\"wpforms-field-label\">Prix :<\/label><div class=\"wpforms-single-item-price-content\"><div class=\"wpforms-single-item-price wpforms-field-medium wpforms-payment-price\">Prix\u00a0: <span class=\"wpforms-price\">24,00 &euro;<\/span><\/div><\/div><input type=\"hidden\" id=\"wpforms-44-field_122\" class=\"wpforms-field-medium wpforms-payment-price\" name=\"wpforms[fields][122]\" value=\"24,00 &euro;\"><\/div><div id=\"wpforms-44-field_120-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"120\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"21\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-22 last \" data-page=\"22\" style=\"display:none;\"><div id=\"wpforms-44-field_121-container\" class=\"wpforms-field wpforms-field-paypal-commerce\" data-field-id=\"121\"><label class=\"wpforms-field-label\">Paiement <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"hidden\" name=\"wpforms[fields][121][orderID]\" class=\"wpforms-paypal-commerce-order-id\" \/><input type=\"hidden\" name=\"wpforms[fields][121][subscriptionID]\" class=\"wpforms-paypal-commerce-subscription-id\" \/><input type=\"hidden\" name=\"wpforms[fields][121][subscriptionProcessorID]\" class=\"wpforms-paypal-commerce-subscription-processor-id\" \/><input type=\"hidden\" name=\"wpforms[fields][121][source]\" class=\"wpforms-paypal-commerce-source\" \/><input type=\"hidden\" name=\"wpforms[fields][121][fastlane_token]\" class=\"wpforms-paypal-commerce-fastlane-token\" \/><div class=\"wpforms-paypal-commerce-card-fields \"><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-paypal-commerce-supported-cards\"><div class=\"wpforms-paypal-commerce-maestro-icon\"><\/div><div class=\"wpforms-paypal-commerce-mastercard-icon\"><\/div><div class=\"wpforms-paypal-commerce-visa-icon\"><\/div><\/div><\/div><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-paypal-commerce-number\"><div id=\"wpforms-44-field_121-cardnumber\" class=\"wpforms-field-paypal-commerce-cardnumber wpforms-field-required\" aria-errormessage=\"wpforms-44-field_121-cardnumber-error\" data-required=\"required\"><\/div><input type=\"text\" class=\"wpforms-paypal-commerce-credit-card-hidden-input\" name=\"wpforms[paypal-commerce-credit-card-hidden-input-44]\" id=\"wpforms-paypal-commerce-credit-card-hidden-input-44-number\" disabled style=\"display: none;\"><label for=\"wpforms-paypal-commerce-credit-card-hidden-input-44-number\" class=\"wpforms-field-sublabel after\">Num\u00e9ro de carte<\/label><\/div><\/div><div class=\"wpforms-field-row wpforms-field-row-responsive wpforms-field-medium\"><div class=\"wpforms-field-row-block wpforms-one-half wpforms-first wpforms-field-paypal-commerce-date\"><div id=\"wpforms-44-field_121-carddate\" class=\"wpforms-field-paypal-commerce-carddate wpforms-field-required\" aria-errormessage=\"wpforms-44-field_121-carddate-error\" data-required=\"required\"><\/div><input type=\"text\" class=\"wpforms-paypal-commerce-credit-card-hidden-input\" name=\"wpforms[paypal-commerce-credit-card-hidden-input-44]\" id=\"wpforms-paypal-commerce-credit-card-hidden-input-44-date\" disabled style=\"display: none;\"><label for=\"wpforms-paypal-commerce-credit-card-hidden-input-44-date\" class=\"wpforms-field-sublabel after\">Expiration Date<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half wpforms-field-paypal-commerce-code\"><div id=\"wpforms-44-field_121-cardcode\" class=\"wpforms-field-paypal-commerce-cardcode wpforms-field-required\" aria-errormessage=\"wpforms-44-field_121-cardcode-error\" data-required=\"required\"><\/div><input type=\"text\" class=\"wpforms-paypal-commerce-credit-card-hidden-input\" name=\"wpforms[paypal-commerce-credit-card-hidden-input-44]\" id=\"wpforms-paypal-commerce-credit-card-hidden-input-44-code\" disabled style=\"display: none;\"><label for=\"wpforms-paypal-commerce-credit-card-hidden-input-44-code\" class=\"wpforms-field-sublabel after\">Code de s\u00e9curit\u00e9 (CVC)<\/label><\/div><\/div><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-paypal-commerce-name\"><input type=\"text\" id=\"wpforms-44-field_121-cardname\" class=\"wpforms-field-paypal-commerce-cardname wpforms-field-required\" name=\"wpforms[fields][121][cardname]\" aria-errormessage=\"wpforms-44-field_121-cardname-error\" required><label for=\"wpforms-44-field_121-cardname\" class=\"wpforms-field-sublabel after\">Card Holder Name<\/label><\/div><\/div><\/div><\/div><div id=\"wpforms-44-field_5-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"5\"><\/div><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" style=\"display:none;\"><input type=\"hidden\" name=\"wpforms[id]\" value=\"44\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/app.vosol-france.com\/index.php\/wp-json\/wp\/v2\/pages\/47\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-44\" class=\"wpforms-submit\" data-alt-text=\"Sending...\" data-submit-text=\"Terminer\" aria-live=\"assertive\" value=\"wpforms-submit\">Terminer<\/button><img decoding=\"async\" src=\"https:\/\/app.vosol-france.com\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Chargement en cours\"><div class=\"wpforms-paypal-commerce-single-submit-button size-medium\"><img decoding=\"async\" src=\"https:\/\/app.vosol-france.com\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-paypal-commerce-single-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Chargement en cours\"><div class=\"wpforms-paypal-commerce-applepay-button wpforms-hidden\" style=\"--apple-pay-button-border-radius: 23px;\"><\/div><div class=\"wpforms-paypal-commerce-googlepay-button wpforms-hidden\"><\/div><\/div><div class=\"wpforms-paypal-commerce-subscriptions-submit-button size-medium\"><img decoding=\"async\" src=\"https:\/\/app.vosol-france.com\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-paypal-commerce-recurring-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Chargement en cours\"><\/div><\/div><\/form><\/div>  <!-- .wpforms-container -->\r\n                    \r\n                    <!-- \r\n                    OU si vous avez le code HTML :\r\n                    \r\n                    <div class=\"wpforms-form\">\r\n                        <!-- Code HTML g\u00e9n\u00e9r\u00e9 par WPForms -->\r\n                    <\/div>\r\n                    -->\r\n                    \r\n                    <!-- ===== FIN DE LA ZONE D'INT\u00c9GRATION ===== -->\r\n                <\/div>\r\n\r\n                <!-- ==================================================== -->\r\n                <!--     FIN ZONE D'INT\u00c9GRATION WPForms                   -->\r\n                <!-- ==================================================== -->\r\n\r\n                <!-- Message d'aide si le formulaire n'est pas charg\u00e9 -->\r\n                <div id=\"wpformsFallback\" style=\"display: none;\">\r\n                    <div class=\"integration-instruction\">\r\n                        <i class=\"fas fa-code\"><\/i>\r\n                        <h4>Int\u00e9grez votre formulaire WPForms ID 44<\/h4>\r\n                        <p>\r\n                            Collez votre code WPForms dans la zone pr\u00e9vue ci-dessus.\r\n                        <\/p>\r\n                        <div class=\"code-block\">\r\n                            <code><style id=\"wpforms-css-vars-44\">\n\t\t\t\t#wpforms-44 {\n\t\t\t\t--wpforms-field-size-input-height: 43px;\n--wpforms-field-size-input-spacing: 15px;\n--wpforms-field-size-font-size: 16px;\n--wpforms-field-size-line-height: 19px;\n--wpforms-field-size-padding-h: 14px;\n--wpforms-field-size-checkbox-size: 16px;\n--wpforms-field-size-sublabel-spacing: 5px;\n--wpforms-field-size-icon-size: 1;\n--wpforms-label-size-font-size: 16px;\n--wpforms-label-size-line-height: 19px;\n--wpforms-label-size-sublabel-font-size: 14px;\n--wpforms-label-size-sublabel-line-height: 17px;\n--wpforms-button-size-font-size: 17px;\n--wpforms-button-size-height: 41px;\n--wpforms-button-size-padding-h: 15px;\n--wpforms-button-size-margin-top: 10px;\n--wpforms-container-shadow-size-box-shadow: none;\n\t\t\t}\n\t\t\t<\/style><div class=\"wpforms-container wpforms-container-full wpforms-paypal-commerce wpforms-render-modern\" id=\"wpforms-44\"><form id=\"wpforms-form-44\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"44\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/index.php\/wp-json\/wp\/v2\/pages\/47\" data-token=\"f436251ed89244ea4ac8ab7b974aa6ec\" data-token-time=\"1784100250\"><noscript class=\"wpforms-error-noscript\">Veuillez activer JavaScript dans votre navigateur pour remplir ce formulaire.<\/noscript><div id=\"wpforms-error-noscript\" style=\"display: none;\">Veuillez activer JavaScript dans votre navigateur pour remplir ce formulaire.<\/div><div class=\"wpforms-page-indicator progress\" data-indicator=\"progress\" data-indicator-color=\"#3a54b3\" data-scroll=\"1\" role=\"progressbar\" aria-valuenow=\"1\" aria-valuemin=\"1\" aria-valuemax=\"22\" tabindex=\"-1\"><span class=\"wpforms-page-indicator-page-title\" ><\/span><span class=\"wpforms-page-indicator-page-title-sep\" style=\"display:none;\"> - <\/span><span class=\"wpforms-page-indicator-steps\">Step <span class=\"wpforms-page-indicator-steps-current\">1<\/span> of 22<\/span><div class=\"wpforms-page-indicator-page-progress-wrap\"><div class=\"wpforms-page-indicator-page-progress\" style=\"width:4.5454545454545%;background-color:#3a54b3\"><\/div><\/div><\/div><div class=\"wpforms-field-container\"><div class=\"wpforms-page wpforms-page-1 \" data-page=\"1\"><div id=\"wpforms-44-field_4-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"4\"><\/div><div id=\"wpforms-44-field_13-container\" class=\"wpforms-field wpforms-field-content\" data-field-id=\"13\"><div id=\"wpforms-44-field_13\" class=\"wpforms-field-medium wpforms-field-row\" aria-errormessage=\"wpforms-44-field_13-error\"><h4 class=\"jfWelcome-header form-header\"><span style=\"color:#0000ff\">Bienvenue sur votre auto-diagnostic<\/span><\/h4>\n<div class=\"jfWelcome-description form-subHeader\"><span style=\"color:#3366ff\">Lors de votre auto-diagnostic, votre cas est imm\u00e9diatement transmis \u00e0 nos m\u00e9decins partenaires pour une v\u00e9rification en direct, permettant ainsi d'obtenir votre arr\u00eat maladie rapidement.<\/span><\/div>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><div id=\"wpforms-44-field_3-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"3\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"1\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Commencer<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-2  \" data-page=\"2\" style=\"display:none;\"><div id=\"wpforms-44-field_14-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-modern\" data-field-id=\"14\"><label class=\"wpforms-field-label\" for=\"wpforms-44-field_14\">Choisissez la maladie pr\u00e9sum\u00e9e: <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><select id=\"wpforms-44-field_14\" class=\"wpforms-field-large wpforms-field-required choicesjs-select\" data-size-class=\"wpforms-field-row wpforms-field-large\" data-search-enabled=\"1\" name=\"wpforms[fields][14]\" required=\"required\"><option value=\"\" class=\"placeholder\" disabled  selected='selected'><\/option><option value=\"Veuillez s\u00e9lectionner\"  class=\"choice-1 depth-1\"  >Veuillez s\u00e9lectionner<\/option><option value=\"Gastro-ent\u00e9rite\"  class=\"choice-2 depth-1\"  >Gastro-ent\u00e9rite<\/option><option value=\"Sympt\u00f4me Corona\"  class=\"choice-3 depth-1\"  >Sympt\u00f4me Corona<\/option><option value=\"Stress\"  class=\"choice-7 depth-1\"  >Stress<\/option><option value=\"Migraine\"  class=\"choice-6 depth-1\"  >Migraine<\/option><option value=\"Mal de dos\"  class=\"choice-5 depth-1\"  >Mal de dos<\/option><option value=\"Douleurs menstruelles\"  class=\"choice-4 depth-1\"  >Douleurs menstruelles<\/option><option value=\"Cystite\"  class=\"choice-8 depth-1\"  >Cystite<\/option><option value=\"Blessures\"  class=\"choice-9 depth-1\"  >Blessures<\/option><option value=\"Douleurs abdominales \/ pelviennes\"  class=\"choice-10 depth-1\"  >Douleurs abdominales \/ pelviennes<\/option><option value=\"Hypertension\"  class=\"choice-11 depth-1\"  >Hypertension<\/option><option value=\"Allergie\"  class=\"choice-12 depth-1\"  >Allergie<\/option><option value=\"Le corps n\u2019est pas libre de ses mouvements\"  class=\"choice-13 depth-1\"  >Le corps n\u2019est pas libre de ses mouvements<\/option><option value=\"Probl\u00e8mes dentaires\"  class=\"choice-15 depth-1\"  >Probl\u00e8mes dentaires<\/option><option value=\"Maux de t\u00eate\"  class=\"choice-14 depth-1\"  >Maux de t\u00eate<\/option><option value=\"Naus\u00e9es\/ Vomissements\"  class=\"choice-16 depth-1\"  >Naus\u00e9es\/ Vomissements<\/option><option value=\"Gastrite\"  class=\"choice-17 depth-1\"  >Gastrite<\/option><option value=\"Probl\u00e8mes articulaires\"  class=\"choice-18 depth-1\"  >Probl\u00e8mes articulaires<\/option><option value=\"\u00c9v\u00e8nement : Deuil, crise etc.\"  class=\"choice-19 depth-1\"  >\u00c9v\u00e8nement : Deuil, crise etc.<\/option><option value=\"Syndrome d\u2019\u00e9puisement\"  class=\"choice-20 depth-1\"  >Syndrome d\u2019\u00e9puisement<\/option><\/select><div id=\"wpforms-44-field_14-description\" class=\"wpforms-field-description\">Une seule possibilit\u00e9<\/div><\/div><div id=\"wpforms-44-field_8-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"8\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"2\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-3  \" data-page=\"3\" style=\"display:none;\"><div id=\"wpforms-44-field_15-container\" class=\"wpforms-field wpforms-field-layout\" data-field-id=\"15\"><div class=\"wpforms-field-layout-columns wpforms-field-layout-preset-100\"><div class=\"wpforms-layout-column wpforms-layout-column-100\" ><div id=\"wpforms-44-field_16-container\" class=\"wpforms-field wpforms-field-checkbox wpforms-list-2-columns\" data-field-id=\"16\"><fieldset><legend class=\"wpforms-field-label\">Avez-vous d\u00e9j\u00e0 \u00e9t\u00e9 diagnostiqu\u00e9 pour ce sympt\u00f4me par un m\u00e9decin ? <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><ul id=\"wpforms-44-field_16\" class=\"wpforms-field-required\" data-choice-limit=\"1\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_16_1\" data-rule-check-limit=\"true\" name=\"wpforms[fields][16][]\" value=\"Oui\" aria-errormessage=\"wpforms-44-field_16_1-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_16_1\">Oui<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_16_2\" data-rule-check-limit=\"true\" name=\"wpforms[fields][16][]\" value=\"Non\" aria-errormessage=\"wpforms-44-field_16_2-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_16_2\">Non<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_16_3\" data-rule-check-limit=\"true\" name=\"wpforms[fields][16][]\" value=\"Peut-etre\" aria-errormessage=\"wpforms-44-field_16_3-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_16_3\">Peut-etre<\/label><\/li><\/ul><\/fieldset><\/div><\/div><\/div><\/div><div id=\"wpforms-44-field_6-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"6\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"3\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-4  \" data-page=\"4\" style=\"display:none;\"><div id=\"wpforms-44-field_17-container\" class=\"wpforms-field wpforms-field-checkbox wpforms-list-3-columns\" data-field-id=\"17\"><fieldset><legend class=\"wpforms-field-label\">\ud83e\udd15 Choisissez vos sympt\u00f4mes : <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><ul id=\"wpforms-44-field_17\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_17_1\" name=\"wpforms[fields][17][]\" value=\"Fi\u00e8vre\" aria-errormessage=\"wpforms-44-field_17_1-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_17_1\">Fi\u00e8vre<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_17_2\" name=\"wpforms[fields][17][]\" value=\"Naus\u00e9es\" aria-errormessage=\"wpforms-44-field_17_2-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_17_2\">Naus\u00e9es<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_17_3\" name=\"wpforms[fields][17][]\" value=\"Diarrh\u00e9e\" aria-errormessage=\"wpforms-44-field_17_3-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_17_3\">Diarrh\u00e9e<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_17_4\" name=\"wpforms[fields][17][]\" value=\"Toux sans mucus\" aria-errormessage=\"wpforms-44-field_17_4-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_17_4\">Toux sans mucus<\/label><\/li><li class=\"choice-5 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_17_5\" name=\"wpforms[fields][17][]\" value=\"Toux avec mucosit\u00e9s\" aria-errormessage=\"wpforms-44-field_17_5-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_17_5\">Toux avec mucosit\u00e9s<\/label><\/li><li class=\"choice-6 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_17_6\" name=\"wpforms[fields][17][]\" value=\"Malaise\" aria-errormessage=\"wpforms-44-field_17_6-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_17_6\">Malaise<\/label><\/li><li class=\"choice-7 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_17_7\" name=\"wpforms[fields][17][]\" value=\"Fatigue\" aria-errormessage=\"wpforms-44-field_17_7-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_17_7\">Fatigue<\/label><\/li><li class=\"choice-9 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_17_9\" name=\"wpforms[fields][17][]\" value=\"Hypertension art\u00e9rielle\" aria-errormessage=\"wpforms-44-field_17_9-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_17_9\">Hypertension art\u00e9rielle<\/label><\/li><li class=\"choice-8 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_17_8\" name=\"wpforms[fields][17][]\" value=\"Le corps n&#039;est pas libre de ses mouvements\" aria-errormessage=\"wpforms-44-field_17_8-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_17_8\">Le corps n'est pas libre de ses mouvements<\/label><\/li><li class=\"choice-10 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_17_10\" name=\"wpforms[fields][17][]\" value=\"\u00c9v\u00e9nement stressant de la vie\" aria-errormessage=\"wpforms-44-field_17_10-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_17_10\">\u00c9v\u00e9nement stressant de la vie<\/label><\/li><li class=\"choice-11 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_17_11\" name=\"wpforms[fields][17][]\" value=\"Troubles du sommeil\" aria-errormessage=\"wpforms-44-field_17_11-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_17_11\">Troubles du sommeil<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-44-field_7-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"7\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"4\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-5  \" data-page=\"5\" style=\"display:none;\"><div id=\"wpforms-44-field_24-container\" class=\"wpforms-field wpforms-field-checkbox wpforms-list-3-columns\" data-field-id=\"24\"><fieldset><legend class=\"wpforms-field-label\">douleurs situ\u00e9es dans la :  <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><ul id=\"wpforms-44-field_24\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_24_1\" name=\"wpforms[fields][24][]\" value=\"T\u00eate\" aria-errormessage=\"wpforms-44-field_24_1-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_24_1\">T\u00eate<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_24_2\" name=\"wpforms[fields][24][]\" value=\"Ventre\" aria-errormessage=\"wpforms-44-field_24_2-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_24_2\">Ventre<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_24_3\" name=\"wpforms[fields][24][]\" value=\"Dent\" aria-errormessage=\"wpforms-44-field_24_3-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_24_3\">Dent<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_24_4\" name=\"wpforms[fields][24][]\" value=\"Dos\" aria-errormessage=\"wpforms-44-field_24_4-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_24_4\">Dos<\/label><\/li><li class=\"choice-7 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_24_7\" name=\"wpforms[fields][24][]\" value=\"Cou\" aria-errormessage=\"wpforms-44-field_24_7-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_24_7\">Cou<\/label><\/li><li class=\"choice-6 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_24_6\" name=\"wpforms[fields][24][]\" value=\"Membres\" aria-errormessage=\"wpforms-44-field_24_6-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_24_6\">Membres<\/label><\/li><li class=\"choice-5 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_24_5\" name=\"wpforms[fields][24][]\" value=\"Oreille\" aria-errormessage=\"wpforms-44-field_24_5-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_24_5\">Oreille<\/label><\/li><li class=\"choice-8 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_24_8\" name=\"wpforms[fields][24][]\" value=\"Organe sexuel\" aria-errormessage=\"wpforms-44-field_24_8-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_24_8\">Organe sexuel<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-44-field_23-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"23\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"5\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-6  \" data-page=\"6\" style=\"display:none;\"><div id=\"wpforms-44-field_26-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"26\"><label class=\"wpforms-field-label\" for=\"wpforms-44-field_26\">\ud83d\udcdd D\u00e9crire tous les autres sympt\u00f4mes :<\/label><textarea id=\"wpforms-44-field_26\" class=\"wpforms-field-medium\" name=\"wpforms[fields][26]\" aria-errormessage=\"wpforms-44-field_26-error\" ><\/textarea><\/div><div id=\"wpforms-44-field_25-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"25\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"6\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-7  \" data-page=\"7\" style=\"display:none;\"><div id=\"wpforms-44-field_27-container\" class=\"wpforms-field wpforms-field-checkbox wpforms-list-3-columns\" data-field-id=\"27\"><fieldset><legend class=\"wpforms-field-label\">\u26a1 Est-ce que les sympt\u00f4mes sont apparues soudainement ? <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><ul id=\"wpforms-44-field_27\" class=\"wpforms-field-required\" data-choice-limit=\"1\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_27_1\" data-rule-check-limit=\"true\" name=\"wpforms[fields][27][]\" value=\"Oui\" aria-errormessage=\"wpforms-44-field_27_1-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_27_1\">Oui<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_27_2\" data-rule-check-limit=\"true\" name=\"wpforms[fields][27][]\" value=\"Non\" aria-errormessage=\"wpforms-44-field_27_2-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_27_2\">Non<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_27_3\" data-rule-check-limit=\"true\" name=\"wpforms[fields][27][]\" value=\"Peut-\u00eatre\" aria-errormessage=\"wpforms-44-field_27_3-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_27_3\">Peut-\u00eatre<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-44-field_28-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"28\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"7\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-8  \" data-page=\"8\" style=\"display:none;\"><div id=\"wpforms-44-field_30-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"30\"><label class=\"wpforms-field-label\" for=\"wpforms-44-field_30\">\ud83d\udc8a Si vous prenez des m\u00e9dicaments : Quels sont les m\u00e9dicaments pris r\u00e9guli\u00e8rement ?<\/label><textarea id=\"wpforms-44-field_30\" class=\"wpforms-field-medium\" name=\"wpforms[fields][30]\" aria-errormessage=\"wpforms-44-field_30-error\" ><\/textarea><\/div><div id=\"wpforms-44-field_29-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"29\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"8\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-9  \" data-page=\"9\" style=\"display:none;\"><div id=\"wpforms-44-field_33-container\" class=\"wpforms-field wpforms-field-content\" data-field-id=\"33\"><div id=\"wpforms-44-field_33\" class=\"wpforms-field-medium wpforms-field-row\" aria-errormessage=\"wpforms-44-field_33-error\"><p>\u26a0\ufe0f Pr\u00e9sentez-vous l'un de ces facteurs de risque ?<\/p>\n<ul>\n<li><span style=\"color:#3366ff\">Vous avez des difficult\u00e9s respiratoires, des vomissements ou de la diarrh\u00e9e<\/span><\/li>\n<li><span style=\"color:#3366ff\">Bruits ou obstructions lors de la respiration<\/span><\/li>\n<li><span style=\"color:#3366ff\">Enceinte, immunod\u00e9ficience<\/span><\/li>\n<li><span style=\"color:#3366ff\">Douleur intense, en particulier dans l'oreille, le visage ou les membres<\/span><\/li>\n<li><span style=\"color:#3366ff\">Douleur au larynx, \u00e0 la poitrine ou \u00e0 l'abdomen<\/span><\/li>\n<li><span style=\"color:#3366ff\">Maladie cardiaque, respiratoire ou intestinale chronique<\/span><\/li>\n<li><span style=\"color:#3366ff\">Voyage tropical au cours des deux derniers mois<\/span><\/li>\n<li><span style=\"color:#3366ff\">Sentiment de maladie grave ou difficult\u00e9 \u00e0 avaler<\/span><\/li>\n<li><span style=\"color:#3366ff\">Paralysie, troubles de la conscience, saignements, \u00e9ruptions cutan\u00e9es<\/span><\/li>\n<\/ul>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><div id=\"wpforms-44-field_31-container\" class=\"wpforms-field wpforms-field-checkbox wpforms-conditional-trigger\" data-field-id=\"31\"><fieldset><legend class=\"wpforms-field-label wpforms-label-hide\" aria-hidden=\"false\">\u26a0\ufe0f Pr\u00e9sentez-vous l&#039;un de ces facteurs de risque ? <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><ul id=\"wpforms-44-field_31\" class=\"wpforms-field-required\" data-choice-limit=\"1\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_31_1\" data-rule-check-limit=\"true\" name=\"wpforms[fields][31][]\" value=\"Oui\" aria-errormessage=\"wpforms-44-field_31_1-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_31_1\">Oui<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_31_2\" data-rule-check-limit=\"true\" name=\"wpforms[fields][31][]\" value=\"Non\" aria-errormessage=\"wpforms-44-field_31_2-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_31_2\">Non<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-44-field_34-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"34\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"9\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-10  \" data-page=\"10\" style=\"display:none;\"><div id=\"wpforms-44-field_93-container\" class=\"wpforms-field wpforms-field-content wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"93\" style=\"display:none;\"><div id=\"wpforms-44-field_93\" class=\"wpforms-field-medium wpforms-field-row\" aria-errormessage=\"wpforms-44-field_93-error\"><h4>Votre cas ne peux pas \u00eatre traiter en ligne sans consultation d'un m\u00e9decin !<\/h4>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><div id=\"wpforms-44-field_90-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"90\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-prev wpforms-disabled\"\n\t\t\t\t\tdata-action=\"prev\" data-page=\"10\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Pr\u00e9c\u00e9dent<\/button><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"10\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-11  \" data-page=\"11\" style=\"display:none;\"><div id=\"wpforms-44-field_35-container\" class=\"wpforms-field wpforms-field-checkbox wpforms-list-2-columns\" data-field-id=\"35\"><fieldset><legend class=\"wpforms-field-label\">\ud83e\udd14 Votre employeur est-il insatisfait de votre travail, m\u00e9fiant ou a d\u00e9j\u00e0 contest\u00e9 des attestations ?  <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><ul id=\"wpforms-44-field_35\" class=\"wpforms-field-required\" data-choice-limit=\"1\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_35_1\" data-rule-check-limit=\"true\" name=\"wpforms[fields][35][]\" value=\"Oui\" aria-errormessage=\"wpforms-44-field_35_1-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_35_1\">Oui<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_35_2\" data-rule-check-limit=\"true\" name=\"wpforms[fields][35][]\" value=\"Non\" aria-errormessage=\"wpforms-44-field_35_2-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_35_2\">Non<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-44-field_39-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"39\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"11\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-12  \" data-page=\"12\" style=\"display:none;\"><div id=\"wpforms-44-field_37-container\" class=\"wpforms-field wpforms-field-checkbox wpforms-list-2-columns\" data-field-id=\"37\"><fieldset><legend class=\"wpforms-field-label\">\ud83d\udcdd Avez-vous besoin d&#039;un nouvel arr\u00eat maladie ou d&#039;une prolongation ? <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><ul id=\"wpforms-44-field_37\" class=\"wpforms-field-required\" data-choice-limit=\"1\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_37_1\" data-rule-check-limit=\"true\" name=\"wpforms[fields][37][]\" value=\"Nouvel Arr\u00eat maladie\" aria-errormessage=\"wpforms-44-field_37_1-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_37_1\">Nouvel Arr\u00eat maladie<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_37_2\" data-rule-check-limit=\"true\" name=\"wpforms[fields][37][]\" value=\"Suivi\" aria-errormessage=\"wpforms-44-field_37_2-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_37_2\">Suivi<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-44-field_38-container\" class=\"wpforms-field wpforms-field-content\" data-field-id=\"38\"><div id=\"wpforms-44-field_38\" class=\"wpforms-field-medium wpforms-field-row\" aria-errormessage=\"wpforms-44-field_38-error\"><p><span style=\"color:#3366ff\">Choisissez le suivi de l'arr\u00eat maladie uniquement si vous avez d\u00e9j\u00e0 eu un arr\u00eat maladie pour les m\u00eames sympt\u00f4mes et pour un maximum de 7 jours<\/span><\/p>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><div id=\"wpforms-44-field_40-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"40\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"12\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-13  \" data-page=\"13\" style=\"display:none;\"><div id=\"wpforms-44-field_41-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"41\"><label class=\"wpforms-field-label\" for=\"wpforms-44-field_41\">\ud83d\udc68\u200d\ud83d\udd27 Quelle est votre profession actuelle ?  <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><textarea id=\"wpforms-44-field_41\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][41]\" aria-errormessage=\"wpforms-44-field_41-error\" required><\/textarea><\/div><div id=\"wpforms-44-field_42-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"42\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"13\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-14  \" data-page=\"14\" style=\"display:none;\"><div id=\"wpforms-44-field_46-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-id=\"46\"><fieldset><legend class=\"wpforms-field-label\">\ud83d\udcaa \u00c0 quel point votre travail est-il physiquement exigeant ?  <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><ul id=\"wpforms-44-field_46\" class=\"wpforms-field-required\" data-choice-limit=\"1\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_46_1\" data-rule-check-limit=\"true\" name=\"wpforms[fields][46][]\" value=\"L\u00e9ger\" aria-errormessage=\"wpforms-44-field_46_1-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_46_1\">L\u00e9ger<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_46_2\" data-rule-check-limit=\"true\" name=\"wpforms[fields][46][]\" value=\"Moyen\" aria-errormessage=\"wpforms-44-field_46_2-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_46_2\">Moyen<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_46_3\" data-rule-check-limit=\"true\" name=\"wpforms[fields][46][]\" value=\"Elev\u00e9\" aria-errormessage=\"wpforms-44-field_46_3-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_46_3\">Elev\u00e9<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-44-field_45-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"45\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"14\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-15  \" data-page=\"15\" style=\"display:none;\"><div id=\"wpforms-44-field_47-container\" class=\"wpforms-field wpforms-field-content\" data-field-id=\"47\"><div id=\"wpforms-44-field_47\" class=\"wpforms-field-medium wpforms-field-row\" aria-errormessage=\"wpforms-44-field_47-error\"><h4><img decoding=\"async\" class=\"emoji\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/15.0.3\/svg\/1f4c6.svg\" alt=\"\ud83d\udcc6\" \/>\u00a0Choisissez les dates de d\u00e9but &amp; de fin de votre incapacit\u00e9 de travail :<\/h4>\n<p>C'est-\u00e0-dire qu'en raison de la maladie, vous ne pouvez plus exercer votre m\u00e9tier ou vous pr\u00e9sentez un risque de retarder la gu\u00e9rison.<\/p>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><div id=\"wpforms-44-field_48-container\" class=\"wpforms-field wpforms-field-layout\" data-field-id=\"48\"><div class=\"wpforms-field-layout-rows wpforms-field-large\"><div class=\"wpforms-layout-row\"><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-44-field_49-container\" class=\"wpforms-field wpforms-field-date-time\" data-field-id=\"49\"><label class=\"wpforms-field-label\" for=\"wpforms-44-field_49\">Date de d\u00e9but: <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><div class=\"wpforms-datepicker-wrap\"><input type=\"text\" id=\"wpforms-44-field_49\" class=\"wpforms-field-date-time-date wpforms-datepicker wpforms-field-required wpforms-field-medium\" data-date-format=\"d\/m\/Y\" data-disable-past-dates=\"0\" data-input=\"true\" name=\"wpforms[fields][49][date]\" aria-errormessage=\"wpforms-44-field_49-error\" required><a title=\"Effacer la date\" data-clear role=\"button\" tabindex=\"0\" class=\"wpforms-datepicker-clear\" aria-label=\"Effacer la date\" style=\"display:none;\"><\/a><\/div><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-44-field_50-container\" class=\"wpforms-field wpforms-field-date-time\" data-field-id=\"50\"><label class=\"wpforms-field-label\" for=\"wpforms-44-field_50\">Date de fin: <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><div class=\"wpforms-datepicker-wrap\"><input type=\"text\" id=\"wpforms-44-field_50\" class=\"wpforms-field-date-time-date wpforms-datepicker wpforms-field-required wpforms-field-medium\" data-date-format=\"d\/m\/Y\" data-disable-past-dates=\"0\" data-input=\"true\" name=\"wpforms[fields][50][date]\" aria-errormessage=\"wpforms-44-field_50-error\" required><a title=\"Effacer la date\" data-clear role=\"button\" tabindex=\"0\" class=\"wpforms-datepicker-clear\" aria-label=\"Effacer la date\" style=\"display:none;\"><\/a><\/div><\/div><\/div><\/div><\/div><\/div><div id=\"wpforms-44-field_43-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"43\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"15\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-16  \" data-page=\"16\" style=\"display:none;\"><div id=\"wpforms-44-field_52-container\" class=\"wpforms-field wpforms-field-layout\" data-field-id=\"52\"><div class=\"wpforms-field-layout-rows wpforms-field-large\"><div class=\"wpforms-layout-row\"><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-44-field_53-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"53\"><label class=\"wpforms-field-label\" for=\"wpforms-44-field_53\">Pr\u00e9nom: <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-44-field_53\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][53]\" aria-errormessage=\"wpforms-44-field_53-error\" required><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-44-field_54-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"54\"><label class=\"wpforms-field-label\" for=\"wpforms-44-field_54\">Nom : <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-44-field_54\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][54]\" aria-errormessage=\"wpforms-44-field_54-error\" required><\/div><\/div><\/div><div class=\"wpforms-layout-row\"><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-44-field_55-container\" class=\"wpforms-field wpforms-field-date-time\" data-field-id=\"55\"><label class=\"wpforms-field-label\" for=\"wpforms-44-field_55\">\ud83c\udf82 Date de naissance : <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><div class=\"wpforms-datepicker-wrap\"><input type=\"text\" id=\"wpforms-44-field_55\" class=\"wpforms-field-date-time-date wpforms-datepicker wpforms-field-required wpforms-field-medium\" data-date-format=\"d\/m\/Y\" data-disable-past-dates=\"0\" data-input=\"true\" name=\"wpforms[fields][55][date]\" aria-errormessage=\"wpforms-44-field_55-error\" required><a title=\"Effacer la date\" data-clear role=\"button\" tabindex=\"0\" class=\"wpforms-datepicker-clear\" aria-label=\"Effacer la date\" style=\"display:none;\"><\/a><\/div><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-44-field_56-container\" class=\"wpforms-field wpforms-field-phone\" data-field-id=\"56\"><label class=\"wpforms-field-label\" for=\"wpforms-44-field_56\">T\u00e9l\u00e9phone: <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"tel\" id=\"wpforms-44-field_56\" class=\"wpforms-field-medium wpforms-field-required\" data-rule-int-phone-field=\"true\" name=\"wpforms[fields][56]\" aria-label=\"T\u00e9l\u00e9phone:\" aria-errormessage=\"wpforms-44-field_56-error\" required><\/div><\/div><\/div><div class=\"wpforms-layout-row\"><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-44-field_78-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"78\"><label class=\"wpforms-field-label\" for=\"wpforms-44-field_78\">E-mail <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-44-field_78\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][78]\" spellcheck=\"false\" aria-errormessage=\"wpforms-44-field_78-error\" required><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-50\"><\/div><\/div><\/div><\/div><div id=\"wpforms-44-field_44-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"44\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"16\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-17  \" data-page=\"17\" style=\"display:none;\"><div id=\"wpforms-44-field_51-container\" class=\"wpforms-field wpforms-field-layout\" data-field-id=\"51\"><div class=\"wpforms-field-layout-rows wpforms-field-large\"><div class=\"wpforms-layout-row\"><div class=\"wpforms-layout-column wpforms-layout-column-100\"><div id=\"wpforms-44-field_61-container\" class=\"wpforms-field wpforms-field-address\" data-field-id=\"61\"><fieldset><legend class=\"wpforms-field-label\">Adresse: <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><div class=\"wpforms-field-row wpforms-field-large\"><div ><input type=\"text\" id=\"wpforms-44-field_61\" class=\"wpforms-field-address-address1 wpforms-field-required\" name=\"wpforms[fields][61][address1]\" aria-errormessage=\"wpforms-44-field_61-error\" required><label for=\"wpforms-44-field_61\" class=\"wpforms-field-sublabel after\">Adresse ligne\u00a01<\/label><\/div><\/div><div class=\"wpforms-field-row wpforms-field-large\"><div class=\"wpforms-field-row-block wpforms-one-half wpforms-first\"><input type=\"text\" id=\"wpforms-44-field_61-city\" class=\"wpforms-field-address-city wpforms-field-required\" name=\"wpforms[fields][61][city]\" aria-errormessage=\"wpforms-44-field_61-city-error\" required><label for=\"wpforms-44-field_61-city\" class=\"wpforms-field-sublabel after\">Ville<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-44-field_61-state\" class=\"wpforms-field-address-state wpforms-field-required\" name=\"wpforms[fields][61][state]\" aria-errormessage=\"wpforms-44-field_61-state-error\" required><label for=\"wpforms-44-field_61-state\" class=\"wpforms-field-sublabel after\">\u00c9tat \/ Province \/ R\u00e9gion<\/label><\/div><\/div><div class=\"wpforms-field-row wpforms-field-large\"><div class=\"wpforms-field-row-block wpforms-one-half wpforms-first\"><input type=\"text\" id=\"wpforms-44-field_61-postal\" class=\"wpforms-field-address-postal wpforms-field-required\" name=\"wpforms[fields][61][postal]\" aria-errormessage=\"wpforms-44-field_61-postal-error\" required><label for=\"wpforms-44-field_61-postal\" class=\"wpforms-field-sublabel after\">Code postal<\/label><\/div><\/div><\/fieldset><\/div><\/div><\/div><div class=\"wpforms-layout-row\"><div class=\"wpforms-layout-column wpforms-layout-column-100\"><div id=\"wpforms-44-field_82-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"82\"><label class=\"wpforms-field-label\" for=\"wpforms-44-field_82\">Pays <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-44-field_82\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][82]\" placeholder=\"France\" aria-errormessage=\"wpforms-44-field_82-error\" required><\/div><\/div><\/div><\/div><\/div><div id=\"wpforms-44-field_36-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"36\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"17\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-18  \" data-page=\"18\" style=\"display:none;\"><div id=\"wpforms-44-field_64-container\" class=\"wpforms-field wpforms-field-layout\" data-field-id=\"64\"><div class=\"wpforms-field-layout-rows wpforms-field-large\"><div class=\"wpforms-layout-row\"><div class=\"wpforms-layout-column wpforms-layout-column-100\"><div id=\"wpforms-44-field_75-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"75\"><label class=\"wpforms-field-label\" for=\"wpforms-44-field_75\">Localisation du m\u00e9decin: <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-44-field_75\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][75]\" aria-errormessage=\"wpforms-44-field_75-error\" required><\/div><\/div><\/div><\/div><\/div><div id=\"wpforms-44-field_62-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"62\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"18\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-19  \" data-page=\"19\" style=\"display:none;\"><div id=\"wpforms-44-field_68-container\" class=\"wpforms-field wpforms-field-checkbox wpforms-list-inline\" data-field-id=\"68\"><fieldset><legend class=\"wpforms-field-label\">Cochez la case appropri\u00e9e: <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><ul id=\"wpforms-44-field_68\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_68_1\" name=\"wpforms[fields][68][]\" value=\"Employ\u00e9\" aria-errormessage=\"wpforms-44-field_68_1-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_68_1\">Employ\u00e9<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_68_2\" name=\"wpforms[fields][68][]\" value=\"Ind\u00e9pendant\" aria-errormessage=\"wpforms-44-field_68_2-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_68_2\">Ind\u00e9pendant<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_68_3\" name=\"wpforms[fields][68][]\" value=\"Fonctionnaire\" aria-errormessage=\"wpforms-44-field_68_3-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_68_3\">Fonctionnaire<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_68_4\" name=\"wpforms[fields][68][]\" value=\"Activit\u00e9 non salari\u00e9 agricole\" aria-errormessage=\"wpforms-44-field_68_4-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_68_4\">Activit\u00e9 non salari\u00e9 agricole<\/label><\/li><li class=\"choice-5 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_68_5\" name=\"wpforms[fields][68][]\" value=\"\u00c9tudiant\" aria-errormessage=\"wpforms-44-field_68_5-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_68_5\">\u00c9tudiant<\/label><\/li><li class=\"choice-7 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_68_7\" name=\"wpforms[fields][68][]\" value=\"Sans emploi\" aria-errormessage=\"wpforms-44-field_68_7-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_68_7\">Sans emploi<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-44-field_67-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"67\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"19\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-20  \" data-page=\"20\" style=\"display:none;\"><div id=\"wpforms-44-field_69-container\" class=\"wpforms-field wpforms-field-layout\" data-field-id=\"69\"><div class=\"wpforms-field-layout-rows wpforms-field-large\"><div class=\"wpforms-layout-row\"><div class=\"wpforms-layout-column wpforms-layout-column-100\"><div id=\"wpforms-44-field_70-container\" class=\"wpforms-field wpforms-field-number\" data-field-id=\"70\"><label class=\"wpforms-field-label\" for=\"wpforms-44-field_70\">Num\u00e9ro de s\u00e9curit\u00e9 sociale : <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"number\" id=\"wpforms-44-field_70\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][70]\" step=\"any\" aria-errormessage=\"wpforms-44-field_70-error\" required><\/div><\/div><\/div><\/div><\/div><div id=\"wpforms-44-field_66-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"66\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"20\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-21  \" data-page=\"21\" style=\"display:none;\"><div id=\"wpforms-44-field_74-container\" class=\"wpforms-field wpforms-field-content\" data-field-id=\"74\"><div id=\"wpforms-44-field_74\" class=\"wpforms-field-large wpforms-field-row\" aria-errormessage=\"wpforms-44-field_74-error\"><h4><span class=\"jsQuestionLabelContainer jfQuestionLabelContainer\"><strong>Paiement s\u00e9curis\u00e9 de votre arr\u00eat maladie<\/strong><\/span><span class=\"jfRequiredStar\">*<\/span><\/h4>\n<h6><span style=\"font-family:monospace;font-size:16px\">Votre auto-diagnostic est d\u00e9j\u00e0 transmis \u00e0 l'un de nos m\u00e9decins partenaires<\/span><span style=\"font-family:monospace;font-size:16px\">,<\/span><\/h6>\n<p>vous recevrez votre arr\u00eat maladie tr\u00e8s rapidement<\/p>\n<div class=\"paymentCard-footer-wrapper\">\n<div class=\"paymentCard-productListWrapper\">\n<div class=\"paymentCard-footer\">\n<div class=\"paymentCard-footerRight new-payment-coupon\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>.<\/p>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><div id=\"wpforms-44-field_122-container\" class=\"wpforms-field wpforms-field-payment-single\" data-field-id=\"122\"><label class=\"wpforms-field-label\">Prix :<\/label><div class=\"wpforms-single-item-price-content\"><div class=\"wpforms-single-item-price wpforms-field-medium wpforms-payment-price\">Prix\u00a0: <span class=\"wpforms-price\">24,00 &euro;<\/span><\/div><\/div><input type=\"hidden\" id=\"wpforms-44-field_122\" class=\"wpforms-field-medium wpforms-payment-price\" name=\"wpforms[fields][122]\" value=\"24,00 &euro;\"><\/div><div id=\"wpforms-44-field_120-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"120\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"21\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-22 last \" data-page=\"22\" style=\"display:none;\"><div id=\"wpforms-44-field_121-container\" class=\"wpforms-field wpforms-field-paypal-commerce\" data-field-id=\"121\"><label class=\"wpforms-field-label\">Paiement <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"hidden\" name=\"wpforms[fields][121][orderID]\" class=\"wpforms-paypal-commerce-order-id\" \/><input type=\"hidden\" name=\"wpforms[fields][121][subscriptionID]\" class=\"wpforms-paypal-commerce-subscription-id\" \/><input type=\"hidden\" name=\"wpforms[fields][121][subscriptionProcessorID]\" class=\"wpforms-paypal-commerce-subscription-processor-id\" \/><input type=\"hidden\" name=\"wpforms[fields][121][source]\" class=\"wpforms-paypal-commerce-source\" \/><input type=\"hidden\" name=\"wpforms[fields][121][fastlane_token]\" class=\"wpforms-paypal-commerce-fastlane-token\" \/><div class=\"wpforms-paypal-commerce-card-fields \"><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-paypal-commerce-supported-cards\"><div class=\"wpforms-paypal-commerce-maestro-icon\"><\/div><div class=\"wpforms-paypal-commerce-mastercard-icon\"><\/div><div class=\"wpforms-paypal-commerce-visa-icon\"><\/div><\/div><\/div><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-paypal-commerce-number\"><div id=\"wpforms-44-field_121-cardnumber\" class=\"wpforms-field-paypal-commerce-cardnumber wpforms-field-required\" aria-errormessage=\"wpforms-44-field_121-cardnumber-error\" data-required=\"required\"><\/div><input type=\"text\" class=\"wpforms-paypal-commerce-credit-card-hidden-input\" name=\"wpforms[paypal-commerce-credit-card-hidden-input-44]\" id=\"wpforms-paypal-commerce-credit-card-hidden-input-44-number\" disabled style=\"display: none;\"><label for=\"wpforms-paypal-commerce-credit-card-hidden-input-44-number\" class=\"wpforms-field-sublabel after\">Num\u00e9ro de carte<\/label><\/div><\/div><div class=\"wpforms-field-row wpforms-field-row-responsive wpforms-field-medium\"><div class=\"wpforms-field-row-block wpforms-one-half wpforms-first wpforms-field-paypal-commerce-date\"><div id=\"wpforms-44-field_121-carddate\" class=\"wpforms-field-paypal-commerce-carddate wpforms-field-required\" aria-errormessage=\"wpforms-44-field_121-carddate-error\" data-required=\"required\"><\/div><input type=\"text\" class=\"wpforms-paypal-commerce-credit-card-hidden-input\" name=\"wpforms[paypal-commerce-credit-card-hidden-input-44]\" id=\"wpforms-paypal-commerce-credit-card-hidden-input-44-date\" disabled style=\"display: none;\"><label for=\"wpforms-paypal-commerce-credit-card-hidden-input-44-date\" class=\"wpforms-field-sublabel after\">Expiration Date<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half wpforms-field-paypal-commerce-code\"><div id=\"wpforms-44-field_121-cardcode\" class=\"wpforms-field-paypal-commerce-cardcode wpforms-field-required\" aria-errormessage=\"wpforms-44-field_121-cardcode-error\" data-required=\"required\"><\/div><input type=\"text\" class=\"wpforms-paypal-commerce-credit-card-hidden-input\" name=\"wpforms[paypal-commerce-credit-card-hidden-input-44]\" id=\"wpforms-paypal-commerce-credit-card-hidden-input-44-code\" disabled style=\"display: none;\"><label for=\"wpforms-paypal-commerce-credit-card-hidden-input-44-code\" class=\"wpforms-field-sublabel after\">Code de s\u00e9curit\u00e9 (CVC)<\/label><\/div><\/div><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-paypal-commerce-name\"><input type=\"text\" id=\"wpforms-44-field_121-cardname\" class=\"wpforms-field-paypal-commerce-cardname wpforms-field-required\" name=\"wpforms[fields][121][cardname]\" aria-errormessage=\"wpforms-44-field_121-cardname-error\" required><label for=\"wpforms-44-field_121-cardname\" class=\"wpforms-field-sublabel after\">Card Holder Name<\/label><\/div><\/div><\/div><\/div><div id=\"wpforms-44-field_5-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"5\"><\/div><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" style=\"display:none;\"><input type=\"hidden\" name=\"wpforms[id]\" value=\"44\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/app.vosol-france.com\/index.php\/wp-json\/wp\/v2\/pages\/47\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-44\" class=\"wpforms-submit\" data-alt-text=\"Sending...\" data-submit-text=\"Terminer\" aria-live=\"assertive\" value=\"wpforms-submit\">Terminer<\/button><img decoding=\"async\" src=\"https:\/\/app.vosol-france.com\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Chargement en cours\"><div class=\"wpforms-paypal-commerce-single-submit-button size-medium\"><img decoding=\"async\" src=\"https:\/\/app.vosol-france.com\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-paypal-commerce-single-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Chargement en cours\"><div class=\"wpforms-paypal-commerce-applepay-button wpforms-hidden\" style=\"--apple-pay-button-border-radius: 23px;\"><\/div><div class=\"wpforms-paypal-commerce-googlepay-button wpforms-hidden\"><\/div><\/div><div class=\"wpforms-paypal-commerce-subscriptions-submit-button size-medium\"><img decoding=\"async\" src=\"https:\/\/app.vosol-france.com\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-paypal-commerce-recurring-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Chargement en cours\"><\/div><\/div><\/form><\/div>  <!-- .wpforms-container --><\/code>\r\n                            <button class=\"copy-btn\" onclick=\"copyCode(this)\">Copier<\/button>\r\n                        <\/div>\r\n                        <p style=\"font-size: 12px; color: #94a3b8; margin-top: 4px;\">\r\n                            <i class=\"fas fa-info-circle\"><\/i>\r\n                            Remplacez <code style=\"background: #1e293b; padding: 2px 8px; border-radius: 4px;\"><style id=\"wpforms-css-vars-44\">\n\t\t\t\t#wpforms-44 {\n\t\t\t\t--wpforms-field-size-input-height: 43px;\n--wpforms-field-size-input-spacing: 15px;\n--wpforms-field-size-font-size: 16px;\n--wpforms-field-size-line-height: 19px;\n--wpforms-field-size-padding-h: 14px;\n--wpforms-field-size-checkbox-size: 16px;\n--wpforms-field-size-sublabel-spacing: 5px;\n--wpforms-field-size-icon-size: 1;\n--wpforms-label-size-font-size: 16px;\n--wpforms-label-size-line-height: 19px;\n--wpforms-label-size-sublabel-font-size: 14px;\n--wpforms-label-size-sublabel-line-height: 17px;\n--wpforms-button-size-font-size: 17px;\n--wpforms-button-size-height: 41px;\n--wpforms-button-size-padding-h: 15px;\n--wpforms-button-size-margin-top: 10px;\n--wpforms-container-shadow-size-box-shadow: none;\n\t\t\t}\n\t\t\t<\/style><div class=\"wpforms-container wpforms-container-full wpforms-paypal-commerce wpforms-render-modern\" id=\"wpforms-44\"><form id=\"wpforms-form-44\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"44\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/index.php\/wp-json\/wp\/v2\/pages\/47\" data-token=\"f436251ed89244ea4ac8ab7b974aa6ec\" data-token-time=\"1784100250\"><noscript class=\"wpforms-error-noscript\">Veuillez activer JavaScript dans votre navigateur pour remplir ce formulaire.<\/noscript><div id=\"wpforms-error-noscript\" style=\"display: none;\">Veuillez activer JavaScript dans votre navigateur pour remplir ce formulaire.<\/div><div class=\"wpforms-page-indicator progress\" data-indicator=\"progress\" data-indicator-color=\"#3a54b3\" data-scroll=\"1\" role=\"progressbar\" aria-valuenow=\"1\" aria-valuemin=\"1\" aria-valuemax=\"22\" tabindex=\"-1\"><span class=\"wpforms-page-indicator-page-title\" ><\/span><span class=\"wpforms-page-indicator-page-title-sep\" style=\"display:none;\"> - <\/span><span class=\"wpforms-page-indicator-steps\">Step <span class=\"wpforms-page-indicator-steps-current\">1<\/span> of 22<\/span><div class=\"wpforms-page-indicator-page-progress-wrap\"><div class=\"wpforms-page-indicator-page-progress\" style=\"width:4.5454545454545%;background-color:#3a54b3\"><\/div><\/div><\/div><div class=\"wpforms-field-container\"><div class=\"wpforms-page wpforms-page-1 \" data-page=\"1\"><div id=\"wpforms-44-field_4-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"4\"><\/div><div id=\"wpforms-44-field_13-container\" class=\"wpforms-field wpforms-field-content\" data-field-id=\"13\"><div id=\"wpforms-44-field_13\" class=\"wpforms-field-medium wpforms-field-row\" aria-errormessage=\"wpforms-44-field_13-error\"><h4 class=\"jfWelcome-header form-header\"><span style=\"color:#0000ff\">Bienvenue sur votre auto-diagnostic<\/span><\/h4>\n<div class=\"jfWelcome-description form-subHeader\"><span style=\"color:#3366ff\">Lors de votre auto-diagnostic, votre cas est imm\u00e9diatement transmis \u00e0 nos m\u00e9decins partenaires pour une v\u00e9rification en direct, permettant ainsi d'obtenir votre arr\u00eat maladie rapidement.<\/span><\/div>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><div id=\"wpforms-44-field_3-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"3\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"1\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Commencer<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-2  \" data-page=\"2\" style=\"display:none;\"><div id=\"wpforms-44-field_14-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-modern\" data-field-id=\"14\"><label class=\"wpforms-field-label\" for=\"wpforms-44-field_14\">Choisissez la maladie pr\u00e9sum\u00e9e: <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><select id=\"wpforms-44-field_14\" class=\"wpforms-field-large wpforms-field-required choicesjs-select\" data-size-class=\"wpforms-field-row wpforms-field-large\" data-search-enabled=\"1\" name=\"wpforms[fields][14]\" required=\"required\"><option value=\"\" class=\"placeholder\" disabled  selected='selected'><\/option><option value=\"Veuillez s\u00e9lectionner\"  class=\"choice-1 depth-1\"  >Veuillez s\u00e9lectionner<\/option><option value=\"Gastro-ent\u00e9rite\"  class=\"choice-2 depth-1\"  >Gastro-ent\u00e9rite<\/option><option value=\"Sympt\u00f4me Corona\"  class=\"choice-3 depth-1\"  >Sympt\u00f4me Corona<\/option><option value=\"Stress\"  class=\"choice-7 depth-1\"  >Stress<\/option><option value=\"Migraine\"  class=\"choice-6 depth-1\"  >Migraine<\/option><option value=\"Mal de dos\"  class=\"choice-5 depth-1\"  >Mal de dos<\/option><option value=\"Douleurs menstruelles\"  class=\"choice-4 depth-1\"  >Douleurs menstruelles<\/option><option value=\"Cystite\"  class=\"choice-8 depth-1\"  >Cystite<\/option><option value=\"Blessures\"  class=\"choice-9 depth-1\"  >Blessures<\/option><option value=\"Douleurs abdominales \/ pelviennes\"  class=\"choice-10 depth-1\"  >Douleurs abdominales \/ pelviennes<\/option><option value=\"Hypertension\"  class=\"choice-11 depth-1\"  >Hypertension<\/option><option value=\"Allergie\"  class=\"choice-12 depth-1\"  >Allergie<\/option><option value=\"Le corps n\u2019est pas libre de ses mouvements\"  class=\"choice-13 depth-1\"  >Le corps n\u2019est pas libre de ses mouvements<\/option><option value=\"Probl\u00e8mes dentaires\"  class=\"choice-15 depth-1\"  >Probl\u00e8mes dentaires<\/option><option value=\"Maux de t\u00eate\"  class=\"choice-14 depth-1\"  >Maux de t\u00eate<\/option><option value=\"Naus\u00e9es\/ Vomissements\"  class=\"choice-16 depth-1\"  >Naus\u00e9es\/ Vomissements<\/option><option value=\"Gastrite\"  class=\"choice-17 depth-1\"  >Gastrite<\/option><option value=\"Probl\u00e8mes articulaires\"  class=\"choice-18 depth-1\"  >Probl\u00e8mes articulaires<\/option><option value=\"\u00c9v\u00e8nement : Deuil, crise etc.\"  class=\"choice-19 depth-1\"  >\u00c9v\u00e8nement : Deuil, crise etc.<\/option><option value=\"Syndrome d\u2019\u00e9puisement\"  class=\"choice-20 depth-1\"  >Syndrome d\u2019\u00e9puisement<\/option><\/select><div id=\"wpforms-44-field_14-description\" class=\"wpforms-field-description\">Une seule possibilit\u00e9<\/div><\/div><div id=\"wpforms-44-field_8-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"8\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"2\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-3  \" data-page=\"3\" style=\"display:none;\"><div id=\"wpforms-44-field_15-container\" class=\"wpforms-field wpforms-field-layout\" data-field-id=\"15\"><div class=\"wpforms-field-layout-columns wpforms-field-layout-preset-100\"><div class=\"wpforms-layout-column wpforms-layout-column-100\" ><div id=\"wpforms-44-field_16-container\" class=\"wpforms-field wpforms-field-checkbox wpforms-list-2-columns\" data-field-id=\"16\"><fieldset><legend class=\"wpforms-field-label\">Avez-vous d\u00e9j\u00e0 \u00e9t\u00e9 diagnostiqu\u00e9 pour ce sympt\u00f4me par un m\u00e9decin ? <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><ul id=\"wpforms-44-field_16\" class=\"wpforms-field-required\" data-choice-limit=\"1\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_16_1\" data-rule-check-limit=\"true\" name=\"wpforms[fields][16][]\" value=\"Oui\" aria-errormessage=\"wpforms-44-field_16_1-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_16_1\">Oui<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_16_2\" data-rule-check-limit=\"true\" name=\"wpforms[fields][16][]\" value=\"Non\" aria-errormessage=\"wpforms-44-field_16_2-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_16_2\">Non<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_16_3\" data-rule-check-limit=\"true\" name=\"wpforms[fields][16][]\" value=\"Peut-etre\" aria-errormessage=\"wpforms-44-field_16_3-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_16_3\">Peut-etre<\/label><\/li><\/ul><\/fieldset><\/div><\/div><\/div><\/div><div id=\"wpforms-44-field_6-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"6\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"3\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-4  \" data-page=\"4\" style=\"display:none;\"><div id=\"wpforms-44-field_17-container\" class=\"wpforms-field wpforms-field-checkbox wpforms-list-3-columns\" data-field-id=\"17\"><fieldset><legend class=\"wpforms-field-label\">\ud83e\udd15 Choisissez vos sympt\u00f4mes : <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><ul id=\"wpforms-44-field_17\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_17_1\" name=\"wpforms[fields][17][]\" value=\"Fi\u00e8vre\" aria-errormessage=\"wpforms-44-field_17_1-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_17_1\">Fi\u00e8vre<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_17_2\" name=\"wpforms[fields][17][]\" value=\"Naus\u00e9es\" aria-errormessage=\"wpforms-44-field_17_2-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_17_2\">Naus\u00e9es<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_17_3\" name=\"wpforms[fields][17][]\" value=\"Diarrh\u00e9e\" aria-errormessage=\"wpforms-44-field_17_3-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_17_3\">Diarrh\u00e9e<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_17_4\" name=\"wpforms[fields][17][]\" value=\"Toux sans mucus\" aria-errormessage=\"wpforms-44-field_17_4-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_17_4\">Toux sans mucus<\/label><\/li><li class=\"choice-5 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_17_5\" name=\"wpforms[fields][17][]\" value=\"Toux avec mucosit\u00e9s\" aria-errormessage=\"wpforms-44-field_17_5-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_17_5\">Toux avec mucosit\u00e9s<\/label><\/li><li class=\"choice-6 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_17_6\" name=\"wpforms[fields][17][]\" value=\"Malaise\" aria-errormessage=\"wpforms-44-field_17_6-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_17_6\">Malaise<\/label><\/li><li class=\"choice-7 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_17_7\" name=\"wpforms[fields][17][]\" value=\"Fatigue\" aria-errormessage=\"wpforms-44-field_17_7-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_17_7\">Fatigue<\/label><\/li><li class=\"choice-9 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_17_9\" name=\"wpforms[fields][17][]\" value=\"Hypertension art\u00e9rielle\" aria-errormessage=\"wpforms-44-field_17_9-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_17_9\">Hypertension art\u00e9rielle<\/label><\/li><li class=\"choice-8 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_17_8\" name=\"wpforms[fields][17][]\" value=\"Le corps n&#039;est pas libre de ses mouvements\" aria-errormessage=\"wpforms-44-field_17_8-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_17_8\">Le corps n'est pas libre de ses mouvements<\/label><\/li><li class=\"choice-10 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_17_10\" name=\"wpforms[fields][17][]\" value=\"\u00c9v\u00e9nement stressant de la vie\" aria-errormessage=\"wpforms-44-field_17_10-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_17_10\">\u00c9v\u00e9nement stressant de la vie<\/label><\/li><li class=\"choice-11 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_17_11\" name=\"wpforms[fields][17][]\" value=\"Troubles du sommeil\" aria-errormessage=\"wpforms-44-field_17_11-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_17_11\">Troubles du sommeil<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-44-field_7-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"7\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"4\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-5  \" data-page=\"5\" style=\"display:none;\"><div id=\"wpforms-44-field_24-container\" class=\"wpforms-field wpforms-field-checkbox wpforms-list-3-columns\" data-field-id=\"24\"><fieldset><legend class=\"wpforms-field-label\">douleurs situ\u00e9es dans la :  <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><ul id=\"wpforms-44-field_24\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_24_1\" name=\"wpforms[fields][24][]\" value=\"T\u00eate\" aria-errormessage=\"wpforms-44-field_24_1-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_24_1\">T\u00eate<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_24_2\" name=\"wpforms[fields][24][]\" value=\"Ventre\" aria-errormessage=\"wpforms-44-field_24_2-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_24_2\">Ventre<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_24_3\" name=\"wpforms[fields][24][]\" value=\"Dent\" aria-errormessage=\"wpforms-44-field_24_3-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_24_3\">Dent<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_24_4\" name=\"wpforms[fields][24][]\" value=\"Dos\" aria-errormessage=\"wpforms-44-field_24_4-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_24_4\">Dos<\/label><\/li><li class=\"choice-7 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_24_7\" name=\"wpforms[fields][24][]\" value=\"Cou\" aria-errormessage=\"wpforms-44-field_24_7-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_24_7\">Cou<\/label><\/li><li class=\"choice-6 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_24_6\" name=\"wpforms[fields][24][]\" value=\"Membres\" aria-errormessage=\"wpforms-44-field_24_6-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_24_6\">Membres<\/label><\/li><li class=\"choice-5 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_24_5\" name=\"wpforms[fields][24][]\" value=\"Oreille\" aria-errormessage=\"wpforms-44-field_24_5-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_24_5\">Oreille<\/label><\/li><li class=\"choice-8 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_24_8\" name=\"wpforms[fields][24][]\" value=\"Organe sexuel\" aria-errormessage=\"wpforms-44-field_24_8-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_24_8\">Organe sexuel<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-44-field_23-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"23\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"5\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-6  \" data-page=\"6\" style=\"display:none;\"><div id=\"wpforms-44-field_26-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"26\"><label class=\"wpforms-field-label\" for=\"wpforms-44-field_26\">\ud83d\udcdd D\u00e9crire tous les autres sympt\u00f4mes :<\/label><textarea id=\"wpforms-44-field_26\" class=\"wpforms-field-medium\" name=\"wpforms[fields][26]\" aria-errormessage=\"wpforms-44-field_26-error\" ><\/textarea><\/div><div id=\"wpforms-44-field_25-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"25\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"6\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-7  \" data-page=\"7\" style=\"display:none;\"><div id=\"wpforms-44-field_27-container\" class=\"wpforms-field wpforms-field-checkbox wpforms-list-3-columns\" data-field-id=\"27\"><fieldset><legend class=\"wpforms-field-label\">\u26a1 Est-ce que les sympt\u00f4mes sont apparues soudainement ? <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><ul id=\"wpforms-44-field_27\" class=\"wpforms-field-required\" data-choice-limit=\"1\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_27_1\" data-rule-check-limit=\"true\" name=\"wpforms[fields][27][]\" value=\"Oui\" aria-errormessage=\"wpforms-44-field_27_1-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_27_1\">Oui<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_27_2\" data-rule-check-limit=\"true\" name=\"wpforms[fields][27][]\" value=\"Non\" aria-errormessage=\"wpforms-44-field_27_2-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_27_2\">Non<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_27_3\" data-rule-check-limit=\"true\" name=\"wpforms[fields][27][]\" value=\"Peut-\u00eatre\" aria-errormessage=\"wpforms-44-field_27_3-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_27_3\">Peut-\u00eatre<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-44-field_28-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"28\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"7\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-8  \" data-page=\"8\" style=\"display:none;\"><div id=\"wpforms-44-field_30-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"30\"><label class=\"wpforms-field-label\" for=\"wpforms-44-field_30\">\ud83d\udc8a Si vous prenez des m\u00e9dicaments : Quels sont les m\u00e9dicaments pris r\u00e9guli\u00e8rement ?<\/label><textarea id=\"wpforms-44-field_30\" class=\"wpforms-field-medium\" name=\"wpforms[fields][30]\" aria-errormessage=\"wpforms-44-field_30-error\" ><\/textarea><\/div><div id=\"wpforms-44-field_29-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"29\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"8\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-9  \" data-page=\"9\" style=\"display:none;\"><div id=\"wpforms-44-field_33-container\" class=\"wpforms-field wpforms-field-content\" data-field-id=\"33\"><div id=\"wpforms-44-field_33\" class=\"wpforms-field-medium wpforms-field-row\" aria-errormessage=\"wpforms-44-field_33-error\"><p>\u26a0\ufe0f Pr\u00e9sentez-vous l'un de ces facteurs de risque ?<\/p>\n<ul>\n<li><span style=\"color:#3366ff\">Vous avez des difficult\u00e9s respiratoires, des vomissements ou de la diarrh\u00e9e<\/span><\/li>\n<li><span style=\"color:#3366ff\">Bruits ou obstructions lors de la respiration<\/span><\/li>\n<li><span style=\"color:#3366ff\">Enceinte, immunod\u00e9ficience<\/span><\/li>\n<li><span style=\"color:#3366ff\">Douleur intense, en particulier dans l'oreille, le visage ou les membres<\/span><\/li>\n<li><span style=\"color:#3366ff\">Douleur au larynx, \u00e0 la poitrine ou \u00e0 l'abdomen<\/span><\/li>\n<li><span style=\"color:#3366ff\">Maladie cardiaque, respiratoire ou intestinale chronique<\/span><\/li>\n<li><span style=\"color:#3366ff\">Voyage tropical au cours des deux derniers mois<\/span><\/li>\n<li><span style=\"color:#3366ff\">Sentiment de maladie grave ou difficult\u00e9 \u00e0 avaler<\/span><\/li>\n<li><span style=\"color:#3366ff\">Paralysie, troubles de la conscience, saignements, \u00e9ruptions cutan\u00e9es<\/span><\/li>\n<\/ul>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><div id=\"wpforms-44-field_31-container\" class=\"wpforms-field wpforms-field-checkbox wpforms-conditional-trigger\" data-field-id=\"31\"><fieldset><legend class=\"wpforms-field-label wpforms-label-hide\" aria-hidden=\"false\">\u26a0\ufe0f Pr\u00e9sentez-vous l&#039;un de ces facteurs de risque ? <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><ul id=\"wpforms-44-field_31\" class=\"wpforms-field-required\" data-choice-limit=\"1\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_31_1\" data-rule-check-limit=\"true\" name=\"wpforms[fields][31][]\" value=\"Oui\" aria-errormessage=\"wpforms-44-field_31_1-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_31_1\">Oui<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_31_2\" data-rule-check-limit=\"true\" name=\"wpforms[fields][31][]\" value=\"Non\" aria-errormessage=\"wpforms-44-field_31_2-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_31_2\">Non<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-44-field_34-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"34\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"9\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-10  \" data-page=\"10\" style=\"display:none;\"><div id=\"wpforms-44-field_93-container\" class=\"wpforms-field wpforms-field-content wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"93\" style=\"display:none;\"><div id=\"wpforms-44-field_93\" class=\"wpforms-field-medium wpforms-field-row\" aria-errormessage=\"wpforms-44-field_93-error\"><h4>Votre cas ne peux pas \u00eatre traiter en ligne sans consultation d'un m\u00e9decin !<\/h4>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><div id=\"wpforms-44-field_90-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"90\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-prev wpforms-disabled\"\n\t\t\t\t\tdata-action=\"prev\" data-page=\"10\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Pr\u00e9c\u00e9dent<\/button><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"10\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-11  \" data-page=\"11\" style=\"display:none;\"><div id=\"wpforms-44-field_35-container\" class=\"wpforms-field wpforms-field-checkbox wpforms-list-2-columns\" data-field-id=\"35\"><fieldset><legend class=\"wpforms-field-label\">\ud83e\udd14 Votre employeur est-il insatisfait de votre travail, m\u00e9fiant ou a d\u00e9j\u00e0 contest\u00e9 des attestations ?  <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><ul id=\"wpforms-44-field_35\" class=\"wpforms-field-required\" data-choice-limit=\"1\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_35_1\" data-rule-check-limit=\"true\" name=\"wpforms[fields][35][]\" value=\"Oui\" aria-errormessage=\"wpforms-44-field_35_1-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_35_1\">Oui<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_35_2\" data-rule-check-limit=\"true\" name=\"wpforms[fields][35][]\" value=\"Non\" aria-errormessage=\"wpforms-44-field_35_2-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_35_2\">Non<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-44-field_39-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"39\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"11\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-12  \" data-page=\"12\" style=\"display:none;\"><div id=\"wpforms-44-field_37-container\" class=\"wpforms-field wpforms-field-checkbox wpforms-list-2-columns\" data-field-id=\"37\"><fieldset><legend class=\"wpforms-field-label\">\ud83d\udcdd Avez-vous besoin d&#039;un nouvel arr\u00eat maladie ou d&#039;une prolongation ? <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><ul id=\"wpforms-44-field_37\" class=\"wpforms-field-required\" data-choice-limit=\"1\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_37_1\" data-rule-check-limit=\"true\" name=\"wpforms[fields][37][]\" value=\"Nouvel Arr\u00eat maladie\" aria-errormessage=\"wpforms-44-field_37_1-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_37_1\">Nouvel Arr\u00eat maladie<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_37_2\" data-rule-check-limit=\"true\" name=\"wpforms[fields][37][]\" value=\"Suivi\" aria-errormessage=\"wpforms-44-field_37_2-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_37_2\">Suivi<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-44-field_38-container\" class=\"wpforms-field wpforms-field-content\" data-field-id=\"38\"><div id=\"wpforms-44-field_38\" class=\"wpforms-field-medium wpforms-field-row\" aria-errormessage=\"wpforms-44-field_38-error\"><p><span style=\"color:#3366ff\">Choisissez le suivi de l'arr\u00eat maladie uniquement si vous avez d\u00e9j\u00e0 eu un arr\u00eat maladie pour les m\u00eames sympt\u00f4mes et pour un maximum de 7 jours<\/span><\/p>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><div id=\"wpforms-44-field_40-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"40\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"12\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-13  \" data-page=\"13\" style=\"display:none;\"><div id=\"wpforms-44-field_41-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"41\"><label class=\"wpforms-field-label\" for=\"wpforms-44-field_41\">\ud83d\udc68\u200d\ud83d\udd27 Quelle est votre profession actuelle ?  <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><textarea id=\"wpforms-44-field_41\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][41]\" aria-errormessage=\"wpforms-44-field_41-error\" required><\/textarea><\/div><div id=\"wpforms-44-field_42-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"42\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"13\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-14  \" data-page=\"14\" style=\"display:none;\"><div id=\"wpforms-44-field_46-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-id=\"46\"><fieldset><legend class=\"wpforms-field-label\">\ud83d\udcaa \u00c0 quel point votre travail est-il physiquement exigeant ?  <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><ul id=\"wpforms-44-field_46\" class=\"wpforms-field-required\" data-choice-limit=\"1\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_46_1\" data-rule-check-limit=\"true\" name=\"wpforms[fields][46][]\" value=\"L\u00e9ger\" aria-errormessage=\"wpforms-44-field_46_1-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_46_1\">L\u00e9ger<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_46_2\" data-rule-check-limit=\"true\" name=\"wpforms[fields][46][]\" value=\"Moyen\" aria-errormessage=\"wpforms-44-field_46_2-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_46_2\">Moyen<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_46_3\" data-rule-check-limit=\"true\" name=\"wpforms[fields][46][]\" value=\"Elev\u00e9\" aria-errormessage=\"wpforms-44-field_46_3-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_46_3\">Elev\u00e9<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-44-field_45-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"45\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"14\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-15  \" data-page=\"15\" style=\"display:none;\"><div id=\"wpforms-44-field_47-container\" class=\"wpforms-field wpforms-field-content\" data-field-id=\"47\"><div id=\"wpforms-44-field_47\" class=\"wpforms-field-medium wpforms-field-row\" aria-errormessage=\"wpforms-44-field_47-error\"><h4><img decoding=\"async\" class=\"emoji\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/15.0.3\/svg\/1f4c6.svg\" alt=\"\ud83d\udcc6\" \/>\u00a0Choisissez les dates de d\u00e9but &amp; de fin de votre incapacit\u00e9 de travail :<\/h4>\n<p>C'est-\u00e0-dire qu'en raison de la maladie, vous ne pouvez plus exercer votre m\u00e9tier ou vous pr\u00e9sentez un risque de retarder la gu\u00e9rison.<\/p>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><div id=\"wpforms-44-field_48-container\" class=\"wpforms-field wpforms-field-layout\" data-field-id=\"48\"><div class=\"wpforms-field-layout-rows wpforms-field-large\"><div class=\"wpforms-layout-row\"><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-44-field_49-container\" class=\"wpforms-field wpforms-field-date-time\" data-field-id=\"49\"><label class=\"wpforms-field-label\" for=\"wpforms-44-field_49\">Date de d\u00e9but: <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><div class=\"wpforms-datepicker-wrap\"><input type=\"text\" id=\"wpforms-44-field_49\" class=\"wpforms-field-date-time-date wpforms-datepicker wpforms-field-required wpforms-field-medium\" data-date-format=\"d\/m\/Y\" data-disable-past-dates=\"0\" data-input=\"true\" name=\"wpforms[fields][49][date]\" aria-errormessage=\"wpforms-44-field_49-error\" required><a title=\"Effacer la date\" data-clear role=\"button\" tabindex=\"0\" class=\"wpforms-datepicker-clear\" aria-label=\"Effacer la date\" style=\"display:none;\"><\/a><\/div><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-44-field_50-container\" class=\"wpforms-field wpforms-field-date-time\" data-field-id=\"50\"><label class=\"wpforms-field-label\" for=\"wpforms-44-field_50\">Date de fin: <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><div class=\"wpforms-datepicker-wrap\"><input type=\"text\" id=\"wpforms-44-field_50\" class=\"wpforms-field-date-time-date wpforms-datepicker wpforms-field-required wpforms-field-medium\" data-date-format=\"d\/m\/Y\" data-disable-past-dates=\"0\" data-input=\"true\" name=\"wpforms[fields][50][date]\" aria-errormessage=\"wpforms-44-field_50-error\" required><a title=\"Effacer la date\" data-clear role=\"button\" tabindex=\"0\" class=\"wpforms-datepicker-clear\" aria-label=\"Effacer la date\" style=\"display:none;\"><\/a><\/div><\/div><\/div><\/div><\/div><\/div><div id=\"wpforms-44-field_43-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"43\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"15\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-16  \" data-page=\"16\" style=\"display:none;\"><div id=\"wpforms-44-field_52-container\" class=\"wpforms-field wpforms-field-layout\" data-field-id=\"52\"><div class=\"wpforms-field-layout-rows wpforms-field-large\"><div class=\"wpforms-layout-row\"><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-44-field_53-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"53\"><label class=\"wpforms-field-label\" for=\"wpforms-44-field_53\">Pr\u00e9nom: <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-44-field_53\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][53]\" aria-errormessage=\"wpforms-44-field_53-error\" required><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-44-field_54-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"54\"><label class=\"wpforms-field-label\" for=\"wpforms-44-field_54\">Nom : <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-44-field_54\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][54]\" aria-errormessage=\"wpforms-44-field_54-error\" required><\/div><\/div><\/div><div class=\"wpforms-layout-row\"><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-44-field_55-container\" class=\"wpforms-field wpforms-field-date-time\" data-field-id=\"55\"><label class=\"wpforms-field-label\" for=\"wpforms-44-field_55\">\ud83c\udf82 Date de naissance : <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><div class=\"wpforms-datepicker-wrap\"><input type=\"text\" id=\"wpforms-44-field_55\" class=\"wpforms-field-date-time-date wpforms-datepicker wpforms-field-required wpforms-field-medium\" data-date-format=\"d\/m\/Y\" data-disable-past-dates=\"0\" data-input=\"true\" name=\"wpforms[fields][55][date]\" aria-errormessage=\"wpforms-44-field_55-error\" required><a title=\"Effacer la date\" data-clear role=\"button\" tabindex=\"0\" class=\"wpforms-datepicker-clear\" aria-label=\"Effacer la date\" style=\"display:none;\"><\/a><\/div><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-44-field_56-container\" class=\"wpforms-field wpforms-field-phone\" data-field-id=\"56\"><label class=\"wpforms-field-label\" for=\"wpforms-44-field_56\">T\u00e9l\u00e9phone: <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"tel\" id=\"wpforms-44-field_56\" class=\"wpforms-field-medium wpforms-field-required\" data-rule-int-phone-field=\"true\" name=\"wpforms[fields][56]\" aria-label=\"T\u00e9l\u00e9phone:\" aria-errormessage=\"wpforms-44-field_56-error\" required><\/div><\/div><\/div><div class=\"wpforms-layout-row\"><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-44-field_78-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"78\"><label class=\"wpforms-field-label\" for=\"wpforms-44-field_78\">E-mail <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-44-field_78\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][78]\" spellcheck=\"false\" aria-errormessage=\"wpforms-44-field_78-error\" required><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-50\"><\/div><\/div><\/div><\/div><div id=\"wpforms-44-field_44-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"44\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"16\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-17  \" data-page=\"17\" style=\"display:none;\"><div id=\"wpforms-44-field_51-container\" class=\"wpforms-field wpforms-field-layout\" data-field-id=\"51\"><div class=\"wpforms-field-layout-rows wpforms-field-large\"><div class=\"wpforms-layout-row\"><div class=\"wpforms-layout-column wpforms-layout-column-100\"><div id=\"wpforms-44-field_61-container\" class=\"wpforms-field wpforms-field-address\" data-field-id=\"61\"><fieldset><legend class=\"wpforms-field-label\">Adresse: <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><div class=\"wpforms-field-row wpforms-field-large\"><div ><input type=\"text\" id=\"wpforms-44-field_61\" class=\"wpforms-field-address-address1 wpforms-field-required\" name=\"wpforms[fields][61][address1]\" aria-errormessage=\"wpforms-44-field_61-error\" required><label for=\"wpforms-44-field_61\" class=\"wpforms-field-sublabel after\">Adresse ligne\u00a01<\/label><\/div><\/div><div class=\"wpforms-field-row wpforms-field-large\"><div class=\"wpforms-field-row-block wpforms-one-half wpforms-first\"><input type=\"text\" id=\"wpforms-44-field_61-city\" class=\"wpforms-field-address-city wpforms-field-required\" name=\"wpforms[fields][61][city]\" aria-errormessage=\"wpforms-44-field_61-city-error\" required><label for=\"wpforms-44-field_61-city\" class=\"wpforms-field-sublabel after\">Ville<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-44-field_61-state\" class=\"wpforms-field-address-state wpforms-field-required\" name=\"wpforms[fields][61][state]\" aria-errormessage=\"wpforms-44-field_61-state-error\" required><label for=\"wpforms-44-field_61-state\" class=\"wpforms-field-sublabel after\">\u00c9tat \/ Province \/ R\u00e9gion<\/label><\/div><\/div><div class=\"wpforms-field-row wpforms-field-large\"><div class=\"wpforms-field-row-block wpforms-one-half wpforms-first\"><input type=\"text\" id=\"wpforms-44-field_61-postal\" class=\"wpforms-field-address-postal wpforms-field-required\" name=\"wpforms[fields][61][postal]\" aria-errormessage=\"wpforms-44-field_61-postal-error\" required><label for=\"wpforms-44-field_61-postal\" class=\"wpforms-field-sublabel after\">Code postal<\/label><\/div><\/div><\/fieldset><\/div><\/div><\/div><div class=\"wpforms-layout-row\"><div class=\"wpforms-layout-column wpforms-layout-column-100\"><div id=\"wpforms-44-field_82-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"82\"><label class=\"wpforms-field-label\" for=\"wpforms-44-field_82\">Pays <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-44-field_82\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][82]\" placeholder=\"France\" aria-errormessage=\"wpforms-44-field_82-error\" required><\/div><\/div><\/div><\/div><\/div><div id=\"wpforms-44-field_36-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"36\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"17\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-18  \" data-page=\"18\" style=\"display:none;\"><div id=\"wpforms-44-field_64-container\" class=\"wpforms-field wpforms-field-layout\" data-field-id=\"64\"><div class=\"wpforms-field-layout-rows wpforms-field-large\"><div class=\"wpforms-layout-row\"><div class=\"wpforms-layout-column wpforms-layout-column-100\"><div id=\"wpforms-44-field_75-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"75\"><label class=\"wpforms-field-label\" for=\"wpforms-44-field_75\">Localisation du m\u00e9decin: <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-44-field_75\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][75]\" aria-errormessage=\"wpforms-44-field_75-error\" required><\/div><\/div><\/div><\/div><\/div><div id=\"wpforms-44-field_62-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"62\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"18\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-19  \" data-page=\"19\" style=\"display:none;\"><div id=\"wpforms-44-field_68-container\" class=\"wpforms-field wpforms-field-checkbox wpforms-list-inline\" data-field-id=\"68\"><fieldset><legend class=\"wpforms-field-label\">Cochez la case appropri\u00e9e: <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><ul id=\"wpforms-44-field_68\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_68_1\" name=\"wpforms[fields][68][]\" value=\"Employ\u00e9\" aria-errormessage=\"wpforms-44-field_68_1-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_68_1\">Employ\u00e9<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_68_2\" name=\"wpforms[fields][68][]\" value=\"Ind\u00e9pendant\" aria-errormessage=\"wpforms-44-field_68_2-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_68_2\">Ind\u00e9pendant<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_68_3\" name=\"wpforms[fields][68][]\" value=\"Fonctionnaire\" aria-errormessage=\"wpforms-44-field_68_3-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_68_3\">Fonctionnaire<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_68_4\" name=\"wpforms[fields][68][]\" value=\"Activit\u00e9 non salari\u00e9 agricole\" aria-errormessage=\"wpforms-44-field_68_4-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_68_4\">Activit\u00e9 non salari\u00e9 agricole<\/label><\/li><li class=\"choice-5 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_68_5\" name=\"wpforms[fields][68][]\" value=\"\u00c9tudiant\" aria-errormessage=\"wpforms-44-field_68_5-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_68_5\">\u00c9tudiant<\/label><\/li><li class=\"choice-7 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_68_7\" name=\"wpforms[fields][68][]\" value=\"Sans emploi\" aria-errormessage=\"wpforms-44-field_68_7-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_68_7\">Sans emploi<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-44-field_67-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"67\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"19\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-20  \" data-page=\"20\" style=\"display:none;\"><div id=\"wpforms-44-field_69-container\" class=\"wpforms-field wpforms-field-layout\" data-field-id=\"69\"><div class=\"wpforms-field-layout-rows wpforms-field-large\"><div class=\"wpforms-layout-row\"><div class=\"wpforms-layout-column wpforms-layout-column-100\"><div id=\"wpforms-44-field_70-container\" class=\"wpforms-field wpforms-field-number\" data-field-id=\"70\"><label class=\"wpforms-field-label\" for=\"wpforms-44-field_70\">Num\u00e9ro de s\u00e9curit\u00e9 sociale : <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"number\" id=\"wpforms-44-field_70\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][70]\" step=\"any\" aria-errormessage=\"wpforms-44-field_70-error\" required><\/div><\/div><\/div><\/div><\/div><div id=\"wpforms-44-field_66-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"66\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"20\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-21  \" data-page=\"21\" style=\"display:none;\"><div id=\"wpforms-44-field_74-container\" class=\"wpforms-field wpforms-field-content\" data-field-id=\"74\"><div id=\"wpforms-44-field_74\" class=\"wpforms-field-large wpforms-field-row\" aria-errormessage=\"wpforms-44-field_74-error\"><h4><span class=\"jsQuestionLabelContainer jfQuestionLabelContainer\"><strong>Paiement s\u00e9curis\u00e9 de votre arr\u00eat maladie<\/strong><\/span><span class=\"jfRequiredStar\">*<\/span><\/h4>\n<h6><span style=\"font-family:monospace;font-size:16px\">Votre auto-diagnostic est d\u00e9j\u00e0 transmis \u00e0 l'un de nos m\u00e9decins partenaires<\/span><span style=\"font-family:monospace;font-size:16px\">,<\/span><\/h6>\n<p>vous recevrez votre arr\u00eat maladie tr\u00e8s rapidement<\/p>\n<div class=\"paymentCard-footer-wrapper\">\n<div class=\"paymentCard-productListWrapper\">\n<div class=\"paymentCard-footer\">\n<div class=\"paymentCard-footerRight new-payment-coupon\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>.<\/p>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><div id=\"wpforms-44-field_122-container\" class=\"wpforms-field wpforms-field-payment-single\" data-field-id=\"122\"><label class=\"wpforms-field-label\">Prix :<\/label><div class=\"wpforms-single-item-price-content\"><div class=\"wpforms-single-item-price wpforms-field-medium wpforms-payment-price\">Prix\u00a0: <span class=\"wpforms-price\">24,00 &euro;<\/span><\/div><\/div><input type=\"hidden\" id=\"wpforms-44-field_122\" class=\"wpforms-field-medium wpforms-payment-price\" name=\"wpforms[fields][122]\" value=\"24,00 &euro;\"><\/div><div id=\"wpforms-44-field_120-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"120\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"21\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-22 last \" data-page=\"22\" style=\"display:none;\"><div id=\"wpforms-44-field_121-container\" class=\"wpforms-field wpforms-field-paypal-commerce\" data-field-id=\"121\"><label class=\"wpforms-field-label\">Paiement <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"hidden\" name=\"wpforms[fields][121][orderID]\" class=\"wpforms-paypal-commerce-order-id\" \/><input type=\"hidden\" name=\"wpforms[fields][121][subscriptionID]\" class=\"wpforms-paypal-commerce-subscription-id\" \/><input type=\"hidden\" name=\"wpforms[fields][121][subscriptionProcessorID]\" class=\"wpforms-paypal-commerce-subscription-processor-id\" \/><input type=\"hidden\" name=\"wpforms[fields][121][source]\" class=\"wpforms-paypal-commerce-source\" \/><input type=\"hidden\" name=\"wpforms[fields][121][fastlane_token]\" class=\"wpforms-paypal-commerce-fastlane-token\" \/><div class=\"wpforms-paypal-commerce-card-fields \"><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-paypal-commerce-supported-cards\"><div class=\"wpforms-paypal-commerce-maestro-icon\"><\/div><div class=\"wpforms-paypal-commerce-mastercard-icon\"><\/div><div class=\"wpforms-paypal-commerce-visa-icon\"><\/div><\/div><\/div><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-paypal-commerce-number\"><div id=\"wpforms-44-field_121-cardnumber\" class=\"wpforms-field-paypal-commerce-cardnumber wpforms-field-required\" aria-errormessage=\"wpforms-44-field_121-cardnumber-error\" data-required=\"required\"><\/div><input type=\"text\" class=\"wpforms-paypal-commerce-credit-card-hidden-input\" name=\"wpforms[paypal-commerce-credit-card-hidden-input-44]\" id=\"wpforms-paypal-commerce-credit-card-hidden-input-44-number\" disabled style=\"display: none;\"><label for=\"wpforms-paypal-commerce-credit-card-hidden-input-44-number\" class=\"wpforms-field-sublabel after\">Num\u00e9ro de carte<\/label><\/div><\/div><div class=\"wpforms-field-row wpforms-field-row-responsive wpforms-field-medium\"><div class=\"wpforms-field-row-block wpforms-one-half wpforms-first wpforms-field-paypal-commerce-date\"><div id=\"wpforms-44-field_121-carddate\" class=\"wpforms-field-paypal-commerce-carddate wpforms-field-required\" aria-errormessage=\"wpforms-44-field_121-carddate-error\" data-required=\"required\"><\/div><input type=\"text\" class=\"wpforms-paypal-commerce-credit-card-hidden-input\" name=\"wpforms[paypal-commerce-credit-card-hidden-input-44]\" id=\"wpforms-paypal-commerce-credit-card-hidden-input-44-date\" disabled style=\"display: none;\"><label for=\"wpforms-paypal-commerce-credit-card-hidden-input-44-date\" class=\"wpforms-field-sublabel after\">Expiration Date<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half wpforms-field-paypal-commerce-code\"><div id=\"wpforms-44-field_121-cardcode\" class=\"wpforms-field-paypal-commerce-cardcode wpforms-field-required\" aria-errormessage=\"wpforms-44-field_121-cardcode-error\" data-required=\"required\"><\/div><input type=\"text\" class=\"wpforms-paypal-commerce-credit-card-hidden-input\" name=\"wpforms[paypal-commerce-credit-card-hidden-input-44]\" id=\"wpforms-paypal-commerce-credit-card-hidden-input-44-code\" disabled style=\"display: none;\"><label for=\"wpforms-paypal-commerce-credit-card-hidden-input-44-code\" class=\"wpforms-field-sublabel after\">Code de s\u00e9curit\u00e9 (CVC)<\/label><\/div><\/div><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-paypal-commerce-name\"><input type=\"text\" id=\"wpforms-44-field_121-cardname\" class=\"wpforms-field-paypal-commerce-cardname wpforms-field-required\" name=\"wpforms[fields][121][cardname]\" aria-errormessage=\"wpforms-44-field_121-cardname-error\" required><label for=\"wpforms-44-field_121-cardname\" class=\"wpforms-field-sublabel after\">Card Holder Name<\/label><\/div><\/div><\/div><\/div><div id=\"wpforms-44-field_5-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"5\"><\/div><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" style=\"display:none;\"><input type=\"hidden\" name=\"wpforms[id]\" value=\"44\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/app.vosol-france.com\/index.php\/wp-json\/wp\/v2\/pages\/47\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-44\" class=\"wpforms-submit\" data-alt-text=\"Sending...\" data-submit-text=\"Terminer\" aria-live=\"assertive\" value=\"wpforms-submit\">Terminer<\/button><img decoding=\"async\" src=\"https:\/\/app.vosol-france.com\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Chargement en cours\"><div class=\"wpforms-paypal-commerce-single-submit-button size-medium\"><img decoding=\"async\" src=\"https:\/\/app.vosol-france.com\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-paypal-commerce-single-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Chargement en cours\"><div class=\"wpforms-paypal-commerce-applepay-button wpforms-hidden\" style=\"--apple-pay-button-border-radius: 23px;\"><\/div><div class=\"wpforms-paypal-commerce-googlepay-button wpforms-hidden\"><\/div><\/div><div class=\"wpforms-paypal-commerce-subscriptions-submit-button size-medium\"><img decoding=\"async\" src=\"https:\/\/app.vosol-france.com\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-paypal-commerce-recurring-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Chargement en cours\"><\/div><\/div><\/form><\/div>  <!-- .wpforms-container --><\/code> par votre code\r\n                        <\/p>\r\n                    <\/div>\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n        <!-- ============================================================ -->\r\n        <!-- ========== FIN FORM SECTION ========== -->\r\n        <!-- ============================================================ -->\r\n\r\n        <!-- ========== FOOTER ========== -->\r\n        <div class=\"footer\">\r\n            <div class=\"footer-links\">\r\n                <a href=\"#\" onclick=\"showToast('\ud83d\udcde Support : 01 23 45 67 89')\">Aide<\/a>\r\n                <a href=\"#\" onclick=\"showToast('\ud83d\udd12 Arr\u00eat de travail s\u00e9curis\u00e9 et conforme')\">S\u00e9curit\u00e9<\/a>\r\n                <a href=\"#\" onclick=\"showToast('\ud83d\udce7 contact@arret-travail.fr')\">Contact<\/a>\r\n                <a href=\"#\" onclick=\"showToast('\ud83d\udcf1 Version mobile optimis\u00e9e')\">Mobile<\/a>\r\n                <a href=\"#\" onclick=\"showToast('\ud83d\udccb Mentions l\u00e9gales disponibles')\">Mentions l\u00e9gales<\/a>\r\n            <\/div>\r\n            <div class=\"footer-divider\"><\/div>\r\n            <div class=\"footer-copy\">\r\n                &copy; Vosol-France \u00b7 Tous droits r\u00e9serv\u00e9s\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n\r\n    <!-- ========== FAB ========== -->\r\n    <button class=\"fab-help\" onclick=\"showToast('\ud83d\udcac Un conseiller est disponible pour vous aider')\" aria-label=\"Aide\">\r\n        <i class=\"fas fa-headset\"><\/i>\r\n    <\/button>\r\n\r\n    <!-- ========== TOAST ========== -->\r\n    <div class=\"toast\" id=\"toast\"><\/div>\r\n\r\n    <script>\r\n        \/\/ ========== V\u00c9RIFICATION DE WPForms ==========\r\n        document.addEventListener('DOMContentLoaded', function() {\r\n            const wpformsContainer = document.querySelector('.wpforms-container');\r\n            if (wpformsContainer) {\r\n                const content = wpformsContainer.innerHTML;\r\n                if (content.includes('<style id=\"wpforms-css-vars-44\">\n\t\t\t\t#wpforms-44 {\n\t\t\t\t--wpforms-field-size-input-height: 43px;\n--wpforms-field-size-input-spacing: 15px;\n--wpforms-field-size-font-size: 16px;\n--wpforms-field-size-line-height: 19px;\n--wpforms-field-size-padding-h: 14px;\n--wpforms-field-size-checkbox-size: 16px;\n--wpforms-field-size-sublabel-spacing: 5px;\n--wpforms-field-size-icon-size: 1;\n--wpforms-label-size-font-size: 16px;\n--wpforms-label-size-line-height: 19px;\n--wpforms-label-size-sublabel-font-size: 14px;\n--wpforms-label-size-sublabel-line-height: 17px;\n--wpforms-button-size-font-size: 17px;\n--wpforms-button-size-height: 41px;\n--wpforms-button-size-padding-h: 15px;\n--wpforms-button-size-margin-top: 10px;\n--wpforms-container-shadow-size-box-shadow: none;\n\t\t\t}\n\t\t\t<\/style><div class=\"wpforms-container wpforms-container-full wpforms-paypal-commerce wpforms-render-modern\" id=\"wpforms-44\"><form id=\"wpforms-form-44\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"44\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/index.php\/wp-json\/wp\/v2\/pages\/47\" data-token=\"f436251ed89244ea4ac8ab7b974aa6ec\" data-token-time=\"1784100250\"><noscript class=\"wpforms-error-noscript\">Veuillez activer JavaScript dans votre navigateur pour remplir ce formulaire.<\/noscript><div id=\"wpforms-error-noscript\" style=\"display: none;\">Veuillez activer JavaScript dans votre navigateur pour remplir ce formulaire.<\/div><div class=\"wpforms-page-indicator progress\" data-indicator=\"progress\" data-indicator-color=\"#3a54b3\" data-scroll=\"1\" role=\"progressbar\" aria-valuenow=\"1\" aria-valuemin=\"1\" aria-valuemax=\"22\" tabindex=\"-1\"><span class=\"wpforms-page-indicator-page-title\" ><\/span><span class=\"wpforms-page-indicator-page-title-sep\" style=\"display:none;\"> - <\/span><span class=\"wpforms-page-indicator-steps\">Step <span class=\"wpforms-page-indicator-steps-current\">1<\/span> of 22<\/span><div class=\"wpforms-page-indicator-page-progress-wrap\"><div class=\"wpforms-page-indicator-page-progress\" style=\"width:4.5454545454545%;background-color:#3a54b3\"><\/div><\/div><\/div><div class=\"wpforms-field-container\"><div class=\"wpforms-page wpforms-page-1 \" data-page=\"1\"><div id=\"wpforms-44-field_4-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"4\"><\/div><div id=\"wpforms-44-field_13-container\" class=\"wpforms-field wpforms-field-content\" data-field-id=\"13\"><div id=\"wpforms-44-field_13\" class=\"wpforms-field-medium wpforms-field-row\" aria-errormessage=\"wpforms-44-field_13-error\"><h4 class=\"jfWelcome-header form-header\"><span style=\"color:#0000ff\">Bienvenue sur votre auto-diagnostic<\/span><\/h4>\n<div class=\"jfWelcome-description form-subHeader\"><span style=\"color:#3366ff\">Lors de votre auto-diagnostic, votre cas est imm\u00e9diatement transmis \u00e0 nos m\u00e9decins partenaires pour une v\u00e9rification en direct, permettant ainsi d'obtenir votre arr\u00eat maladie rapidement.<\/span><\/div>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><div id=\"wpforms-44-field_3-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"3\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"1\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Commencer<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-2  \" data-page=\"2\" style=\"display:none;\"><div id=\"wpforms-44-field_14-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-modern\" data-field-id=\"14\"><label class=\"wpforms-field-label\" for=\"wpforms-44-field_14\">Choisissez la maladie pr\u00e9sum\u00e9e: <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><select id=\"wpforms-44-field_14\" class=\"wpforms-field-large wpforms-field-required choicesjs-select\" data-size-class=\"wpforms-field-row wpforms-field-large\" data-search-enabled=\"1\" name=\"wpforms[fields][14]\" required=\"required\"><option value=\"\" class=\"placeholder\" disabled  selected='selected'><\/option><option value=\"Veuillez s\u00e9lectionner\"  class=\"choice-1 depth-1\"  >Veuillez s\u00e9lectionner<\/option><option value=\"Gastro-ent\u00e9rite\"  class=\"choice-2 depth-1\"  >Gastro-ent\u00e9rite<\/option><option value=\"Sympt\u00f4me Corona\"  class=\"choice-3 depth-1\"  >Sympt\u00f4me Corona<\/option><option value=\"Stress\"  class=\"choice-7 depth-1\"  >Stress<\/option><option value=\"Migraine\"  class=\"choice-6 depth-1\"  >Migraine<\/option><option value=\"Mal de dos\"  class=\"choice-5 depth-1\"  >Mal de dos<\/option><option value=\"Douleurs menstruelles\"  class=\"choice-4 depth-1\"  >Douleurs menstruelles<\/option><option value=\"Cystite\"  class=\"choice-8 depth-1\"  >Cystite<\/option><option value=\"Blessures\"  class=\"choice-9 depth-1\"  >Blessures<\/option><option value=\"Douleurs abdominales \/ pelviennes\"  class=\"choice-10 depth-1\"  >Douleurs abdominales \/ pelviennes<\/option><option value=\"Hypertension\"  class=\"choice-11 depth-1\"  >Hypertension<\/option><option value=\"Allergie\"  class=\"choice-12 depth-1\"  >Allergie<\/option><option value=\"Le corps n\u2019est pas libre de ses mouvements\"  class=\"choice-13 depth-1\"  >Le corps n\u2019est pas libre de ses mouvements<\/option><option value=\"Probl\u00e8mes dentaires\"  class=\"choice-15 depth-1\"  >Probl\u00e8mes dentaires<\/option><option value=\"Maux de t\u00eate\"  class=\"choice-14 depth-1\"  >Maux de t\u00eate<\/option><option value=\"Naus\u00e9es\/ Vomissements\"  class=\"choice-16 depth-1\"  >Naus\u00e9es\/ Vomissements<\/option><option value=\"Gastrite\"  class=\"choice-17 depth-1\"  >Gastrite<\/option><option value=\"Probl\u00e8mes articulaires\"  class=\"choice-18 depth-1\"  >Probl\u00e8mes articulaires<\/option><option value=\"\u00c9v\u00e8nement : Deuil, crise etc.\"  class=\"choice-19 depth-1\"  >\u00c9v\u00e8nement : Deuil, crise etc.<\/option><option value=\"Syndrome d\u2019\u00e9puisement\"  class=\"choice-20 depth-1\"  >Syndrome d\u2019\u00e9puisement<\/option><\/select><div id=\"wpforms-44-field_14-description\" class=\"wpforms-field-description\">Une seule possibilit\u00e9<\/div><\/div><div id=\"wpforms-44-field_8-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"8\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"2\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-3  \" data-page=\"3\" style=\"display:none;\"><div id=\"wpforms-44-field_15-container\" class=\"wpforms-field wpforms-field-layout\" data-field-id=\"15\"><div class=\"wpforms-field-layout-columns wpforms-field-layout-preset-100\"><div class=\"wpforms-layout-column wpforms-layout-column-100\" ><div id=\"wpforms-44-field_16-container\" class=\"wpforms-field wpforms-field-checkbox wpforms-list-2-columns\" data-field-id=\"16\"><fieldset><legend class=\"wpforms-field-label\">Avez-vous d\u00e9j\u00e0 \u00e9t\u00e9 diagnostiqu\u00e9 pour ce sympt\u00f4me par un m\u00e9decin ? <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><ul id=\"wpforms-44-field_16\" class=\"wpforms-field-required\" data-choice-limit=\"1\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_16_1\" data-rule-check-limit=\"true\" name=\"wpforms[fields][16][]\" value=\"Oui\" aria-errormessage=\"wpforms-44-field_16_1-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_16_1\">Oui<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_16_2\" data-rule-check-limit=\"true\" name=\"wpforms[fields][16][]\" value=\"Non\" aria-errormessage=\"wpforms-44-field_16_2-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_16_2\">Non<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_16_3\" data-rule-check-limit=\"true\" name=\"wpforms[fields][16][]\" value=\"Peut-etre\" aria-errormessage=\"wpforms-44-field_16_3-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_16_3\">Peut-etre<\/label><\/li><\/ul><\/fieldset><\/div><\/div><\/div><\/div><div id=\"wpforms-44-field_6-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"6\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"3\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-4  \" data-page=\"4\" style=\"display:none;\"><div id=\"wpforms-44-field_17-container\" class=\"wpforms-field wpforms-field-checkbox wpforms-list-3-columns\" data-field-id=\"17\"><fieldset><legend class=\"wpforms-field-label\">\ud83e\udd15 Choisissez vos sympt\u00f4mes : <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><ul id=\"wpforms-44-field_17\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_17_1\" name=\"wpforms[fields][17][]\" value=\"Fi\u00e8vre\" aria-errormessage=\"wpforms-44-field_17_1-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_17_1\">Fi\u00e8vre<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_17_2\" name=\"wpforms[fields][17][]\" value=\"Naus\u00e9es\" aria-errormessage=\"wpforms-44-field_17_2-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_17_2\">Naus\u00e9es<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_17_3\" name=\"wpforms[fields][17][]\" value=\"Diarrh\u00e9e\" aria-errormessage=\"wpforms-44-field_17_3-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_17_3\">Diarrh\u00e9e<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_17_4\" name=\"wpforms[fields][17][]\" value=\"Toux sans mucus\" aria-errormessage=\"wpforms-44-field_17_4-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_17_4\">Toux sans mucus<\/label><\/li><li class=\"choice-5 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_17_5\" name=\"wpforms[fields][17][]\" value=\"Toux avec mucosit\u00e9s\" aria-errormessage=\"wpforms-44-field_17_5-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_17_5\">Toux avec mucosit\u00e9s<\/label><\/li><li class=\"choice-6 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_17_6\" name=\"wpforms[fields][17][]\" value=\"Malaise\" aria-errormessage=\"wpforms-44-field_17_6-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_17_6\">Malaise<\/label><\/li><li class=\"choice-7 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_17_7\" name=\"wpforms[fields][17][]\" value=\"Fatigue\" aria-errormessage=\"wpforms-44-field_17_7-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_17_7\">Fatigue<\/label><\/li><li class=\"choice-9 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_17_9\" name=\"wpforms[fields][17][]\" value=\"Hypertension art\u00e9rielle\" aria-errormessage=\"wpforms-44-field_17_9-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_17_9\">Hypertension art\u00e9rielle<\/label><\/li><li class=\"choice-8 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_17_8\" name=\"wpforms[fields][17][]\" value=\"Le corps n&#039;est pas libre de ses mouvements\" aria-errormessage=\"wpforms-44-field_17_8-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_17_8\">Le corps n'est pas libre de ses mouvements<\/label><\/li><li class=\"choice-10 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_17_10\" name=\"wpforms[fields][17][]\" value=\"\u00c9v\u00e9nement stressant de la vie\" aria-errormessage=\"wpforms-44-field_17_10-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_17_10\">\u00c9v\u00e9nement stressant de la vie<\/label><\/li><li class=\"choice-11 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_17_11\" name=\"wpforms[fields][17][]\" value=\"Troubles du sommeil\" aria-errormessage=\"wpforms-44-field_17_11-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_17_11\">Troubles du sommeil<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-44-field_7-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"7\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"4\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-5  \" data-page=\"5\" style=\"display:none;\"><div id=\"wpforms-44-field_24-container\" class=\"wpforms-field wpforms-field-checkbox wpforms-list-3-columns\" data-field-id=\"24\"><fieldset><legend class=\"wpforms-field-label\">douleurs situ\u00e9es dans la :  <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><ul id=\"wpforms-44-field_24\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_24_1\" name=\"wpforms[fields][24][]\" value=\"T\u00eate\" aria-errormessage=\"wpforms-44-field_24_1-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_24_1\">T\u00eate<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_24_2\" name=\"wpforms[fields][24][]\" value=\"Ventre\" aria-errormessage=\"wpforms-44-field_24_2-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_24_2\">Ventre<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_24_3\" name=\"wpforms[fields][24][]\" value=\"Dent\" aria-errormessage=\"wpforms-44-field_24_3-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_24_3\">Dent<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_24_4\" name=\"wpforms[fields][24][]\" value=\"Dos\" aria-errormessage=\"wpforms-44-field_24_4-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_24_4\">Dos<\/label><\/li><li class=\"choice-7 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_24_7\" name=\"wpforms[fields][24][]\" value=\"Cou\" aria-errormessage=\"wpforms-44-field_24_7-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_24_7\">Cou<\/label><\/li><li class=\"choice-6 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_24_6\" name=\"wpforms[fields][24][]\" value=\"Membres\" aria-errormessage=\"wpforms-44-field_24_6-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_24_6\">Membres<\/label><\/li><li class=\"choice-5 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_24_5\" name=\"wpforms[fields][24][]\" value=\"Oreille\" aria-errormessage=\"wpforms-44-field_24_5-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_24_5\">Oreille<\/label><\/li><li class=\"choice-8 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_24_8\" name=\"wpforms[fields][24][]\" value=\"Organe sexuel\" aria-errormessage=\"wpforms-44-field_24_8-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_24_8\">Organe sexuel<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-44-field_23-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"23\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"5\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-6  \" data-page=\"6\" style=\"display:none;\"><div id=\"wpforms-44-field_26-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"26\"><label class=\"wpforms-field-label\" for=\"wpforms-44-field_26\">\ud83d\udcdd D\u00e9crire tous les autres sympt\u00f4mes :<\/label><textarea id=\"wpforms-44-field_26\" class=\"wpforms-field-medium\" name=\"wpforms[fields][26]\" aria-errormessage=\"wpforms-44-field_26-error\" ><\/textarea><\/div><div id=\"wpforms-44-field_25-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"25\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"6\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-7  \" data-page=\"7\" style=\"display:none;\"><div id=\"wpforms-44-field_27-container\" class=\"wpforms-field wpforms-field-checkbox wpforms-list-3-columns\" data-field-id=\"27\"><fieldset><legend class=\"wpforms-field-label\">\u26a1 Est-ce que les sympt\u00f4mes sont apparues soudainement ? <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><ul id=\"wpforms-44-field_27\" class=\"wpforms-field-required\" data-choice-limit=\"1\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_27_1\" data-rule-check-limit=\"true\" name=\"wpforms[fields][27][]\" value=\"Oui\" aria-errormessage=\"wpforms-44-field_27_1-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_27_1\">Oui<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_27_2\" data-rule-check-limit=\"true\" name=\"wpforms[fields][27][]\" value=\"Non\" aria-errormessage=\"wpforms-44-field_27_2-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_27_2\">Non<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_27_3\" data-rule-check-limit=\"true\" name=\"wpforms[fields][27][]\" value=\"Peut-\u00eatre\" aria-errormessage=\"wpforms-44-field_27_3-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_27_3\">Peut-\u00eatre<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-44-field_28-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"28\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"7\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-8  \" data-page=\"8\" style=\"display:none;\"><div id=\"wpforms-44-field_30-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"30\"><label class=\"wpforms-field-label\" for=\"wpforms-44-field_30\">\ud83d\udc8a Si vous prenez des m\u00e9dicaments : Quels sont les m\u00e9dicaments pris r\u00e9guli\u00e8rement ?<\/label><textarea id=\"wpforms-44-field_30\" class=\"wpforms-field-medium\" name=\"wpforms[fields][30]\" aria-errormessage=\"wpforms-44-field_30-error\" ><\/textarea><\/div><div id=\"wpforms-44-field_29-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"29\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"8\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-9  \" data-page=\"9\" style=\"display:none;\"><div id=\"wpforms-44-field_33-container\" class=\"wpforms-field wpforms-field-content\" data-field-id=\"33\"><div id=\"wpforms-44-field_33\" class=\"wpforms-field-medium wpforms-field-row\" aria-errormessage=\"wpforms-44-field_33-error\"><p>\u26a0\ufe0f Pr\u00e9sentez-vous l'un de ces facteurs de risque ?<\/p>\n<ul>\n<li><span style=\"color:#3366ff\">Vous avez des difficult\u00e9s respiratoires, des vomissements ou de la diarrh\u00e9e<\/span><\/li>\n<li><span style=\"color:#3366ff\">Bruits ou obstructions lors de la respiration<\/span><\/li>\n<li><span style=\"color:#3366ff\">Enceinte, immunod\u00e9ficience<\/span><\/li>\n<li><span style=\"color:#3366ff\">Douleur intense, en particulier dans l'oreille, le visage ou les membres<\/span><\/li>\n<li><span style=\"color:#3366ff\">Douleur au larynx, \u00e0 la poitrine ou \u00e0 l'abdomen<\/span><\/li>\n<li><span style=\"color:#3366ff\">Maladie cardiaque, respiratoire ou intestinale chronique<\/span><\/li>\n<li><span style=\"color:#3366ff\">Voyage tropical au cours des deux derniers mois<\/span><\/li>\n<li><span style=\"color:#3366ff\">Sentiment de maladie grave ou difficult\u00e9 \u00e0 avaler<\/span><\/li>\n<li><span style=\"color:#3366ff\">Paralysie, troubles de la conscience, saignements, \u00e9ruptions cutan\u00e9es<\/span><\/li>\n<\/ul>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><div id=\"wpforms-44-field_31-container\" class=\"wpforms-field wpforms-field-checkbox wpforms-conditional-trigger\" data-field-id=\"31\"><fieldset><legend class=\"wpforms-field-label wpforms-label-hide\" aria-hidden=\"false\">\u26a0\ufe0f Pr\u00e9sentez-vous l&#039;un de ces facteurs de risque ? <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><ul id=\"wpforms-44-field_31\" class=\"wpforms-field-required\" data-choice-limit=\"1\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_31_1\" data-rule-check-limit=\"true\" name=\"wpforms[fields][31][]\" value=\"Oui\" aria-errormessage=\"wpforms-44-field_31_1-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_31_1\">Oui<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_31_2\" data-rule-check-limit=\"true\" name=\"wpforms[fields][31][]\" value=\"Non\" aria-errormessage=\"wpforms-44-field_31_2-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_31_2\">Non<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-44-field_34-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"34\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"9\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-10  \" data-page=\"10\" style=\"display:none;\"><div id=\"wpforms-44-field_93-container\" class=\"wpforms-field wpforms-field-content wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"93\" style=\"display:none;\"><div id=\"wpforms-44-field_93\" class=\"wpforms-field-medium wpforms-field-row\" aria-errormessage=\"wpforms-44-field_93-error\"><h4>Votre cas ne peux pas \u00eatre traiter en ligne sans consultation d'un m\u00e9decin !<\/h4>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><div id=\"wpforms-44-field_90-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"90\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-prev wpforms-disabled\"\n\t\t\t\t\tdata-action=\"prev\" data-page=\"10\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Pr\u00e9c\u00e9dent<\/button><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"10\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-11  \" data-page=\"11\" style=\"display:none;\"><div id=\"wpforms-44-field_35-container\" class=\"wpforms-field wpforms-field-checkbox wpforms-list-2-columns\" data-field-id=\"35\"><fieldset><legend class=\"wpforms-field-label\">\ud83e\udd14 Votre employeur est-il insatisfait de votre travail, m\u00e9fiant ou a d\u00e9j\u00e0 contest\u00e9 des attestations ?  <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><ul id=\"wpforms-44-field_35\" class=\"wpforms-field-required\" data-choice-limit=\"1\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_35_1\" data-rule-check-limit=\"true\" name=\"wpforms[fields][35][]\" value=\"Oui\" aria-errormessage=\"wpforms-44-field_35_1-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_35_1\">Oui<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_35_2\" data-rule-check-limit=\"true\" name=\"wpforms[fields][35][]\" value=\"Non\" aria-errormessage=\"wpforms-44-field_35_2-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_35_2\">Non<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-44-field_39-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"39\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"11\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-12  \" data-page=\"12\" style=\"display:none;\"><div id=\"wpforms-44-field_37-container\" class=\"wpforms-field wpforms-field-checkbox wpforms-list-2-columns\" data-field-id=\"37\"><fieldset><legend class=\"wpforms-field-label\">\ud83d\udcdd Avez-vous besoin d&#039;un nouvel arr\u00eat maladie ou d&#039;une prolongation ? <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><ul id=\"wpforms-44-field_37\" class=\"wpforms-field-required\" data-choice-limit=\"1\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_37_1\" data-rule-check-limit=\"true\" name=\"wpforms[fields][37][]\" value=\"Nouvel Arr\u00eat maladie\" aria-errormessage=\"wpforms-44-field_37_1-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_37_1\">Nouvel Arr\u00eat maladie<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_37_2\" data-rule-check-limit=\"true\" name=\"wpforms[fields][37][]\" value=\"Suivi\" aria-errormessage=\"wpforms-44-field_37_2-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_37_2\">Suivi<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-44-field_38-container\" class=\"wpforms-field wpforms-field-content\" data-field-id=\"38\"><div id=\"wpforms-44-field_38\" class=\"wpforms-field-medium wpforms-field-row\" aria-errormessage=\"wpforms-44-field_38-error\"><p><span style=\"color:#3366ff\">Choisissez le suivi de l'arr\u00eat maladie uniquement si vous avez d\u00e9j\u00e0 eu un arr\u00eat maladie pour les m\u00eames sympt\u00f4mes et pour un maximum de 7 jours<\/span><\/p>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><div id=\"wpforms-44-field_40-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"40\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"12\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-13  \" data-page=\"13\" style=\"display:none;\"><div id=\"wpforms-44-field_41-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"41\"><label class=\"wpforms-field-label\" for=\"wpforms-44-field_41\">\ud83d\udc68\u200d\ud83d\udd27 Quelle est votre profession actuelle ?  <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><textarea id=\"wpforms-44-field_41\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][41]\" aria-errormessage=\"wpforms-44-field_41-error\" required><\/textarea><\/div><div id=\"wpforms-44-field_42-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"42\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"13\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-14  \" data-page=\"14\" style=\"display:none;\"><div id=\"wpforms-44-field_46-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-id=\"46\"><fieldset><legend class=\"wpforms-field-label\">\ud83d\udcaa \u00c0 quel point votre travail est-il physiquement exigeant ?  <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><ul id=\"wpforms-44-field_46\" class=\"wpforms-field-required\" data-choice-limit=\"1\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_46_1\" data-rule-check-limit=\"true\" name=\"wpforms[fields][46][]\" value=\"L\u00e9ger\" aria-errormessage=\"wpforms-44-field_46_1-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_46_1\">L\u00e9ger<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_46_2\" data-rule-check-limit=\"true\" name=\"wpforms[fields][46][]\" value=\"Moyen\" aria-errormessage=\"wpforms-44-field_46_2-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_46_2\">Moyen<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_46_3\" data-rule-check-limit=\"true\" name=\"wpforms[fields][46][]\" value=\"Elev\u00e9\" aria-errormessage=\"wpforms-44-field_46_3-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_46_3\">Elev\u00e9<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-44-field_45-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"45\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"14\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-15  \" data-page=\"15\" style=\"display:none;\"><div id=\"wpforms-44-field_47-container\" class=\"wpforms-field wpforms-field-content\" data-field-id=\"47\"><div id=\"wpforms-44-field_47\" class=\"wpforms-field-medium wpforms-field-row\" aria-errormessage=\"wpforms-44-field_47-error\"><h4><img decoding=\"async\" class=\"emoji\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/15.0.3\/svg\/1f4c6.svg\" alt=\"\ud83d\udcc6\" \/>\u00a0Choisissez les dates de d\u00e9but &amp; de fin de votre incapacit\u00e9 de travail :<\/h4>\n<p>C'est-\u00e0-dire qu'en raison de la maladie, vous ne pouvez plus exercer votre m\u00e9tier ou vous pr\u00e9sentez un risque de retarder la gu\u00e9rison.<\/p>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><div id=\"wpforms-44-field_48-container\" class=\"wpforms-field wpforms-field-layout\" data-field-id=\"48\"><div class=\"wpforms-field-layout-rows wpforms-field-large\"><div class=\"wpforms-layout-row\"><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-44-field_49-container\" class=\"wpforms-field wpforms-field-date-time\" data-field-id=\"49\"><label class=\"wpforms-field-label\" for=\"wpforms-44-field_49\">Date de d\u00e9but: <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><div class=\"wpforms-datepicker-wrap\"><input type=\"text\" id=\"wpforms-44-field_49\" class=\"wpforms-field-date-time-date wpforms-datepicker wpforms-field-required wpforms-field-medium\" data-date-format=\"d\/m\/Y\" data-disable-past-dates=\"0\" data-input=\"true\" name=\"wpforms[fields][49][date]\" aria-errormessage=\"wpforms-44-field_49-error\" required><a title=\"Effacer la date\" data-clear role=\"button\" tabindex=\"0\" class=\"wpforms-datepicker-clear\" aria-label=\"Effacer la date\" style=\"display:none;\"><\/a><\/div><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-44-field_50-container\" class=\"wpforms-field wpforms-field-date-time\" data-field-id=\"50\"><label class=\"wpforms-field-label\" for=\"wpforms-44-field_50\">Date de fin: <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><div class=\"wpforms-datepicker-wrap\"><input type=\"text\" id=\"wpforms-44-field_50\" class=\"wpforms-field-date-time-date wpforms-datepicker wpforms-field-required wpforms-field-medium\" data-date-format=\"d\/m\/Y\" data-disable-past-dates=\"0\" data-input=\"true\" name=\"wpforms[fields][50][date]\" aria-errormessage=\"wpforms-44-field_50-error\" required><a title=\"Effacer la date\" data-clear role=\"button\" tabindex=\"0\" class=\"wpforms-datepicker-clear\" aria-label=\"Effacer la date\" style=\"display:none;\"><\/a><\/div><\/div><\/div><\/div><\/div><\/div><div id=\"wpforms-44-field_43-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"43\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"15\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-16  \" data-page=\"16\" style=\"display:none;\"><div id=\"wpforms-44-field_52-container\" class=\"wpforms-field wpforms-field-layout\" data-field-id=\"52\"><div class=\"wpforms-field-layout-rows wpforms-field-large\"><div class=\"wpforms-layout-row\"><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-44-field_53-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"53\"><label class=\"wpforms-field-label\" for=\"wpforms-44-field_53\">Pr\u00e9nom: <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-44-field_53\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][53]\" aria-errormessage=\"wpforms-44-field_53-error\" required><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-44-field_54-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"54\"><label class=\"wpforms-field-label\" for=\"wpforms-44-field_54\">Nom : <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-44-field_54\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][54]\" aria-errormessage=\"wpforms-44-field_54-error\" required><\/div><\/div><\/div><div class=\"wpforms-layout-row\"><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-44-field_55-container\" class=\"wpforms-field wpforms-field-date-time\" data-field-id=\"55\"><label class=\"wpforms-field-label\" for=\"wpforms-44-field_55\">\ud83c\udf82 Date de naissance : <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><div class=\"wpforms-datepicker-wrap\"><input type=\"text\" id=\"wpforms-44-field_55\" class=\"wpforms-field-date-time-date wpforms-datepicker wpforms-field-required wpforms-field-medium\" data-date-format=\"d\/m\/Y\" data-disable-past-dates=\"0\" data-input=\"true\" name=\"wpforms[fields][55][date]\" aria-errormessage=\"wpforms-44-field_55-error\" required><a title=\"Effacer la date\" data-clear role=\"button\" tabindex=\"0\" class=\"wpforms-datepicker-clear\" aria-label=\"Effacer la date\" style=\"display:none;\"><\/a><\/div><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-44-field_56-container\" class=\"wpforms-field wpforms-field-phone\" data-field-id=\"56\"><label class=\"wpforms-field-label\" for=\"wpforms-44-field_56\">T\u00e9l\u00e9phone: <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"tel\" id=\"wpforms-44-field_56\" class=\"wpforms-field-medium wpforms-field-required\" data-rule-int-phone-field=\"true\" name=\"wpforms[fields][56]\" aria-label=\"T\u00e9l\u00e9phone:\" aria-errormessage=\"wpforms-44-field_56-error\" required><\/div><\/div><\/div><div class=\"wpforms-layout-row\"><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-44-field_78-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"78\"><label class=\"wpforms-field-label\" for=\"wpforms-44-field_78\">E-mail <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-44-field_78\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][78]\" spellcheck=\"false\" aria-errormessage=\"wpforms-44-field_78-error\" required><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-50\"><\/div><\/div><\/div><\/div><div id=\"wpforms-44-field_44-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"44\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"16\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-17  \" data-page=\"17\" style=\"display:none;\"><div id=\"wpforms-44-field_51-container\" class=\"wpforms-field wpforms-field-layout\" data-field-id=\"51\"><div class=\"wpforms-field-layout-rows wpforms-field-large\"><div class=\"wpforms-layout-row\"><div class=\"wpforms-layout-column wpforms-layout-column-100\"><div id=\"wpforms-44-field_61-container\" class=\"wpforms-field wpforms-field-address\" data-field-id=\"61\"><fieldset><legend class=\"wpforms-field-label\">Adresse: <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><div class=\"wpforms-field-row wpforms-field-large\"><div ><input type=\"text\" id=\"wpforms-44-field_61\" class=\"wpforms-field-address-address1 wpforms-field-required\" name=\"wpforms[fields][61][address1]\" aria-errormessage=\"wpforms-44-field_61-error\" required><label for=\"wpforms-44-field_61\" class=\"wpforms-field-sublabel after\">Adresse ligne\u00a01<\/label><\/div><\/div><div class=\"wpforms-field-row wpforms-field-large\"><div class=\"wpforms-field-row-block wpforms-one-half wpforms-first\"><input type=\"text\" id=\"wpforms-44-field_61-city\" class=\"wpforms-field-address-city wpforms-field-required\" name=\"wpforms[fields][61][city]\" aria-errormessage=\"wpforms-44-field_61-city-error\" required><label for=\"wpforms-44-field_61-city\" class=\"wpforms-field-sublabel after\">Ville<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-44-field_61-state\" class=\"wpforms-field-address-state wpforms-field-required\" name=\"wpforms[fields][61][state]\" aria-errormessage=\"wpforms-44-field_61-state-error\" required><label for=\"wpforms-44-field_61-state\" class=\"wpforms-field-sublabel after\">\u00c9tat \/ Province \/ R\u00e9gion<\/label><\/div><\/div><div class=\"wpforms-field-row wpforms-field-large\"><div class=\"wpforms-field-row-block wpforms-one-half wpforms-first\"><input type=\"text\" id=\"wpforms-44-field_61-postal\" class=\"wpforms-field-address-postal wpforms-field-required\" name=\"wpforms[fields][61][postal]\" aria-errormessage=\"wpforms-44-field_61-postal-error\" required><label for=\"wpforms-44-field_61-postal\" class=\"wpforms-field-sublabel after\">Code postal<\/label><\/div><\/div><\/fieldset><\/div><\/div><\/div><div class=\"wpforms-layout-row\"><div class=\"wpforms-layout-column wpforms-layout-column-100\"><div id=\"wpforms-44-field_82-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"82\"><label class=\"wpforms-field-label\" for=\"wpforms-44-field_82\">Pays <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-44-field_82\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][82]\" placeholder=\"France\" aria-errormessage=\"wpforms-44-field_82-error\" required><\/div><\/div><\/div><\/div><\/div><div id=\"wpforms-44-field_36-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"36\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"17\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-18  \" data-page=\"18\" style=\"display:none;\"><div id=\"wpforms-44-field_64-container\" class=\"wpforms-field wpforms-field-layout\" data-field-id=\"64\"><div class=\"wpforms-field-layout-rows wpforms-field-large\"><div class=\"wpforms-layout-row\"><div class=\"wpforms-layout-column wpforms-layout-column-100\"><div id=\"wpforms-44-field_75-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"75\"><label class=\"wpforms-field-label\" for=\"wpforms-44-field_75\">Localisation du m\u00e9decin: <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-44-field_75\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][75]\" aria-errormessage=\"wpforms-44-field_75-error\" required><\/div><\/div><\/div><\/div><\/div><div id=\"wpforms-44-field_62-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"62\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"18\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-19  \" data-page=\"19\" style=\"display:none;\"><div id=\"wpforms-44-field_68-container\" class=\"wpforms-field wpforms-field-checkbox wpforms-list-inline\" data-field-id=\"68\"><fieldset><legend class=\"wpforms-field-label\">Cochez la case appropri\u00e9e: <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><ul id=\"wpforms-44-field_68\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_68_1\" name=\"wpforms[fields][68][]\" value=\"Employ\u00e9\" aria-errormessage=\"wpforms-44-field_68_1-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_68_1\">Employ\u00e9<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_68_2\" name=\"wpforms[fields][68][]\" value=\"Ind\u00e9pendant\" aria-errormessage=\"wpforms-44-field_68_2-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_68_2\">Ind\u00e9pendant<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_68_3\" name=\"wpforms[fields][68][]\" value=\"Fonctionnaire\" aria-errormessage=\"wpforms-44-field_68_3-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_68_3\">Fonctionnaire<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_68_4\" name=\"wpforms[fields][68][]\" value=\"Activit\u00e9 non salari\u00e9 agricole\" aria-errormessage=\"wpforms-44-field_68_4-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_68_4\">Activit\u00e9 non salari\u00e9 agricole<\/label><\/li><li class=\"choice-5 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_68_5\" name=\"wpforms[fields][68][]\" value=\"\u00c9tudiant\" aria-errormessage=\"wpforms-44-field_68_5-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_68_5\">\u00c9tudiant<\/label><\/li><li class=\"choice-7 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_68_7\" name=\"wpforms[fields][68][]\" value=\"Sans emploi\" aria-errormessage=\"wpforms-44-field_68_7-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_68_7\">Sans emploi<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-44-field_67-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"67\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"19\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-20  \" data-page=\"20\" style=\"display:none;\"><div id=\"wpforms-44-field_69-container\" class=\"wpforms-field wpforms-field-layout\" data-field-id=\"69\"><div class=\"wpforms-field-layout-rows wpforms-field-large\"><div class=\"wpforms-layout-row\"><div class=\"wpforms-layout-column wpforms-layout-column-100\"><div id=\"wpforms-44-field_70-container\" class=\"wpforms-field wpforms-field-number\" data-field-id=\"70\"><label class=\"wpforms-field-label\" for=\"wpforms-44-field_70\">Num\u00e9ro de s\u00e9curit\u00e9 sociale : <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"number\" id=\"wpforms-44-field_70\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][70]\" step=\"any\" aria-errormessage=\"wpforms-44-field_70-error\" required><\/div><\/div><\/div><\/div><\/div><div id=\"wpforms-44-field_66-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"66\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"20\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-21  \" data-page=\"21\" style=\"display:none;\"><div id=\"wpforms-44-field_74-container\" class=\"wpforms-field wpforms-field-content\" data-field-id=\"74\"><div id=\"wpforms-44-field_74\" class=\"wpforms-field-large wpforms-field-row\" aria-errormessage=\"wpforms-44-field_74-error\"><h4><span class=\"jsQuestionLabelContainer jfQuestionLabelContainer\"><strong>Paiement s\u00e9curis\u00e9 de votre arr\u00eat maladie<\/strong><\/span><span class=\"jfRequiredStar\">*<\/span><\/h4>\n<h6><span style=\"font-family:monospace;font-size:16px\">Votre auto-diagnostic est d\u00e9j\u00e0 transmis \u00e0 l'un de nos m\u00e9decins partenaires<\/span><span style=\"font-family:monospace;font-size:16px\">,<\/span><\/h6>\n<p>vous recevrez votre arr\u00eat maladie tr\u00e8s rapidement<\/p>\n<div class=\"paymentCard-footer-wrapper\">\n<div class=\"paymentCard-productListWrapper\">\n<div class=\"paymentCard-footer\">\n<div class=\"paymentCard-footerRight new-payment-coupon\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>.<\/p>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><div id=\"wpforms-44-field_122-container\" class=\"wpforms-field wpforms-field-payment-single\" data-field-id=\"122\"><label class=\"wpforms-field-label\">Prix :<\/label><div class=\"wpforms-single-item-price-content\"><div class=\"wpforms-single-item-price wpforms-field-medium wpforms-payment-price\">Prix\u00a0: <span class=\"wpforms-price\">24,00 &euro;<\/span><\/div><\/div><input type=\"hidden\" id=\"wpforms-44-field_122\" class=\"wpforms-field-medium wpforms-payment-price\" name=\"wpforms[fields][122]\" value=\"24,00 &euro;\"><\/div><div id=\"wpforms-44-field_120-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"120\"><div class=\"wpforms-clear wpforms-pagebreak-center\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"21\" data-formid=\"44\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-22 last \" data-page=\"22\" style=\"display:none;\"><div id=\"wpforms-44-field_121-container\" class=\"wpforms-field wpforms-field-paypal-commerce\" data-field-id=\"121\"><label class=\"wpforms-field-label\">Paiement <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"hidden\" name=\"wpforms[fields][121][orderID]\" class=\"wpforms-paypal-commerce-order-id\" \/><input type=\"hidden\" name=\"wpforms[fields][121][subscriptionID]\" class=\"wpforms-paypal-commerce-subscription-id\" \/><input type=\"hidden\" name=\"wpforms[fields][121][subscriptionProcessorID]\" class=\"wpforms-paypal-commerce-subscription-processor-id\" \/><input type=\"hidden\" name=\"wpforms[fields][121][source]\" class=\"wpforms-paypal-commerce-source\" \/><input type=\"hidden\" name=\"wpforms[fields][121][fastlane_token]\" class=\"wpforms-paypal-commerce-fastlane-token\" \/><div class=\"wpforms-paypal-commerce-card-fields \"><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-paypal-commerce-supported-cards\"><div class=\"wpforms-paypal-commerce-maestro-icon\"><\/div><div class=\"wpforms-paypal-commerce-mastercard-icon\"><\/div><div class=\"wpforms-paypal-commerce-visa-icon\"><\/div><\/div><\/div><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-paypal-commerce-number\"><div id=\"wpforms-44-field_121-cardnumber\" class=\"wpforms-field-paypal-commerce-cardnumber wpforms-field-required\" aria-errormessage=\"wpforms-44-field_121-cardnumber-error\" data-required=\"required\"><\/div><input type=\"text\" class=\"wpforms-paypal-commerce-credit-card-hidden-input\" name=\"wpforms[paypal-commerce-credit-card-hidden-input-44]\" id=\"wpforms-paypal-commerce-credit-card-hidden-input-44-number\" disabled style=\"display: none;\"><label for=\"wpforms-paypal-commerce-credit-card-hidden-input-44-number\" class=\"wpforms-field-sublabel after\">Num\u00e9ro de carte<\/label><\/div><\/div><div class=\"wpforms-field-row wpforms-field-row-responsive wpforms-field-medium\"><div class=\"wpforms-field-row-block wpforms-one-half wpforms-first wpforms-field-paypal-commerce-date\"><div id=\"wpforms-44-field_121-carddate\" class=\"wpforms-field-paypal-commerce-carddate wpforms-field-required\" aria-errormessage=\"wpforms-44-field_121-carddate-error\" data-required=\"required\"><\/div><input type=\"text\" class=\"wpforms-paypal-commerce-credit-card-hidden-input\" name=\"wpforms[paypal-commerce-credit-card-hidden-input-44]\" id=\"wpforms-paypal-commerce-credit-card-hidden-input-44-date\" disabled style=\"display: none;\"><label for=\"wpforms-paypal-commerce-credit-card-hidden-input-44-date\" class=\"wpforms-field-sublabel after\">Expiration Date<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half wpforms-field-paypal-commerce-code\"><div id=\"wpforms-44-field_121-cardcode\" class=\"wpforms-field-paypal-commerce-cardcode wpforms-field-required\" aria-errormessage=\"wpforms-44-field_121-cardcode-error\" data-required=\"required\"><\/div><input type=\"text\" class=\"wpforms-paypal-commerce-credit-card-hidden-input\" name=\"wpforms[paypal-commerce-credit-card-hidden-input-44]\" id=\"wpforms-paypal-commerce-credit-card-hidden-input-44-code\" disabled style=\"display: none;\"><label for=\"wpforms-paypal-commerce-credit-card-hidden-input-44-code\" class=\"wpforms-field-sublabel after\">Code de s\u00e9curit\u00e9 (CVC)<\/label><\/div><\/div><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-paypal-commerce-name\"><input type=\"text\" id=\"wpforms-44-field_121-cardname\" class=\"wpforms-field-paypal-commerce-cardname wpforms-field-required\" name=\"wpforms[fields][121][cardname]\" aria-errormessage=\"wpforms-44-field_121-cardname-error\" required><label for=\"wpforms-44-field_121-cardname\" class=\"wpforms-field-sublabel after\">Card Holder Name<\/label><\/div><\/div><\/div><\/div><div id=\"wpforms-44-field_5-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"5\"><\/div><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" style=\"display:none;\"><input type=\"hidden\" name=\"wpforms[id]\" value=\"44\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/app.vosol-france.com\/index.php\/wp-json\/wp\/v2\/pages\/47\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-44\" class=\"wpforms-submit\" data-alt-text=\"Sending...\" data-submit-text=\"Terminer\" aria-live=\"assertive\" value=\"wpforms-submit\">Terminer<\/button><img decoding=\"async\" src=\"https:\/\/app.vosol-france.com\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Chargement en cours\"><div class=\"wpforms-paypal-commerce-single-submit-button size-medium\"><img decoding=\"async\" src=\"https:\/\/app.vosol-france.com\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-paypal-commerce-single-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Chargement en cours\"><div class=\"wpforms-paypal-commerce-applepay-button wpforms-hidden\" style=\"--apple-pay-button-border-radius: 23px;\"><\/div><div class=\"wpforms-paypal-commerce-googlepay-button wpforms-hidden\"><\/div><\/div><div class=\"wpforms-paypal-commerce-subscriptions-submit-button size-medium\"><img decoding=\"async\" src=\"https:\/\/app.vosol-france.com\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-paypal-commerce-recurring-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Chargement en cours\"><\/div><\/div><\/form><\/div>  <!-- .wpforms-container -->')) {\r\n                    document.getElementById('wpformsFallback').style.display = 'block';\r\n                }\r\n            }\r\n        });\r\n\r\n        \/\/ ========== COPY CODE ==========\r\n        function copyCode(button) {\r\n            const codeBlock = button.closest('.code-block');\r\n            const code = codeBlock.querySelector('code').textContent;\r\n            \r\n            navigator.clipboard.writeText(code).then(() => {\r\n                const originalText = button.textContent;\r\n                button.textContent = '\u2705 Copi\u00e9 !';\r\n                setTimeout(() => {\r\n                    button.textContent = originalText;\r\n                }, 2000);\r\n                showToast('\ud83d\udccb Code copi\u00e9 dans le presse-papier');\r\n            }).catch(() => {\r\n                const textarea = document.createElement('textarea');\r\n                textarea.value = code;\r\n                document.body.appendChild(textarea);\r\n                textarea.select();\r\n                document.execCommand('copy');\r\n                document.body.removeChild(textarea);\r\n                showToast('\ud83d\udccb Code copi\u00e9 dans le presse-papier');\r\n            });\r\n        }\r\n\r\n        \/\/ ========== TOAST ==========\r\n        let toastTimeout;\r\n\r\n        function showToast(message) {\r\n            const toast = document.getElementById('toast');\r\n            toast.textContent = message;\r\n            toast.classList.add('show');\r\n            \r\n            clearTimeout(toastTimeout);\r\n            toastTimeout = setTimeout(() => {\r\n                toast.classList.remove('show');\r\n            }, 3000);\r\n        }\r\n\r\n        \/\/ ========== SMOOTH SCROLL ==========\r\n        document.querySelectorAll('a[href^=\"#\"]').forEach(anchor => {\r\n            anchor.addEventListener('click', function(e) {\r\n                e.preventDefault();\r\n                const target = document.querySelector(this.getAttribute('href'));\r\n                if (target) {\r\n                    target.scrollIntoView({ behavior: 'smooth', block: 'start' });\r\n                }\r\n            });\r\n        });\r\n\r\n        \/\/ ========== DARK MODE ==========\r\n        if (window.matchMedia && window.matchMedia('(prefers-color-scheme: dark)').matches) {\r\n            document.querySelector('meta[name=\"theme-color\"]').content = '#0f172a';\r\n        }\r\n\r\n        \/\/ ========== CONSOLE ==========\r\n        console.log('%c\ud83d\udcc4 Arr\u00eat de travail en ligne', 'font-size: 22px; font-weight: bold; color: #059669;');\r\n        console.log('%c\u26a1 Obtenez votre arr\u00eat maladie en 2 minutes - PDF instantan\u00e9', 'font-size: 14px; color: #059669;');\r\n        console.log('%c\u2728 Formulaire WPForms ID: 44', 'font-size: 14px; color: #7c3aed;');\r\n        console.log('%c\ud83d\udcdd Collez votre code WPForms dans la zone pr\u00e9vue', 'font-size: 12px; color: #64748b;');\r\n    <\/script>\r\n<\/body>\r\n<\/html>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Arr\u00eat de travail en ligne | Service Officiel Arr\u00eat de travail S\u00e9curis\u00e9 S\u00e9curis\u00e9 &amp; Rapide Obtenez votre arr\u00eat maladie en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"","ast-site-content-layout":"full-width-container","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-47","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/app.vosol-france.com\/index.php\/wp-json\/wp\/v2\/pages\/47","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/app.vosol-france.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/app.vosol-france.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/app.vosol-france.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/app.vosol-france.com\/index.php\/wp-json\/wp\/v2\/comments?post=47"}],"version-history":[{"count":206,"href":"https:\/\/app.vosol-france.com\/index.php\/wp-json\/wp\/v2\/pages\/47\/revisions"}],"predecessor-version":[{"id":693,"href":"https:\/\/app.vosol-france.com\/index.php\/wp-json\/wp\/v2\/pages\/47\/revisions\/693"}],"wp:attachment":[{"href":"https:\/\/app.vosol-france.com\/index.php\/wp-json\/wp\/v2\/media?parent=47"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}